{"id":10061,"date":"2020-01-13T11:03:44","date_gmt":"2020-01-13T17:03:44","guid":{"rendered":"http:\/\/redaccionoaxaca.com\/?p=10061"},"modified":"2020-01-13T11:03:44","modified_gmt":"2020-01-13T17:03:44","slug":"baja-la-competitividad-y-crecimiento-economico-de-oaxaca-prende-foco-amarillo-en-percepcion-de-inseguridad-y-verde-en-deuda-estatal","status":"publish","type":"post","link":"https:\/\/redaccionoaxaca.com\/index.php\/2020\/01\/13\/baja-la-competitividad-y-crecimiento-economico-de-oaxaca-prende-foco-amarillo-en-percepcion-de-inseguridad-y-verde-en-deuda-estatal\/","title":{"rendered":"Baja la competitividad y crecimiento econ\u00f3mico de Oaxaca; prende foco amarillo en percepci\u00f3n de inseguridad y verde en deuda estatal."},"content":{"rendered":"<div dir=\"ltr\">\n<div><\/div>\n<div><strong>#Redacci\u00f3nOaxaca<\/strong><\/div>\n<\/div>\n<div><\/div>\n<div><strong>#Oaxaca<\/strong><\/div>\n<div><\/div>\n<div dir=\"ltr\">\n<div><strong>Jaime GUERRERO<\/strong><\/div>\n<div><\/div>\n<div style=\"text-align: justify;\">La organizaci\u00f3n M\u00e9xico \u00bfC\u00f3mo vamos?, Sem\u00e1foro delictivo Nacional, \u00cdndice de Competitividad Estatal 2018 y Sem\u00e1foro de la Deuda estatal por la Secretar\u00eda de Hacienda y Cr\u00e9dito P\u00fablico 2019, ubica a Oaxaca en el lugar 30 de competitividad, en foco rojo por un saldo de -2.6 por ciento en crecimiento econ\u00f3mico en el segundo trimestre de 2019.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">El balance denominado &#8220;Paquetes Econ\u00f3micos Estatales 2020&#8221;, presenta la situaci\u00f3n actual de las finanzas estatales a partir de la aprobaci\u00f3n de los paquetes econ\u00f3micos para el presente a\u00f1o en cada entidad, asimismo, la informaci\u00f3n\u00a0tambi\u00e9n fue tomada de los sem\u00e1foros estatales de la organizaci\u00f3n M\u00e9xico \u00bfC\u00f3mo vamos?, Sem\u00e1foro delictivo Nacional, \u00cdndice de Competitividad Estatal 2018 y Sem\u00e1foro de la Deuda estatal por la Secretar\u00eda de Hacienda y Cr\u00e9dito P\u00fablico 2019.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">El documento fue enviado al sector empresarial afiliado a la Confederaci\u00f3n Patronal de la Rep\u00fablica Mexicana (Coparmex) con el objetivo de que puedan analizar el panorama econ\u00f3mico social y puedan tomar las decisiones m\u00e1s acertadas para sus negocios.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">En el caso espec\u00edfico de Oaxaca, ante tal panorama la entidad se ubica en el lugar 30 de competitividad, en foco rojo por un saldo de -2.6 por ciento en crecimiento econ\u00f3mico en el segundo trimestre de 2019, en sem\u00e1foro amarillo por percepci\u00f3n de inseguridad y en sem\u00e1foro verde en el indicador de deuda estatal emitido por la Secretar\u00eda de Hacienda y Cr\u00e9dito P\u00fablico al registrar una deuda p\u00fablica de 4.1 a 4.5 por ciento del a\u00f1o de 2017 al 2018.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">De su lado el Banco Mundial, al advertir que existe el riesgo de que el crecimiento se deteriore a\u00fan m\u00e1s, degrad\u00f3 a la econom\u00eda mexicana a un nulo avance en 2019, y recort\u00f3 a 1.2% su previsi\u00f3n para el 2020.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><b>Para el 2019, el nuevo pron\u00f3stico pas\u00f3 de 0.6% a 0% y para este a\u00f1o que reci\u00e9n comienza de 1.5% a 1.2%<\/b>. Tambi\u00e9n hizo proyecciones para el 2021 en donde prev\u00e9 un repunte de 1.8% y para el 2022 de 2.3 por ciento.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">En la edici\u00f3n de enero de Perspectivas Econ\u00f3micas Mundiales, que dio a conocer, el organismo estableci\u00f3 que la actualizaci\u00f3n de su pron\u00f3stico se dar\u00e1 a medida que repunten las inversiones en nuestro pa\u00eds.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><b>En M\u00e9xico, el crecimiento aumentar\u00e1 al 1.2 % este 2020<\/b>, debido a que la merma en la incertidumbre normativa contribuir\u00e1 a que las inversiones repunten, detall\u00f3.<\/div>\n<div style=\"text-align: justify;\">Ubic\u00f3 que el mayor riesgo para M\u00e9xico y el conjunto de las econom\u00edas en Am\u00e9rica Latina es su exposici\u00f3n a que el\u00a0<b>crecimiento<\/b>\u00a0se siga da\u00f1ando.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Mientras que en la parte externa, en particular, los riesgos vinculados con el comercio y el financiamiento, son elevados, advirti\u00f3.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><b>En Am\u00e9rica Latina, se espera que en 2020 el crecimiento regional aumente al 1.8 %<\/b>\u00a0a medida que se consolide el crecimiento en las econom\u00edas m\u00e1s grandes y se eleve la demanda interna en toda la regi\u00f3n.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">En 2020 el crecimiento de la econom\u00eda mundial se acercar\u00e1, seg\u00fan las previsiones, al 2.5 % a medida que las inversiones y el comercio se recuperen gradualmente de la significativa debilidad que mostraron en a\u00f1o pasado.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><b>Sin embargo, a\u00fan persisten riesgos de que la situaci\u00f3n empeore,<\/b>\u00a0afirma el Banco Mundial en la edici\u00f3n de enero de 2020 de Perspectivas econ\u00f3micas mundiales.<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO La organizaci\u00f3n M\u00e9xico \u00bfC\u00f3mo vamos?, Sem\u00e1foro delictivo Nacional, \u00cdndice de Competitividad Estatal 2018 y Sem\u00e1foro de la Deuda estatal por la Secretar\u00eda de Hacienda y Cr\u00e9dito P\u00fablico 2019, ubica a Oaxaca en el lugar 30 de competitividad, en foco rojo por un saldo de -2.6 por ciento en crecimiento econ\u00f3mico en [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":{"0":"post-10061","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-uncategorized"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9Ynjw-2Ch","jetpack-related-posts":[{"id":5193,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2019\/02\/04\/inversion-de-eolicas-sube-indicadores-economicos-de-oaxaca-pero-persiste-pobreza-laboral\/","url_meta":{"origin":10061,"position":0},"title":"Inversi\u00f3n de e\u00f3licas sube indicadores econ\u00f3micos  de Oaxaca, pero persiste pobreza laboral.","author":"jaime","date":"febrero 4, 2019","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca\u00a0 Jaime GUERRERO\u00a0 De acuerdo a la Organizaci\u00f3n No Gubernamental, \u201cM\u00e9xico, \u00bfC\u00f3mo Vamos?\u201d, integrado por investigadores, acad\u00e9micos y expertos en econom\u00eda y pol\u00edtica p\u00fablica mexicana, Oaxaca est\u00e1 en sem\u00e1foro verde en los que a crecimiento econ\u00f3mico se refiere. De acuerdo con los resultados del Indicador Trimestral de la Actividad\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":20030,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2021\/08\/12\/oaxaca-el-top-10-de-certificacion-policial-y-semaforo-verde-con-baja-incidencia-delictiva-sesnsp\/","url_meta":{"origin":10061,"position":1},"title":"Oaxaca el top 10 de certificaci\u00f3n policial y\u00a0sem\u00e1foro verde con baja incidencia delictiva: SESNSP.","author":"ariadna","date":"agosto 12, 2021","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO\u00a0 El Consejo Nacional de Seguridad P\u00fablica, report\u00f3 que Oaxaca est\u00e1 ubicada en el lugar 10 en el Certificado \u00danico Policial (CUP), ubic\u00e1ndose con el mayor n\u00famero de polic\u00edas certificados. De acuerdo a los informes presentados, con corte al 30 de junio, del universo de los polic\u00edas\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":7989,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2019\/08\/13\/oaxaca-campeche-tamaulipas-nayarit-y-edomex-en-foco-rojo-por-deuda-per-capita-datacoparmex\/","url_meta":{"origin":10061,"position":2},"title":"Oaxaca, Campeche, Tamaulipas, Nayarit y EdoMex,  en foco rojo por deuda per c\u00e1pita: DataCoparmex.","author":"mayra","date":"agosto 13, 2019","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO En el \u00faltimo a\u00f1o la deuda per c\u00e1pita de Oaxaca, ubica a la entidad en foco rojo, debido a que que durante el primer trimestre de 2018 cada habitante arrastraba una deuda de 2 mil 954 pesos, al primer trimestre de este 2019, es de 3\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":20010,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2021\/08\/12\/oaxaca-entre-los-estados-con-mayor-numero-de-policias-certificados\/","url_meta":{"origin":10061,"position":3},"title":"Oaxaca entre los estados con mayor n\u00famero de polic\u00edas certificados.","author":"ariadna","date":"agosto 12, 2021","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Oaxaca de Ju\u00e1rez, Oax. 12 de agosto de 2021. El Secretario Ejecutivo del Sistema Estatal de Seguridad P\u00fablica en Oaxaca, Jos\u00e9 Manuel Vera Salinas, particip\u00f3 en la Reuni\u00f3n Nacional de Secretarios Ejecutivos de Seguridad P\u00fablica convocada para el d\u00eda de hoy por el Secretariado Ejecutivo del Sistema Nacional\u2026","rel":"","context":"En &quot;Imagen&quot;","block_context":{"text":"Imagen","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/imagen\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2021\/08\/IMG-20210812-WA0116-300x225.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3183,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2018\/10\/11\/oaxaca-en-el-ranking-15-de-transparencia-del-gasto-2018-imco\/","url_meta":{"origin":10061,"position":4},"title":"OAXACA EN EL RANKING 15 DE TRANSPARENCIA DEL GASTO 2018: IMCO","author":"denise","date":"octubre 11, 2018","format":false,"excerpt":"#Redacci\u00f3nOaxaca\u00a0 Jaime GUERRERO \u00a0 De acuerdo al \u00cdndice de Informaci\u00f3n del Ejercicio del Gasto (IIEG 2018), del Instituto Mexicano de la Competitividad (IMCO), en el cumplimiento de la calidad de la informaci\u00f3n sobre el ejercicio del gasto de los 32 poderes ejecutivos estatales, Oaxaca se ubica en el lugar 15,\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4173,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2018\/11\/30\/crece-informalidad-en-oaxaca-al-82-1-en-la-poblacion-economicamente-activa\/","url_meta":{"origin":10061,"position":5},"title":"Crece informalidad en Oaxaca al 82.1%\u00a0  en la poblaci\u00f3n econ\u00f3micamente activa","author":"jaime","date":"noviembre 30, 2018","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO\u00a0\u00a0 En Oaxaca, la informalidad laboral, en el \u00faltimo trimestre registr\u00f3 un incremento 1.7 puntos porcentuales al pasar de 80.4 por ciento a 82.1 por ciento de la poblaci\u00f3n econ\u00f3micamente activa. Si bien la tasa de desocupaci\u00f3n en la entidad es la segunda m\u00e1s baja a nivel\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/10061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/comments?post=10061"}],"version-history":[{"count":1,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/10061\/revisions"}],"predecessor-version":[{"id":10063,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/10061\/revisions\/10063"}],"wp:attachment":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/media?parent=10061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/categories?post=10061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/tags?post=10061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}