{"id":10100,"date":"2020-01-14T17:01:25","date_gmt":"2020-01-14T23:01:25","guid":{"rendered":"http:\/\/redaccionoaxaca.com\/?p=10100"},"modified":"2020-01-14T17:02:08","modified_gmt":"2020-01-14T23:02:08","slug":"los-sindicatos-tienen-libertad-de-manifestacion-pero-seran-atendidos-con-responsabilidad-acorde-a-la-situacion-presupuestal-de-la-ubajo-no-mas-alla-de-ella-rector","status":"publish","type":"post","link":"https:\/\/redaccionoaxaca.com\/index.php\/2020\/01\/14\/los-sindicatos-tienen-libertad-de-manifestacion-pero-seran-atendidos-con-responsabilidad-acorde-a-la-situacion-presupuestal-de-la-ubajo-no-mas-alla-de-ella-rector\/","title":{"rendered":"Los Sindicatos tienen libertad de manifestaci\u00f3n pero ser\u00e1n atendidos con responsabilidad, acorde a la situaci\u00f3n presupuestal de la UBAJO, no m\u00e1s all\u00e1 de ella: Rector."},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>#Redacci\u00f3nOaxaca<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>#Oaxaca<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Maira Ric\u00e1rdez<\/strong><\/p>\n<p style=\"text-align: justify;\">La Universidad Aut\u00f3noma Benito Ju\u00e1rez de Oaxaca es auditada de manera permanente por diversas instancias estatales y federales, no hay recursos disponibles para entregar de acuerdo a las exigencias de sindicatos existentes o por existir, los recursos que a la instituci\u00f3n educativa llegan son igual que en el resto de instancias, revisados a detalle en su ejecuci\u00f3n, no hay manera de desviarlos, precis\u00f3 el Rector de la Universidad, Eduardo Mart\u00ednez.<\/p>\n<p style=\"text-align: justify;\">Refiri\u00f3 que son alrededor de 36 auditor\u00edas las que han sido y est\u00e1n siendo aplicadas a la m\u00e1xima casa de estudios, algunas se llevan incluso a\u00f1os, otras han sido concluidas satisfactoriamente, y en las que ha habido observaciones, corren los tiempos de ley para solventarlas. La UABJO subray\u00f3 no podr\u00e1 quedar bajo sospecha de malversaci\u00f3n afirm\u00f3, hay la disposici\u00f3n de colaborar para comprobar cuentas sanas.<\/p>\n<p style=\"text-align: justify;\">Los grupos sindicales tienen libertad de manifestaci\u00f3n dijo, pero ser\u00e1n atendidos con responsabilidad y transparencia en la medida de las posibilidades y apegados a lo que marca la norma respecto al ejercicio de recursos.<\/p>\n<p style=\"text-align: justify;\">Hay varios temas dijo el Rector, que deben ser atendidos, y se han habilitado mesas de di\u00e1logo con los sindicatos; ellos est\u00e1n sabedores de la situaci\u00f3n presupuestal porque incluso se ha planteado p\u00fablicamente ante el m\u00e1ximo \u00f3rgano de gobierno de la Universidad.<\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-10100-1\" width=\"640\" height=\"352\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/redaccionoaxaca.com\/wp-content\/uploads\/2020\/01\/VID-20200114-WA0112.mp4?_=1\" \/><a href=\"http:\/\/redaccionoaxaca.com\/wp-content\/uploads\/2020\/01\/VID-20200114-WA0112.mp4\">http:\/\/redaccionoaxaca.com\/wp-content\/uploads\/2020\/01\/VID-20200114-WA0112.mp4<\/a><\/video><\/div>\n","protected":false},"excerpt":{"rendered":"<p>#Redacci\u00f3nOaxaca #Oaxaca Maira Ric\u00e1rdez La Universidad Aut\u00f3noma Benito Ju\u00e1rez de Oaxaca es auditada de manera permanente por diversas instancias estatales y federales, no hay recursos disponibles para entregar de acuerdo a las exigencias de sindicatos existentes o por existir, los recursos que a la instituci\u00f3n educativa llegan son igual que en el resto de instancias, [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":{"0":"post-10100","1":"post","2":"type-post","3":"status-publish","4":"format-video","6":"category-uncategorized","7":"post_format-post-format-video"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9Ynjw-2CU","jetpack-related-posts":[{"id":11158,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2020\/03\/12\/capacidad-de-interlocucion-piden-a-rector-por-conflicto-con-steuabjo-segego-ofrece-intervencion\/","url_meta":{"origin":10100,"position":0},"title":"Capacidad de interlocuci\u00f3n piden a rector por  conflicto con Steuabjo; Segego ofrece intervenci\u00f3n.","author":"ariadna","date":"marzo 12, 2020","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO El Secretario General de Gobierno, H\u00e9ctor Anuar Mafud, afirm\u00f3 que la administraci\u00f3n de del rector de la Universidad Aut\u00f3noma Benito Ju\u00e1rez de Oaxaca (UABJO), Eduardo Bautista Mart\u00ednez, debe de tener la capacidad, interlocuci\u00f3n necesaria, disposici\u00f3n y cercan\u00eda, para resolver la problem\u00e1tica act\u00faan con el Sindicato de\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":26718,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2022\/07\/13\/rector-de-la-uabjo-exhorto-a-anteponer-intereses-para-que-facultad-de-contaduria-tenga-actividades-academicas-y-administrativas\/","url_meta":{"origin":10100,"position":1},"title":"Rector de la UABJO exhort\u00f3 a anteponer intereses, para que Facultad de Contadur\u00eda tenga actividades acad\u00e9micas y administrativas","author":"ariadna","date":"julio 13, 2022","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO En medio de conflicto y disputa de la direcci\u00f3n de la Facultad de Contadur\u00eda y Administraci\u00f3n (FCA) de la Universidad Aut\u00f3noma Benito Ju\u00e1rez de Oaxaca, el rector, Cristian Eder Carre\u00f1o L\u00f3pez, llam\u00f3 al di\u00e1logo a las partes, pero aclar\u00f3 que cuando se acordaron las mesas de\u2026","rel":"","context":"En &quot;Imagen&quot;","block_context":{"text":"Imagen","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/imagen\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":21387,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2021\/10\/04\/lunes-caotico-en-la-capital-oaxaquena-sindicatos-y-organizaciones-bloquearon-y-protestaron-recuento-de-los-danos\/","url_meta":{"origin":10100,"position":2},"title":"Lunes ca\u00f3tico en la capital oaxaque\u00f1a, sindicatos y organizaciones bloquearon y protestaron, recuento de los da\u00f1os.","author":"ariadna","date":"octubre 4, 2021","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Ariadna Mendoza Nuevamente iniciamos la semana con protestas y bloqueos en diversos puntos del la capital del estado, en d\u00f3nde sindicatos y organizaciones\u00a0 salieron a las calles por diversas demandas. Para iniciar, desde muy tempranas horas de este lunes, Integrantes del Frente Ind\u00edgena Popular #FIPO-RFM realizaron un bloqueo\u2026","rel":"","context":"En &quot;Imagen&quot;","block_context":{"text":"Imagen","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/imagen\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2021\/10\/IMG-20211004-WA0059-300x169.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":27496,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2022\/08\/25\/suneo-matiza-declaraciones-de-rector-y-afirma-que-no-deja-el-cargo-por-peticion-de-gobierno-entrante-de-jara\/","url_meta":{"origin":10100,"position":3},"title":"SUNEO matiza declaraciones de rector y afirma que  no deja el cargo por petici\u00f3n de Gobierno entrante de Jara","author":"ariadna","date":"agosto 25, 2022","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO El rector del Sistema de Universidades Estatales de Oaxaca (SUNEO), Modesto Seara V\u00e1zquez, se desdijo y matiz\u00f3 sus primeras declaraciones de sus salida -despu\u00e9s de 3 d\u00e9cadas de control y monopolio en ese sistema educativo del estado, financiado por el Gobierno Estatal en turno. En la\u2026","rel":"","context":"En &quot;Al Cierre&quot;","block_context":{"text":"Al Cierre","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/al-cierre\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":26413,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2022\/06\/29\/director-depuesto-de-facultad-de-contaduria-de-la-uabjo-se-niega-a-aceptar-remocion-y-mantienen-tomada-cu\/","url_meta":{"origin":10100,"position":4},"title":"Director depuesto de facultad de Contadur\u00eda de la UABJO se niega a aceptar remoci\u00f3n y mantienen tomada CU","author":"ariadna","date":"junio 29, 2022","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO Gerardo Velasco Soriano anunci\u00f3 que no aceptar\u00e1 su remoci\u00f3n como director de la Facultad de Contadur\u00eda y Administraci\u00f3n de la Universidad Aut\u00f3noma Benito Ju\u00e1rez de Oaxaca (#UABJO), luego de la designaci\u00f3n de Mauro Francisco P\u00e9rez Carrasco por el Consejo T\u00e9cnico. En conferencia de prensa, el director\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":25475,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2022\/05\/06\/en-la-uabjo-hay-presente-pero-hay-mas-futuro-murat-hinojosa\/","url_meta":{"origin":10100,"position":5},"title":"En la UABJO \u201chay presente, pero hay m\u00e1s futuro\u201d: Murat Hinojosa.","author":"ariadna","date":"mayo 6, 2022","format":"video","excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Citlalli L\u00f3pez Vel\u00e1zquez Convocado por el rector de la #UABJO, Cristian Eder Carre\u00f1o L\u00f3pez, cientos de personas, entre ellos el presidente municipal, Francisco Mart\u00ednez Neri y el gobernador del estado, Alejandro Murat Hinojosa, se sumaron al megatequio para el retorno gradual y ordenado a la Universidad Aut\u00f3noma Benito\u2026","rel":"","context":"En &quot;Imagen&quot;","block_context":{"text":"Imagen","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/imagen\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/10100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/comments?post=10100"}],"version-history":[{"count":2,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/10100\/revisions"}],"predecessor-version":[{"id":10105,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/10100\/revisions\/10105"}],"wp:attachment":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/media?parent=10100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/categories?post=10100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/tags?post=10100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}