{"id":10160,"date":"2020-01-16T07:43:18","date_gmt":"2020-01-16T13:43:18","guid":{"rendered":"http:\/\/redaccionoaxaca.com\/?p=10160"},"modified":"2020-01-16T07:43:18","modified_gmt":"2020-01-16T13:43:18","slug":"comision-de-vinculacion-con-oples-del-ine-elige-a-vocero-del-ieepco-como-nuevo-consejero","status":"publish","type":"post","link":"https:\/\/redaccionoaxaca.com\/index.php\/2020\/01\/16\/comision-de-vinculacion-con-oples-del-ine-elige-a-vocero-del-ieepco-como-nuevo-consejero\/","title":{"rendered":"Comisi\u00f3n de Vinculaci\u00f3n con OPLES del INE,  elige a vocero del IEEPCO como nuevo consejero."},"content":{"rendered":"<p class=\"x_ydp97fe9c08MsoNormal\">\n<p class=\"x_ydp97fe9c08MsoNormal\"><b>#Redacci\u00f3nOaxaca<\/b><\/p>\n<p><strong>#Oaxaca<\/strong><\/p>\n<p class=\"x_ydp97fe9c08MsoNormal\"><b>Jaime GUERRERO<\/b><\/p>\n<p class=\"x_ydp97fe9c08MsoNormal\" style=\"text-align: justify;\">La Comisi\u00f3n de Vinculaci\u00f3n con los Organismos P\u00fablicos Locales del Instituto Nacional Electoral, aprob\u00f3 el Proyecto de Acuerdo del Consejo General del INE, por el que se aprueba la designaci\u00f3n de las Consejeras y Consejeros Presidentes de los Organismos P\u00fablicos Locales de Michoac\u00e1n, Nayarit, Puebla y Tamaulipas, del Consejero Electoral del Instituto Estatal Electoral y de Participaci\u00f3n Ciudadana de Oaxaca (IEEPCO), y de Consejeros de Organismos P\u00fablicos Locales de Sonora y Veracruz.<\/p>\n<p class=\"x_ydp97fe9c08MsoNormal\" style=\"text-align: justify;\">La Comisi\u00f3n la integran los consejeros del INE, Marco Antonio Ba\u00f1os Mart\u00ednez, as\u00ed como las consejeras, Dania Paola Ravel Cuevas y Beatriz Claudia Zavala P\u00e9rez.<\/p>\n<p class=\"x_ydp97fe9c08MsoNormal\" style=\"text-align: justify;\">En el caso de Oaxaca, Ba\u00f1os Mart\u00ednez, refiri\u00f3 que en la integraci\u00f3n de las propuestas hab\u00eda perfiles interesantes que hab\u00edan mostrado capacidades, las cuales se apreciaron de manera directa en el proceso de entrevistas y refiri\u00f3 al actual titular de la Unidad T\u00e9cnica de Comunicaci\u00f3n Social del IEEPCO, Alejandro Carrasco Sampedro.<\/p>\n<p class=\"x_ydp97fe9c08MsoNormal\" style=\"text-align: justify;\">Al referirse al actual funcionario del IEEPCO, mencion\u00f3 que, en la entrevista que la persona cuenta con las capacidades necesarias para desempe\u00f1ar un buen papel en el OPLE de Oaxaca.<\/p>\n<p class=\"x_ydp97fe9c08MsoNormal\" style=\"text-align: justify;\">La consejera Zavala P\u00e9rez, destac\u00f3 que los perfiles fueron ciudadanos de otras \u00e1reas que podr\u00e1n favorecer el funcionamiento de los OPLES.<\/p>\n<p class=\"x_ydp97fe9c08MsoNormal\" style=\"text-align: justify;\">Respecto a la perfilada en el Estado de Veracruz, refiri\u00f3 la trayectoria de Mar\u00eda de Lourdes Fern\u00e1ndez, quien inici\u00f3 como capturista en el OPLE de esta entidad y escal\u00f3 en los cargos por su constancia y profesionalismo.<\/p>\n<p class=\"x_ydp97fe9c08MsoNormal\" style=\"text-align: justify;\">Ba\u00f1os Mart\u00ednez, Ravel Cuevas y Zavala P\u00e9rez, coincidieron en se\u00f1alar que todos los aspirantes a consejeros y consejeras de los OPLES, demostraron su capacidad al superar cada una de las etapas establecidas en la convocatoria que son el examen de conocimientos, el ensayo y la entrevista presencial.<\/p>\n<p class=\"x_ydp97fe9c08MsoNormal\" style=\"text-align: justify;\">En el caso de Oaxaca, participaron en el proceso de selecci\u00f3n 61 personas, de las cuales, solo 56 accedieron al examen, posteriormente 15 al ensayo y 8 a las entrevistas finales ante los consejeros y consejeras del INE.<\/p>\n<p class=\"x_ydp97fe9c08MsoNormal\" style=\"text-align: justify;\">En el camino se quedaron funcionarios del IEEPCO, vinculados a dirigentes de partidos pol\u00edticos y funcionarios p\u00fablicos.<\/p>\n<p class=\"x_ydp97fe9c08MsoNormal\" style=\"text-align: justify;\">Y es que desde el pasado 28 de febrero, tras la renuncia de Gerardo Garc\u00eda Marroqu\u00edn al Consejo General del IEEPCO, solo hay 6 de 7 consejeros y consejeras electorales.<\/p>\n<p class=\"x_ydp97fe9c08MsoNormal\" style=\"text-align: justify;\">Para el proceso el INE determin\u00f3 que del 5 al 30 de agosto de 2019 se realizar\u00e1 el registro de aspirantes; del 2 al 27 de septiembre, se revisar\u00e1 por parte del INE, los documentos presentados por los registrados para verificar que cumplan con los requisitos legales.<\/p>\n<p class=\"x_ydp97fe9c08MsoNormal\" style=\"text-align: justify;\">El pasado 9 de noviembre, se realiz\u00f3 un examen a los aspirantes de competencias b\u00e1sicas. Posteriormente, del 21 al 22 de noviembre se calificaron y los 15 aspirantes aprobados presentaron un ensayo el pasado 23 de noviembre. La revisi\u00f3n de estos ensayos fue del 17 al 20 de diciembre. Al final pasaron 8 a entrevistas presenciales.<\/p>\n<p class=\"x_ydp97fe9c08MsoNormal\" style=\"text-align: justify;\">Finalmente, el pr\u00f3ximo 23 de enero de 2020, el dictamen ser\u00e1 sometido a la consideraci\u00f3n del Consejo General del INE, para la designaci\u00f3n del nuevo consejero del IEEPCO.<\/p>\n<p class=\"x_ydp97fe9c08MsoNormal\" style=\"text-align: justify;\">Gabriela G\u00f3mez Esteban, ex funcionaria en SINFRA, durante el periodo de Netzahualc\u00f3yotl Salvatierra y actualmente es interventora designada del IEEPCO, para el proceso de liquidaci\u00f3n de los partidos pol\u00edticos.<\/p>\n<p class=\"x_ydp97fe9c08MsoNormal\" style=\"text-align: justify;\">Zaira Tello Hern\u00e1ndez, Titular de Unidad T\u00e9cnica Jur\u00eddica y de lo Contencioso Electoral, igual adscrita a la Secretar\u00eda Ejecutiva del IEEPCO; Sarah\u00ed R\u00edos Casas, operadora de equipo tecnol\u00f3gico del INE, ex analista del municipio de Puebla.<\/p>\n<p class=\"x_ydp97fe9c08MsoNormal\" style=\"text-align: justify;\">El futuro consejero, Carrasco Sampedro, fue funcionario de Sinfra en el sexenio de Gabino Cu\u00e9 Monteagudo y cercano a Luis Miguel Santib\u00e1\u00f1ez, Secretario Ejecutivo del IEEPCO.<\/p>\n<p class=\"x_ydp97fe9c08MsoNormal\" style=\"text-align: justify;\">Se qued\u00f3 en el camino, Ra\u00fal Castellanos Baltazar, ex vocero del ex edil capitalino, Jos\u00e9 Antonio Hern\u00e1ndez Fraguas, quien fuera representante del PRI ante el Consejo General del INE.<\/p>\n<p class=\"x_ydp97fe9c08MsoNormal\" style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO La Comisi\u00f3n de Vinculaci\u00f3n con los Organismos P\u00fablicos Locales del Instituto Nacional Electoral, aprob\u00f3 el Proyecto de Acuerdo del Consejo General del INE, por el que se aprueba la designaci\u00f3n de las Consejeras y Consejeros Presidentes de los Organismos P\u00fablicos Locales de Michoac\u00e1n, Nayarit, Puebla y Tamaulipas, del Consejero Electoral del [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":{"0":"post-10160","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-uncategorized"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9Ynjw-2DS","jetpack-related-posts":[{"id":10290,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2020\/01\/23\/ine-designa-a-vocero-del-ieepco-como-consejero-se-busca-organo-electoral-a-modo-de-paso-para-el-21-y-sucesion-gubernamental\/","url_meta":{"origin":10160,"position":0},"title":"INE designa a vocero del IEEPCO como consejero; se busca  \u00f3rgano electoral a modo, de paso para el 21 y sucesi\u00f3n gubernamental.","author":"ariadna","date":"enero 23, 2020","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO A sugerencia del Consejero Presidente y de su Secretario Ejecutivo del Instituto Estatal Electoral y de Participaci\u00f3n Ciudadana de Oaxaca (IEEPCO), Gustavo Meixueiro N\u00e1jera y Luis Miguel Santib\u00e1\u00f1ez Su\u00e1rez, respectivamente, el Consejo General del Instituto Nacional Electoral (INE) aprob\u00f3 la designaci\u00f3n del consejero del Organismos P\u00fablicos\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":21794,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2021\/10\/21\/comision-de-vinculacion-con-oples-del-ine-designa-a-activista-elizabeth-sanchez-como-presidenta-del-ieepco-bajaron-a-asesora-de-diputada-de-morena-que-sera-magistrada\/","url_meta":{"origin":10160,"position":1},"title":"Comisi\u00f3n de Vinculaci\u00f3n con OPLES del INE designa a activista, Elizabeth S\u00e1nchez como Presidenta del IEEPCO; bajaron a asesora de diputada de Morena que ser\u00e1 magistrada.","author":"ariadna","date":"octubre 21, 2021","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO Por unanimidad, la Comisi\u00f3n de Vinculaci\u00f3n con los Organismos P\u00fablicos Locales del Instituto Nacional Electoral (#INE) aprob\u00f3 la designaci\u00f3n de Elizabeth S\u00e1nchez Guzm\u00e1n como presidenta del Instituto Estatal Electoral y de Participaci\u00f3n de Oaxaca (#IEEPCO), para un periodo de siete a\u00f1os. El proyecto de la comisi\u00f3n\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":33450,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2024\/09\/19\/listo-en-el-ine-nombres-de-proximos-consejeros-del-ieepco-declaran-desierta-una-consejeria\/","url_meta":{"origin":10160,"position":2},"title":"Listo en el INE nombres de pr\u00f3ximos consejeros del IEEPCO, declaran desierta una consejer\u00eda.","author":"ariadna","date":"septiembre 19, 2024","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO Antes de que formalmente los conozcan los consejeros del Instituto Nacional Electoral, la Unidad T\u00e9cnica de Vinculaci\u00f3n con los Organismos P\u00fablicos Locales del Instituto Nacional Electoral (INE), filtr\u00f3 los nombres de las personas seleccionadas como consejeras y consejeros electorales en 20 estados, entre ellos, los del\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2024\/09\/IMG-20240919-WA0302-228x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7715,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2019\/07\/24\/ine-elegira-a-consejera-faltante-del-ieepco-hasta-el-23-de-enero-del-2020\/","url_meta":{"origin":10160,"position":3},"title":"INE elegir\u00e1 a\u00a0consejera faltante\u00a0del\u00a0  IEEPCO,\u00a0hasta el 23 de enero del 2020.","author":"jaime","date":"julio 24, 2019","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO\u00a0 El Consejo General del Instituto Nacional Electoral (INE) aprob\u00f3 las convocatorias para la designaci\u00f3n de tres plazas a integrar los Consejos Locales en los Organismos P\u00fablicos Locales de Tamaulipas, Oaxaca y Veracruz, los cuales estar\u00e1n en el encargo por siete a\u00f1os a partir de su designaci\u00f3n.\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":10479,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2020\/02\/05\/continua-consejo-a-modo-en-el-ieepco-ex-vocero-rinde-protesta-como-consejero\/","url_meta":{"origin":10160,"position":4},"title":"Contin\u00faa consejo a modo en el IEEPCO,  ex vocero rinde protesta como Consejero.","author":"ariadna","date":"febrero 5, 2020","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO\u00a0 El Consejero Presidente del Instituto Estatal Electoral y de Participaci\u00f3n Ciudadana de Oaxaca, Gustavo Meixueiro N\u00e1jera tom\u00f3 protesta a Alejandro Carrasco Sampedro como nuevo Consejero Electoral, para as\u00ed continuar con un \u00f3rgano electoral a modo de cara a las elecciones locales y federales intermedias del 2021\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":18759,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2021\/05\/05\/diputado-afin-a-candidato-de-morena-que-adelanto-campana-pide-al-ine-destituir-a-consejeros-del-ieepco-por-torpeza\/","url_meta":{"origin":10160,"position":5},"title":"Diputado af\u00edn a candidato de Morena que adelant\u00f3 campa\u00f1a,  pide al INE destituir a consejeros del IEEPCO por \u201ctorpeza\u201d.","author":"ariadna","date":"mayo 5, 2021","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO Pese a que los partidos pol\u00edticos son los que han incurrido en omisi\u00f3n y desacato a la ley electoral en el proceso de registro de sus candidatos y candidatas, el diputado independiente, C\u00e9sar Morales Ni\u00f1o, pidi\u00f3 al Instituto Nacional Electoral (INE) destituir a los actuales Consejeros\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/10160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/comments?post=10160"}],"version-history":[{"count":1,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/10160\/revisions"}],"predecessor-version":[{"id":10162,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/10160\/revisions\/10162"}],"wp:attachment":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/media?parent=10160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/categories?post=10160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/tags?post=10160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}