{"id":10234,"date":"2020-01-21T08:16:18","date_gmt":"2020-01-21T14:16:18","guid":{"rendered":"http:\/\/redaccionoaxaca.com\/?p=10234"},"modified":"2020-01-21T08:16:18","modified_gmt":"2020-01-21T14:16:18","slug":"pieza-por-pieza-de-pais-en-pais-muestra-de-arte-colectivo-que-une-mas-de-500-testimonios-sobre-la-violencia-contra-la-mujer-la-infancia-y-el-planeta-parte-de-mexico-y-recorrera","status":"publish","type":"post","link":"https:\/\/redaccionoaxaca.com\/index.php\/2020\/01\/21\/pieza-por-pieza-de-pais-en-pais-muestra-de-arte-colectivo-que-une-mas-de-500-testimonios-sobre-la-violencia-contra-la-mujer-la-infancia-y-el-planeta-parte-de-mexico-y-recorrera\/","title":{"rendered":"-\u201cPieza por pieza, de pa\u00eds en pa\u00eds\u201d-, muestra de arte colectivo que une m\u00e1s de 500 testimonios sobre la violencia contra la mujer, la infancia y el planeta; parte de M\u00e9xico y recorrer\u00e1 el mundo."},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>#Redacci\u00f3nOaxaca<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>#Oaxaca<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Maira Ric\u00e1rdez<\/strong><\/p>\n<p style=\"text-align: justify;\">*Esta muestra tiene el aporte de Oaxaca a partir del trabajo de 85 ni\u00f1as Juchitecas y un grupo de Oaxaque\u00f1as migrantes radicadas en San Diego, Cal.<\/p>\n<p style=\"text-align: justify;\">Cientos de retazos de manta, m\u00e1s de 500 estiman las organizadoras, fueron convertidos en obras de arte por mujeres de varios pa\u00edses del mundo, incluido M\u00e9xico, donde inicia y parte esta gran muestra de arte colectivo que se exhibir\u00e1 este domingo 26 de enero en la plancha del Z\u00f3calo de la Ciudad de M\u00e9xico y a trav\u00e9s de la cual buscan transmitir a la poblaci\u00f3n diversos y multicolores mensajes que versan sobre la violencia contra la mujer, la violencia contra la infancia y la violencia contra la tierra, explic\u00f3 la creadora de esta iniciativa, curadora y promotora cultural, Marietta Bernstorff.<\/p>\n<p style=\"text-align: justify;\">El objetivo central es no s\u00f3lo visibilizar la violencia hacia ni\u00f1as y ni\u00f1os, mujeres y el planeta, cada vez m\u00e1s creciente, dijo, sino fungir como un medio poderoso y simb\u00f3lico de enlace y sanaci\u00f3n. A la fecha suman alrededor de 500 participantes, pero no dejar\u00e1n de crecer asent\u00f3, porque de la Cd. de M\u00e9xico se van a Tijuana, luego cruzan a San Diego, y Los \u00c1ngeles, hac\u00eda Alemania y potras ciudades de Europa.<\/p>\n<p style=\"text-align: justify;\">La idea es unir a las mujeres y hacerles sentir la fuerza conjunta; hacerse escuchar por los gobiernos, la violencia dijo, est\u00e1 fuera de control.<\/p>\n<p style=\"text-align: justify;\">Estos trozos de arte de 70 por 70 cent\u00edmetros, fueron intervenidos con variadas t\u00e9cnicas de costura, tejido, collage, pintura, entre otras. Mediante el proyecto titulado Patchwork, la Manta de Curaci\u00f3n: Pieza por pieza y de Pa\u00eds; mujeres mexicanas y de pa\u00edses como Estados Unidos, Canad\u00e1, El Salvador, Guatemala, Puerto Rico, Reino Unido, Francia, Espa\u00f1a, Alemania, India, Grecia, entre, expresan su sentir sobre la violencia que padecen como g\u00e9nero, mediante el arte.<\/p>\n<p style=\"text-align: justify;\">En la jornada del pr\u00f3ximo domingo, de 11:00 a 17:00 horas en la esquina de Francisco I. Madero y Plaza de la Constituci\u00f3n, frente a Catedral Metropolitana, adem\u00e1s de exhibir las s\u00e1banas creadas con estos trozos -que ser\u00e1n unidas en tiempo real en el lugar-, el p\u00fablico podr\u00e1 participar en esta manifestaci\u00f3n de activismo pac\u00edfico; ser\u00e1 acompa\u00f1ada por actividades, como talleres de elaboraci\u00f3n de las mismas piezas de tela para quienes quieran crearla en ese momento. As\u00ed como de artistas invitados en artes visuales, m\u00fasica, poes\u00eda, danza, terapias alternativas, que compartir\u00e1n tambi\u00e9n su arte en este espacio.<\/p>\n<p style=\"text-align: justify;\">Cabe se\u00f1alar que esta gran obra colectiva que recorrer\u00e1 el mundo lleva tambi\u00e9n el aporte Oaxaque\u00f1o a trav\u00e9s de 85 ni\u00f1as que plasmaron con dibujos, su sentir y pensar sobre la violencia que han vividos, sus madres, sus t\u00edas, vecinas, o ellas mismas, por el solo hecho de ser mujeres; igual lo han hecho grupos de mujeres migrantes Oaxaque\u00f1as radicadas ahora en Estados Unidos, que han plasmado tambi\u00e9n su sentir de violaciones sufridas, en estos trozos de arte.<\/p>\n<p style=\"text-align: justify;\">Contacto:<\/p>\n<p style=\"text-align: justify;\">Solange Garc\u00eda. Cel. 55-5409-5500\/ arts.media.mx@gmail.com<\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-10234-1\" width=\"640\" height=\"352\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/redaccionoaxaca.com\/wp-content\/uploads\/2020\/01\/VID-20200121-WA0003.mp4?_=1\" \/><a href=\"http:\/\/redaccionoaxaca.com\/wp-content\/uploads\/2020\/01\/VID-20200121-WA0003.mp4\">http:\/\/redaccionoaxaca.com\/wp-content\/uploads\/2020\/01\/VID-20200121-WA0003.mp4<\/a><\/video><\/div>\n","protected":false},"excerpt":{"rendered":"<p>#Redacci\u00f3nOaxaca #Oaxaca Maira Ric\u00e1rdez *Esta muestra tiene el aporte de Oaxaca a partir del trabajo de 85 ni\u00f1as Juchitecas y un grupo de Oaxaque\u00f1as migrantes radicadas en San Diego, Cal. Cientos de retazos de manta, m\u00e1s de 500 estiman las organizadoras, fueron convertidos en obras de arte por mujeres de varios pa\u00edses del mundo, incluido [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":{"0":"post-10234","1":"post","2":"type-post","3":"status-publish","4":"format-video","6":"category-uncategorized","7":"post_format-post-format-video"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9Ynjw-2F4","jetpack-related-posts":[{"id":41166,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2026\/03\/25\/despojo-con-rostro-de-violencia-patrimonial-contra-empresaria-mixe\/","url_meta":{"origin":10234,"position":0},"title":"Despojo con rostro de violencia patrimonial contra empresaria Mixe","author":"ariadna","date":"marzo 25, 2026","format":"video","excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Citlalli L\u00f3pez Vel\u00e1zquez Efra\u00edl Ju\u00e1rez L\u00f3pez, empresaria mixe propietaria de la taquer\u00eda Los Combinados, enfrenta un despojo con rostro de violencia patrimonial por parte de su expareja identificado como Rafael. \u201cComo mujer y sobre todo como mujer ind\u00edgena, construir caminos empresariales en un mundo que no est\u00e1 dise\u00f1ado\u2026","rel":"","context":"En &quot;Al Cierre&quot;","block_context":{"text":"Al Cierre","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/al-cierre\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/03\/IMG-20260325-WA0213.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/03\/IMG-20260325-WA0213.jpg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/03\/IMG-20260325-WA0213.jpg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/03\/IMG-20260325-WA0213.jpg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/03\/IMG-20260325-WA0213.jpg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":6014,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2019\/03\/28\/va-por-carcel-de-33-anos-a-quienes-agredan-con-acido-a-mujeres\/","url_meta":{"origin":10234,"position":1},"title":"Va por c\u00e1rcel de 33 a\u00f1os a\u00a0quienes agredan con \u00e1cido a mujeres.","author":"jaime","date":"marzo 28, 2019","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO \u00a0 De diez a 15 a\u00f1os de prisi\u00f3n a quien lesione a una mujer por raz\u00f3n de g\u00e9nero y hasta 33 a\u00f1os de prisi\u00f3n a quien lo haga con sustancias corrosivas como el \u00e1cido, plantearon los senadores del Partido Verde Ecologista de M\u00e9xico. La propuesta arropada\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":21338,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2021\/10\/01\/eufrosina-presenta-leyivonne-en-san-lazaro-para-erradicar-violencia-politica-vs-mujeres-en-campanas\/","url_meta":{"origin":10234,"position":2},"title":"Eufrosina presenta #LeyIvonne en San L\u00e1zaro para   erradicar violencia pol\u00edtica vs mujeres en campa\u00f1as.","author":"ariadna","date":"octubre 1, 2021","format":"video","excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO Eufrosina Cruz Mendoza, se levant\u00f3 de su curul para enfilarse al atril, al pie de la Mesa Directiva de la C\u00e1mara de Diputados y enunciar su iniciativa de reforma a la Ley General de Acceso de las Mujeres a una Vida Libre de Violencia para establecer\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":350,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2018\/06\/14\/demandan-oaxaquenas-proceso-electoral-en-paz\/","url_meta":{"origin":10234,"position":3},"title":"Demandan oaxaque\u00f1as proceso electoral en paz","author":"citlali","date":"junio 14, 2018","format":false,"excerpt":"Para exigir elecciones en paz, integrantes de distintos colectivos e instituciones p\u00fablicas, protestaron frente a Santo Domingo, como parte de la convocatoria nacional bajo el #AltoALaViolenciaPol\u00edtica. \u201cRechazamos tajantemente la violencia que se ha instalado en este pa\u00eds, cobrando la vida de m\u00e1s de un centenar de hombres y mujeres en\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":146,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2018\/06\/11\/graffiteros-de-san-juanito-dan-sentido-social-a-arte-urbano\/","url_meta":{"origin":10234,"position":4},"title":"Graffiteros de San Juanito dan sentido social a arte urbano","author":"citlali","date":"junio 11, 2018","format":false,"excerpt":"El graffiti plasma a un ni\u00f1o con un libro como un deseo para cientos de infantes que trabajan como jornaleros agr\u00edcolas en los ca\u00f1averales del pa\u00eds. Utilizando la calle como lienzo y para demostrar el sentido social que tiene el arte urbano, jovenes de San Juan Chapultepec agrupados en la\u2026","rel":"","context":"En &quot;Mesa de Redacci\u00f3n&quot;","block_context":{"text":"Mesa de Redacci\u00f3n","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/mesa-de-redaccion\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2018\/06\/grafiti-3-300x200.jpeg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":37868,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2025\/08\/14\/congreso-de-oaxaca-armoniza-el-codigo-penal-local-con-estandares-internacionales-de-derechos-humanos-en-materia-de-violencia-sexual\/","url_meta":{"origin":10234,"position":5},"title":"Congreso de Oaxaca armoniza el C\u00f3digo Penal local con est\u00e1ndares internacionales de derechos humanos en materia de violencia sexual","author":"ariadna","date":"agosto 14, 2025","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca * Con la reforma al C\u00f3digo Penal del Estado se da un paso importante hacia la protecci\u00f3n de las v\u00edctimas de este delito * La LXVI legislatura reafirma su compromiso con los grupos en situaci\u00f3n de vulnerabilidad San Raymundo Jalpan, Oax., a 14 de agosto de 2025.- Con\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/08\/Screenshot_20250814_185155_Facebook-scaled.jpg?fit=1200%2C672&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/08\/Screenshot_20250814_185155_Facebook-scaled.jpg?fit=1200%2C672&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/08\/Screenshot_20250814_185155_Facebook-scaled.jpg?fit=1200%2C672&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/08\/Screenshot_20250814_185155_Facebook-scaled.jpg?fit=1200%2C672&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/08\/Screenshot_20250814_185155_Facebook-scaled.jpg?fit=1200%2C672&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/10234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/comments?post=10234"}],"version-history":[{"count":1,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/10234\/revisions"}],"predecessor-version":[{"id":10238,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/10234\/revisions\/10238"}],"wp:attachment":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/media?parent=10234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/categories?post=10234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/tags?post=10234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}