{"id":1546,"date":"2018-07-26T09:25:43","date_gmt":"2018-07-26T14:25:43","guid":{"rendered":"http:\/\/redaccionoaxaca.com\/?p=1546"},"modified":"2018-07-26T09:54:15","modified_gmt":"2018-07-26T14:54:15","slug":"confirman-construccion-de-carretera-de-cuatro-carriles-entre-pochutla-bahias-de-huatulco","status":"publish","type":"post","link":"https:\/\/redaccionoaxaca.com\/index.php\/2018\/07\/26\/confirman-construccion-de-carretera-de-cuatro-carriles-entre-pochutla-bahias-de-huatulco\/","title":{"rendered":"Confirman construcci\u00f3n de carretera de cuatro carriles entre Pochutla-Bah\u00edas de Huatulco"},"content":{"rendered":"<p class=\"x_MsoNormal\"><strong>#Redacci\u00f3nOaxaca<\/strong><\/p>\n<p>F\u00e9lix Garc\u00eda<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Oaxaca, Oax., 26 Julio 2018.- El Director del Centro de la Secretar\u00eda de Comunicaciones y Transportes (SCT) en Oaxaca, Javier Lazcano, confirm\u00f3 la modernizaci\u00f3n de la carretera federal de la zona de la costa que ser\u00e1 de cuatro carriles entre Pochutla y al entronque del aeropuerto de Bah\u00edas de Huatulco.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">En entrevista con Oro Divisi\u00f3n Noticias, el funcionario federal, explic\u00f3 que tambi\u00e9n est\u00e1 contemplado la modernizaci\u00f3n de la v\u00eda Puerto Escondido-Pochutla, proyecto que permitir\u00e1 una comunicaci\u00f3n m\u00e1s \u00e1gil en la regi\u00f3n que vendr\u00e1 a beneficiar no solo al turismo sino a productores que distribuyen su producci\u00f3n en la zona tur\u00edstica de Bah\u00edas de Huatulco.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Javier Lazcano, destac\u00f3 por otro lado que los recursos para la construcci\u00f3n de la autopista hacia la costa que llevan un 50 por ciento de avance, el gobierno federal y con el apoyo del gobierno estatal, han asegurado los recursos para avanzar con estas obras como el acueducto y t\u00faneles en el kil\u00f3metro117 para que en el segundo semestre se avance, donde se tiene una inversi\u00f3n total en esta etapa del orden de los Tres mil 200 millones de pesos, a cargo de Banobras.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Antes coment\u00f3 que se mantiene atenci\u00f3n a carreteras de la zona de la mixteca, las cuales resultaron sumamente afectadas a consecuencia de las lluvias, entre ellas la v\u00eda Tlaxiaco-Putla Villa de Guerrero, Putla-Zacatepec, los cuales se est\u00e1n interviniendo en este momento y que se culminar\u00e1 en breve.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">Agreg\u00f3 que el mantenimiento a la carretera federal 125 Tlaxiaco-Pinotepa Nacional y las carreteras alimentadoras, se est\u00e1n efectuando y ayer mismo junto con autoridades municipales supervisaron los avances de los trabajos de mantenimiento de la v\u00eda El Ojite-Tlaxiaco.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1547\" src=\"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2018\/07\/WhatsApp-Image-2018-07-26-at-09.14.50-300x169.jpeg?resize=300%2C169\" alt=\"\" width=\"300\" height=\"169\" \/><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1548\" src=\"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2018\/07\/WhatsApp-Image-2018-07-26-at-09.14.49-300x169.jpeg?resize=300%2C169\" alt=\"\" width=\"300\" height=\"169\" \/><\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/qAX6HF59HFM?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=es-MX&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>#Redacci\u00f3nOaxaca F\u00e9lix Garc\u00eda Oaxaca, Oax., 26 Julio 2018.- El Director del Centro de la Secretar\u00eda de Comunicaciones y Transportes (SCT) en Oaxaca, Javier Lazcano, confirm\u00f3 la modernizaci\u00f3n de la carretera federal de la zona de la costa que ser\u00e1 de cuatro carriles entre Pochutla y al entronque del aeropuerto de Bah\u00edas de Huatulco. En entrevista [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4],"tags":[218,14,215,217,216,206],"class_list":{"0":"post-1546","1":"post","2":"type-post","3":"status-publish","4":"format-video","6":"category-agenda-politica","7":"tag-entro-de-la-secretaria-de-comunicaciones-y-transportes-sct","8":"tag-oaxaca","9":"tag-pinotepa-nacional","10":"tag-putla-villa-de-guerrero","11":"tag-putla-zacatepec","12":"tag-tlaxiaco","13":"post_format-post-format-video"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9Ynjw-oW","jetpack-related-posts":[{"id":39623,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2025\/12\/27\/supervisa-titular-de-la-sict-modernizacion-de-la-carretera-pochutla-huatulco\/","url_meta":{"origin":1546,"position":0},"title":"Supervisa titular de la SICT modernizaci\u00f3n de la carretera Pochutla-Huatulco","author":"ariadna","date":"diciembre 27, 2025","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO El secretario de Infraestructura, Comunicaciones y Transportes (SICT), Jes\u00fas Antonio Esteva Medina, realiz\u00f3 una visita de supervisi\u00f3n a los trabajos de modernizaci\u00f3n y ampliaci\u00f3n de la carretera Pochutla-Huatulco, en el estado de Oaxaca, una obra estrat\u00e9gica para el desarrollo econ\u00f3mico y tur\u00edstico de la regi\u00f3n. El\u2026","rel":"","context":"En &quot;Imagen&quot;","block_context":{"text":"Imagen","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/imagen\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/12\/IMG-20251227-WA0084.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/12\/IMG-20251227-WA0084.jpg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/12\/IMG-20251227-WA0084.jpg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/12\/IMG-20251227-WA0084.jpg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/12\/IMG-20251227-WA0084.jpg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":19052,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2021\/05\/19\/alerta-maxima-por-lluvias-en-oaxaca-declara-el-titular-de-cao-ante-deslaves-y-desgajes-de-cerros\/","url_meta":{"origin":1546,"position":1},"title":"ALERTA M\u00c1XIMA POR LLUVIAS EN OAXACA, DECLARA EL TITULAR DE CAO ANTE DESLAVES Y DESGAJES DE CERROS.","author":"ariadna","date":"mayo 19, 2021","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca El titular de Caminos y Aeropistas de Oaxaca (CAO), David Mayr\u00e9n, indic\u00f3 que la entidad se encuentra en alerta m\u00e1xima por el inicio de la temporada de lluvias que provocan deslaves y afectaciones en carreteras y caminos.,tan s\u00f3lo las registradas el pasado lunes dejaron da\u00f1os en dos tramos\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2021\/05\/IMG-20210519-WA0122-300x205.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":25883,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2022\/06\/01\/luto-y-devastacion-por-agatha-en-oaxaca-11-muertos-33-desaparecidos-municipios-de-costa-sierra-sur-e-istmo-siniestrados\/","url_meta":{"origin":1546,"position":2},"title":"Luto y devastaci\u00f3n por Agatha en Oaxaca: 11 muertos,  33 desaparecidos; municipios de Costa, Sierra Sur e Istmo siniestrados","author":"ariadna","date":"junio 1, 2022","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO Luto y devastaci\u00f3n dej\u00f3 a su paso por Oaxaca el hurac\u00e1n Agatha. Hasta ayer por la noche se reportaban 11 personas fallecidas y al menos 33 desaparecidas. LA furia del hurac\u00e1n provoc\u00f3 que algunas personas quedaran sepultadas bajo lodo y otras m\u00e1s fuera arrastradas por r\u00edos\u2026","rel":"","context":"En &quot;Imagen&quot;","block_context":{"text":"Imagen","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/imagen\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":10944,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2020\/03\/02\/negligencia-criminal-en-hospitales-de-la-costa\/","url_meta":{"origin":1546,"position":3},"title":"NEGLIGENCIA CRIMINAL EN HOSPITALES DE LA COSTA.","author":"ariadna","date":"marzo 2, 2020","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Un hombre accidentado estuvo 5 horas a bordo de una ambulancia en estado cr\u00edtico sin que fuera admitido en los hospitales p\u00fablicos de Bah\u00edas de #Huatulco y en San Pedro Pochutla en donde argumentaron que no ten\u00edan personal m\u00e9dico de guardia, ni espacio, ni insumos elementales. Desesperados por\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2020\/03\/IMG-20200302-WA0056-300x169.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":436,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2018\/06\/19\/se-mantiene-busqueda-de-joven-desaparecido-en-la-costa-de-oaxaca-cepco\/","url_meta":{"origin":1546,"position":4},"title":"Se mantiene b\u00fasqueda de joven desaparecido en la Costa de Oaxaca: CEPCO","author":"denise","date":"junio 19, 2018","format":false,"excerpt":"COMUNICADO DE PRENSA: Oaxaca de Ju\u00e1rez, Oax. 19 de junio de 2018. El Gobierno del Estado a trav\u00e9s de la Coordinaci\u00f3n Estatal de Protecci\u00f3n Civil de Oaxaca (CEPCO) informa que se mantiene la b\u00fasqueda del joven E.G.V. quien fuera arrastrado por un arroyo el pasado s\u00e1bado. La CEPCO indica que\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2018\/06\/WhatsApp-Image-2018-06-19-at-12.04.15-300x225.jpeg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4602,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2018\/12\/24\/super-a-la-costa-e-istmo-representan-la-corrupcion-murat-el-pais-es-un-cementerio-de-obras-amlo\/","url_meta":{"origin":1546,"position":5},"title":"S\u00faper a la Costa e Istmo, representan la  corrupci\u00f3n:  Murat; el pais es un cementerio de obras: AMLO.","author":"jaime","date":"diciembre 24, 2018","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO De acuerdo al Gobernador, Alejandro Murat Hinojosa, la s\u00faper carretera Oaxaca-Istmo representa la corrupci\u00f3n y la negligencia, porque se han tardado m\u00e1s de 10 a\u00f1os sin poderse concluir. Ante el presidente de la rep\u00fablica, Andr\u00e9s Manuel L\u00f3pez Obrador, manifest\u00f3 que los grandes anhelos de Oaxaca son\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2018\/12\/IMG-20181224-WA0029-300x200.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/1546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/comments?post=1546"}],"version-history":[{"count":5,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/1546\/revisions"}],"predecessor-version":[{"id":1557,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/1546\/revisions\/1557"}],"wp:attachment":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/media?parent=1546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/categories?post=1546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/tags?post=1546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}