{"id":18736,"date":"2021-05-04T20:45:39","date_gmt":"2021-05-05T01:45:39","guid":{"rendered":"http:\/\/redaccionoaxaca.com\/?p=18736"},"modified":"2021-05-04T20:45:39","modified_gmt":"2021-05-05T01:45:39","slug":"crisis-del-agua-se-agudiza-sapao-sin-capacidad-para-abastecer-ni-el-50-de-la-demanda-en-la-ciudad-los-rangos-de-espera-en-tandeo-llegan-a-casi-un-mes","status":"publish","type":"post","link":"https:\/\/redaccionoaxaca.com\/index.php\/2021\/05\/04\/crisis-del-agua-se-agudiza-sapao-sin-capacidad-para-abastecer-ni-el-50-de-la-demanda-en-la-ciudad-los-rangos-de-espera-en-tandeo-llegan-a-casi-un-mes\/","title":{"rendered":"Crisis del agua se agudiza, SAPAO sin capacidad para abastecer ni el 50% de la demanda en la Ciudad; los rangos de espera en tandeo llegan a casi un mes."},"content":{"rendered":"<p><strong>#Redacci\u00f3nOaxaca<\/strong><\/p>\n<p><strong>#Oaxaca<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Maira Ric\u00e1rdez<\/strong><\/p>\n<p>*<em>Indispensable la cultura de reciclaje por parte de la ciudadan\u00eda para no llegar a momentos insostenibles<\/em><\/p>\n<p style=\"text-align: justify;\">La crisis por el agua se agudiza d\u00eda a d\u00eda en Oaxaca igual que en el resto del pa\u00eds y del mundo, reconoci\u00f3 el Director T\u00e9cnico del Sistema de Agua Potable de Oaxaca (<strong>#SAPAO<\/strong>), actual encargado de la dependencia, Arq. Miguel \u00c1ngel Morales Morales.<\/p>\n<p style=\"text-align: justify;\">Sapao dispone de aguas superficiales a trav\u00e9s del abastecimiento en San Agust\u00edn Etla, y complementa con 39 pozos profundos, sistemas que en conjunto aportan 420 litros de agua por segundo para los habitantes de 350 colonias de Oaxaca de Ju\u00e1rez y 9 municipios conurbados, 420 litros que no son ni la mitad de la demanda real en la ciudad, que es de 960, casi mil litros por segundo, de ah\u00ed la cada vez m\u00e1s espaciada distribuci\u00f3n en los hogares Oaxaque\u00f1os.<\/p>\n<p style=\"text-align: justify;\">La escasez es cada vez m\u00e1s evidente reconoci\u00f3 el Directivo, en zonas donde el n\u00famero de habitantes crece cada d\u00eda como lo son las ciudades, por ejemplo, los Valles Centrales de Oaxaca. La soluci\u00f3n a corto plazo por parte de SAPAO ha sido, cuidar las fuentes disponibles, no sobre explotarlas para no exponer a Oaxaca y sus habitantes a un problema may\u00fasculo, por ello se trabaja bajo un sistema ordenado de tandeo, actualmente la disponibilidad de agua por colonias va de los 17 a los 22 d\u00edas entre servicio y servicio, reconoci\u00f3.<\/p>\n<p style=\"text-align: justify;\">El sevidor, con m\u00e1s de 15 a\u00f1os de servicio en SAPAO dijo que la propuesta de soluci\u00f3n para el sistema operador de agua en esta ciudad, es eficiente las redes de distribuci\u00f3n disponibles para evitar desperdicio del vital l\u00edquido y la construcci\u00f3n de nuevas l\u00edneas de mantenimiento para distribuci\u00f3n. Este 2021 es cr\u00edtico reconoci\u00f3 y lo ser\u00e1 m\u00e1s si es de lluvias minimas, por lo que la misma SAPAO est\u00e1 invirtiendo en proyectos de reforestaci\u00f3n que revitalicen el ecosistema y que puedan redituar agua.<\/p>\n<p style=\"text-align: justify;\">Otro de los factores indispensables es la racionalidad con que la poblaci\u00f3n use e agua, economizar reutilizando el agua de la lavadora y minimizando el chorrro al momento de ba\u00f1arse, deberemos invertir en alg\u00fan recipiente de buen tama\u00f1o para acopiar agua de lluvia o en su caso almacenar en el mismo cuando llegue el agua potable a casa, pues un tinaco de 1,100 litros es insuficiente por mes para una familia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>#Redacci\u00f3nOaxaca #Oaxaca Maira Ric\u00e1rdez *Indispensable la cultura de reciclaje por parte de la ciudadan\u00eda para no llegar a momentos insostenibles La crisis por el agua se agudiza d\u00eda a d\u00eda en Oaxaca igual que en el resto del pa\u00eds y del mundo, reconoci\u00f3 el Director T\u00e9cnico del Sistema de Agua Potable de Oaxaca (#SAPAO), actual [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[7,5,3,6,1],"tags":[],"class_list":{"0":"post-18736","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-al-cierre","7":"category-imagen","8":"category-mesa-de-redaccion","9":"category-tendencias","10":"category-uncategorized"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9Ynjw-4Sc","jetpack-related-posts":[{"id":2581,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2018\/09\/21\/periodo-de-lluvias-agudiza-riesgo-de-socavones-en-oaxaca\/","url_meta":{"origin":18736,"position":0},"title":"Per\u00edodo de lluvias agudiza riesgo de socavones en Oaxaca","author":"denise","date":"septiembre 21, 2018","format":false,"excerpt":"#Redacci\u00f3nOaxaca Maira Ric\u00e1rdez El actual per\u00edodo de lluvias agudiza el riesgo de socavones tambi\u00e9n en Oaxaca, en las \u00faltimas horas, obreros con equipo especializado trabajan en la reparaci\u00f3n del \u00faltimo reportado, de considerable dimensi\u00f3n, registrado en la Col. Reforma Agraria.\u00a0\u00a0La humedad en el pavimento genera reblandecimiento y si a esto\u2026","rel":"","context":"En &quot;Tendencias&quot;","block_context":{"text":"Tendencias","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/tendencias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":6791,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2019\/05\/13\/distribucion-de-agua-en-pipas-gran-estrategia-contra-estiaje-en-este-mes-critico-de-mayo-sapao\/","url_meta":{"origin":18736,"position":1},"title":"Distribuci\u00f3n de agua en pipas, gran estrategia contra estiaje en este mes critico de mayo: SAPAO","author":"denise","date":"mayo 13, 2019","format":false,"excerpt":"#Redacci\u00f3nOaxaca Maira Ric\u00e1rdez De acuerdo a la Comisi\u00f3n Nacional del Agua (Conagua) Gerencia Pac\u00edfico Sur, los meses de abril y mayo ser\u00edan los m\u00e1s cr\u00edticos por la falta de agua este 2019, el estiaje afectar\u00eda no solo los hogares, sino tambi\u00e9n al agro y esto engloba todos los trabajos del\u2026","rel":"","context":"En &quot;Tendencias&quot;","block_context":{"text":"Tendencias","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/tendencias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":549,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2018\/06\/22\/sapao-no-incrementara-tarifas-en-oaxaca-en-lo-inmediato-hacen-falta-recursos-millonarios-pero-en-todo-caso-el-tema-compete-a-los-diputados-sapao\/","url_meta":{"origin":18736,"position":2},"title":"Sapao no incrementar\u00e1 tarifas en Oaxaca en lo inmediato, hacen falta  recursos millonarios pero en todo caso el tema compete a los Diputados: SAPAO","author":"denise","date":"junio 22, 2018","format":false,"excerpt":"#Redacci\u00f3nOaxaca Maira Ricardez Los 10 decretos de Veda de 295 Cuencas de todo el pa\u00eds no significan el incremento de tarifas de agua potable de Oaxaca de Ju\u00e1rez y zona conurbada, aseguro el Asesor T\u00e9cnico del Sistema de Agua Potable y Alcantarilladlo de Oaxaca (SAPAO), Miguel \u00c1ngel Morales Morales. En\u2026","rel":"","context":"En &quot;Mesa de Redacci\u00f3n&quot;","block_context":{"text":"Mesa de Redacci\u00f3n","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/mesa-de-redaccion\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8153,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2019\/08\/26\/en-alerta-sapao-ante-posibles-colapso-del-sistema-por-lluvias\/","url_meta":{"origin":18736,"position":3},"title":"En alerta SAPAO ante posibles colapso del sistema por lluvias.","author":"ariadna","date":"agosto 26, 2019","format":false,"excerpt":"\u00a0 \u00a0 \u00a0 \u00a0 #Redacci\u00f3nOaxaca #Oaxaca Maira Ric\u00e1rdez *Mu\u00f1ecas, cobijas y hasta un becerro, han sido sacados del drenaje en diversos momentos del a\u00f1o La intempestiva lluvia que ba\u00f1o parte de la ciudad este domingo, colaps\u00f3 el c\u00e1rcamo de bombeo Tecnol\u00f3gico que suministra el vital liquido a parte importante la\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":19964,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2021\/08\/11\/sapao-realiza-trabajos-de-desasolve-de-300-registros-del-mercado-20-de-noviembre-en-la-capital-de-oaxaca\/","url_meta":{"origin":18736,"position":4},"title":"SAPAO realiz\u00f3 trabajos de desasolve de 300 registros, del Mercado 20 de noviembre.","author":"ariadna","date":"agosto 11, 2021","format":"video","excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Ariadna Mendoza Este mi\u00e9rcoles, los Servicios de Agua Potable y Alcantarillado de Oaxaca (#SAPAO) llevaron acabo trabajos de desazolve de tuber\u00edas, rejillas y saneamiento del sistema sanitario y pluvial del mercado 20 de noviembre, esto con el objetivo de mantener un espacio limpio, y libre de fauna nociva,\u2026","rel":"","context":"En &quot;Al Cierre&quot;","block_context":{"text":"Al Cierre","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/al-cierre\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2021\/08\/IMG-20210811-WA0104-300x139.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":16171,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2021\/01\/12\/fuga-invisible-sapao-la-corrige\/","url_meta":{"origin":18736,"position":5},"title":"VIDEO:   FUGA INVISIBLE! SAPAO LA CORRIGE.","author":"ariadna","date":"enero 12, 2021","format":"video","excerpt":"\u00a0 #Redacci\u00f3nOaxaca #Oaxaca Humberto Cruz A pesar del peligro por la imprudencia de los automovilistas que no respetan la se\u00f1alizaci\u00f3n, personal de SAPAO detect\u00f3 y repara una l\u00ednea a de conducci\u00f3n de 10 pulgadas que abastece de agua a gran parte de la zona centro y sur- oriente; de la\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/18736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/comments?post=18736"}],"version-history":[{"count":1,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/18736\/revisions"}],"predecessor-version":[{"id":18738,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/18736\/revisions\/18738"}],"wp:attachment":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/media?parent=18736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/categories?post=18736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/tags?post=18736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}