{"id":25022,"date":"2022-04-14T14:21:32","date_gmt":"2022-04-14T19:21:32","guid":{"rendered":"https:\/\/redaccionoaxaca.com\/?p=25022"},"modified":"2022-04-14T14:21:32","modified_gmt":"2022-04-14T19:21:32","slug":"mexico-es-un-pais-soberano-amigo-de-todo-el-mundo-sorprende-el-tono-en-que-e-u-pretende-sojuzgar-voluntades-en-el-mundo-no-lo-habremos-de-permitir","status":"publish","type":"post","link":"https:\/\/redaccionoaxaca.com\/index.php\/2022\/04\/14\/mexico-es-un-pais-soberano-amigo-de-todo-el-mundo-sorprende-el-tono-en-que-e-u-pretende-sojuzgar-voluntades-en-el-mundo-no-lo-habremos-de-permitir\/","title":{"rendered":"M\u00e9xico es un pa\u00eds soberano amigo de todo el mundo, sorprende el tono en que E.U. pretende sojuzgar voluntades en el mundo, no lo habremos de permitir."},"content":{"rendered":"<p><strong>#Redacci\u00f3nOaxaca<\/strong><\/p>\n<p><strong>#Oaxaca<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Maira Ric\u00e1rdez<\/strong><\/p>\n<p>Los Diputados Federales Oaxaque\u00f1os nos mantenemos en el rechazo de posturas injerencistas en las decisiones del pa\u00eds, el debate se da a ra\u00edz de la postura de un congresista Estadounidense de quitar visas a quienes ellos consideren amigos de Rusia, record\u00f3 el Diputado Federal Oaxaque\u00f1o, Armando Contreras Castillo., avalamos dijo la postura del presidente de M\u00e9xico, de una nota diplom\u00e1tica en caso de que la intenci\u00f3n persista.<\/p>\n<p style=\"text-align: justify;\">Fue el mismo presidente de la C\u00e1mara de Diputados, Sergio Guti\u00e9rrez Luna, quien se pronunci\u00f3 contra la demanda del congresista estadounidense Vicente Gonz\u00e1lez de retirar las visas a los 25 legisladores mexicanos que forman parte del Grupo de Amistad M\u00e9xico-Rusia., yo ni visa americana vigente tengo dijo el Diputado Oaxaque\u00f1o, pero la postura radical del legislador americano es, inaceptable consider\u00f3.<\/p>\n<p style=\"text-align: justify;\">Yo soy aut\u00e9nticamente dem\u00f3crata declar\u00f3 y creo, avalo y pele\u00f3 la soberan\u00eda del pa\u00eds, M\u00e9xico debe de mantener amistad con todo el mundo e incluso refiri\u00f3 que el tema deriva de una tradici\u00f3n legislativa federal donde la C\u00e1mara instala lazos de amistad con al menos 100 pa\u00edses del mundo y no por posturas de guerra ajenas a nuestro pa\u00eds esto habr\u00e1 de cambiar, M\u00e9xico no participa de ninguna manera en ese conflicto y en este grupo de amistad la postura de las y los Diputados de M\u00e9xico es que pronto el conflicto termine y se instale la paz entre Rusia y Ucrania.<\/p>\n<p style=\"text-align: justify;\">Armando Contreras fue m\u00e1s all\u00e1 y dijo que entre M\u00e9xico y Rusia hay coincidencias hist\u00f3ricas, en 1910 la lucha para terminar con la dictadura de Porfirio D\u00edaz, as\u00ed como Rusia en 1917 Rusia gest\u00f3 una lucha interna para acabar con el zarismo y el feudalismo que representaba, y que fueron dijo las dos primeras revoluciones del siglo pasado.<\/p>\n<p style=\"text-align: justify;\">En este contexto, la C\u00e1mara de Diputados promover\u00e1 y defender\u00e1 la libertad de sus integrantes para desempe\u00f1ar las labores legislativas y parlamentarias conferidas por el pueblo de M\u00e9xico, plasmadas en la ley suprema, as\u00ed como el derecho a la libertad de expresi\u00f3n, no hay raz\u00f3n para pretender que M\u00e9xico tome partido sostuvo, en una guerra que no es nuestra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>#Redacci\u00f3nOaxaca #Oaxaca Maira Ric\u00e1rdez Los Diputados Federales Oaxaque\u00f1os nos mantenemos en el rechazo de posturas injerencistas en las decisiones del pa\u00eds, el debate se da a ra\u00edz de la postura de un congresista Estadounidense de quitar visas a quienes ellos consideren amigos de Rusia, record\u00f3 el Diputado Federal Oaxaque\u00f1o, Armando Contreras Castillo., avalamos dijo la [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4,5],"tags":[],"class_list":{"0":"post-25022","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-agenda-politica","7":"category-imagen"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9Ynjw-6vA","jetpack-related-posts":[{"id":39733,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2026\/01\/04\/senador-murat-rechaza-injerencia-de-eu-y-responde-a-congresista-a-mexico-y-su-presidenta-hay-que-respetarlo-no-darle-sermones\/","url_meta":{"origin":25022,"position":0},"title":"Senador Murat rechaza injerencia de EU y responde a Congresista: \u201ca M\u00e9xico y su Presidenta hay que respetarlo, no darle sermones\u201d","author":"ariadna","date":"enero 4, 2026","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO El presidente de la Comisi\u00f3n de Relaciones Exteriores del Senado de la Rep\u00fablica, Alejandro Murat Hinojosa, sali\u00f3 al paso de los se\u00f1alamientos de la congresista republicana Anna Paulina Luna, quien cuestion\u00f3 la legitimidad democr\u00e1tica de la presidenta Claudia Sheinbaum Pardo y sugiri\u00f3 que los c\u00e1rteles del\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/01\/InShot_20260104_111114419.jpg?fit=1200%2C768&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/01\/InShot_20260104_111114419.jpg?fit=1200%2C768&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/01\/InShot_20260104_111114419.jpg?fit=1200%2C768&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/01\/InShot_20260104_111114419.jpg?fit=1200%2C768&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/01\/InShot_20260104_111114419.jpg?fit=1200%2C768&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":35483,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2025\/02\/05\/sheinbaum-llama-a-ip-a-fortalecer-plan-mexico\/","url_meta":{"origin":25022,"position":1},"title":"SHEINBAUM LLAMA A IP A FORTALECER PLAN M\u00c9XICO","author":"ariadna","date":"febrero 5, 2025","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO La Presidenta Claudia Sheinbaum hizo un llamado al sector empresarial para fortalecer el Plan M\u00e9xico con el objetivo de impulsar el desarrollo del pa\u00eds en beneficio de las mexicanas y los mexicanos, esto durante un encuentro con 302 representantes de la iniciativa privada en Palacio Nacional.\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":9584,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2019\/12\/12\/sera-austero-el-presupuesto-y-con-sentido-social-afirmo-presidente-del-congreso\/","url_meta":{"origin":25022,"position":2},"title":"Ser\u00e1 austero el presupuesto y con sentido social, afirmo Presidente del Congreso.","author":"ariadna","date":"diciembre 12, 2019","format":false,"excerpt":"#Reacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO El Presidente de la Junta de Coordinaci\u00f3n Pol\u00edtica de la C\u00e1mara de Diputados, Horacio Sosa Villavicencio, afirm\u00f3 que habr\u00e1 austeridad en el gasto de los diputados. No habr\u00e1 incrementos a salarios y desestim\u00f3 acuerdos en lo oscurito con la Secretar\u00eda de Finanzas, en la confecci\u00f3n del\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":10130,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2020\/01\/15\/sergio-mayer-recula-promete-retirar-nombre-de-francisco-toledo-en-medalla-cultural-que-instauro-congreso-federal\/","url_meta":{"origin":25022,"position":3},"title":"Sergio Mayer recula, promete retirar nombre de Francisco Toledo en medalla cultural que instaur\u00f3 Congreso Federal.","author":"ariadna","date":"enero 15, 2020","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO Tras las peticiones de la familia del artista pl\u00e1stico y fil\u00e1ntropo Francisco Toledo, la C\u00e1mara de Diputados Federales, acord\u00f3 retirar su nombre de la medalla que se otorgar\u00eda a la persona que destaque art\u00edsticamente y este comprometido con la labor social. En su lugar se buscar\u00e1\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":7786,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2019\/07\/31\/morena-apoyara-a-amlo-en-su-lucha-por-un-pais-mas-justo-afirman-diputados-federales-oaxaquenos-de-morena\/","url_meta":{"origin":25022,"position":4},"title":"Morena apoyar\u00e1 a AMLO en su lucha por un pa\u00eds m\u00e1s justo, afirman diputados federales oaxaque\u00f1os de Morena.","author":"jaime","date":"julio 31, 2019","format":false,"excerpt":"\u00a0 #Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO\u00a0 Las prioridades de la agenda legislativa de la bancada de Morena, para el pr\u00f3ximo periodo ordinario de sesiones, que inicia\u00a0el 1 de septiembre, est\u00e1n aprobar la Ley de Austeridad y crear el Instituto Nacional de Salud para el Bienestar. Asimismo, garantizar recursos suficientes en el\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2019\/07\/morena1-300x200.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":35410,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2025\/01\/30\/entre-aplausos-despiden-a-diputada-kelly-jannet-cabrera-gonzalez-la-primer-diputada-de-talla-baja-de-mexico\/","url_meta":{"origin":25022,"position":5},"title":"Entre aplausos, despiden a diputada Kelly Jannet Cabrera Gonz\u00e1lez; la primer diputada de talla baja de M\u00e9xico","author":"ariadna","date":"enero 30, 2025","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO El recinto legislativo del Congreso del Estado, fue la primer parada para despedir a la diputada Kelly Jannet Cabrera Gonz\u00e1lez, quien falleci\u00f3 la noche de este mi\u00e9rcoles de una afecci\u00f3n cardiaca. Su labor trascendi\u00f3 el \u00e1mbito legislativo, convirti\u00e9ndose en un ejemplo y s\u00edmbolo de resistencia, inclusi\u00f3n,\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/25022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/comments?post=25022"}],"version-history":[{"count":1,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/25022\/revisions"}],"predecessor-version":[{"id":25024,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/25022\/revisions\/25024"}],"wp:attachment":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/media?parent=25022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/categories?post=25022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/tags?post=25022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}