{"id":27067,"date":"2022-08-03T09:56:04","date_gmt":"2022-08-03T14:56:04","guid":{"rendered":"https:\/\/redaccionoaxaca.com\/?p=27067"},"modified":"2022-08-03T09:56:04","modified_gmt":"2022-08-03T14:56:04","slug":"aventando-sus-desechos-dentro-de-palacio-y-en-la-plaza-de-la-danza-catem-exige-dialogo-con-el-municipio","status":"publish","type":"post","link":"https:\/\/redaccionoaxaca.com\/index.php\/2022\/08\/03\/aventando-sus-desechos-dentro-de-palacio-y-en-la-plaza-de-la-danza-catem-exige-dialogo-con-el-municipio\/","title":{"rendered":"Aventando sus desechos dentro de Palacio y en la plaza de la danza, CATEM exige di\u00e1logo con el Municipio"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>#Redacci\u00f3nOaxaca<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>#Oaxaca<\/strong><\/p>\n<p><strong>Maira Ric\u00e1rdez Luna<\/strong><\/p>\n<p style=\"text-align: justify;\">Miembros de la Confederaci\u00f3n Aut\u00f3noma de Trabajadores y Empleados de M\u00e9xico (CATEM) y del denonimado Sol Rojo, con mujeres al frente comenzaron est\u00e1 ma\u00f1ana a deserdigar sus desechos en la explanada de la plaza de la danza e incluso al interior del Palacio Municipal.<\/p>\n<p style=\"text-align: justify;\">Con la exigencia de que el ayuntamiento les consiga un espacio para descargar sus camiones copados de basura, a gritos Y aventando bolsas de basura exigen la presencia del Mun\u00edcipe Francisco Mart\u00ednez Neri .<\/p>\n<p style=\"text-align: justify;\">Los inconformes aseguran que cada viaje que hac\u00edan al tiradero pagaban 850 pesos a los encargados y ahora exigen que el Ayuntamiento consiga un lugar si los encargados han determinado ya no permitirles el paso.<\/p>\n<p style=\"text-align: justify;\">Tras cerca de 20 d\u00edas estacionados en el play\u00f3n de la central de Abasto, decidieron trasladar algunas de estas unidades con su pestilente carga al centro de la ciudad y desde temprana hora secuestraron la circulaci\u00f3n en calles principales afectando a cientos de ciudadanos, sus mismos clientes potenciales en las colonias donde cobran por llevarse la basura.<\/p>\n<p style=\"text-align: justify;\">&#8220;La autoridad municipal de Oaxaca de Ju\u00e1rez, no est\u00e1 en posibilidad de resolver los planteamientos de estos particulares que se dedican a recolectar por cuenta propia, los residuos s\u00f3lidos&#8221;, dijo con anticipaci\u00f3n Neri al descartar acciones para frenar la movilizaci\u00f3n por parte de los agremiados de CATEM .<\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-27067-1\" width=\"640\" height=\"352\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/redaccionoaxaca.com\/wp-content\/uploads\/2022\/08\/VID-20220803-WA0055.mp4?_=1\" \/><a href=\"https:\/\/redaccionoaxaca.com\/wp-content\/uploads\/2022\/08\/VID-20220803-WA0055.mp4\">https:\/\/redaccionoaxaca.com\/wp-content\/uploads\/2022\/08\/VID-20220803-WA0055.mp4<\/a><\/video><\/div>\n","protected":false},"excerpt":{"rendered":"<p>#Redacci\u00f3nOaxaca #Oaxaca Maira Ric\u00e1rdez Luna Miembros de la Confederaci\u00f3n Aut\u00f3noma de Trabajadores y Empleados de M\u00e9xico (CATEM) y del denonimado Sol Rojo, con mujeres al frente comenzaron est\u00e1 ma\u00f1ana a deserdigar sus desechos en la explanada de la plaza de la danza e incluso al interior del Palacio Municipal. Con la exigencia de que el [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5,3,6],"tags":[],"class_list":{"0":"post-27067","1":"post","2":"type-post","3":"status-publish","4":"format-video","6":"category-imagen","7":"category-mesa-de-redaccion","8":"category-tendencias","9":"post_format-post-format-video"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9Ynjw-72z","jetpack-related-posts":[{"id":27506,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2022\/08\/25\/recolectores-particulares-de-basura-exigen-que-ayuntamiento-les-resuelva-la-operatividad-de-su-negocio\/","url_meta":{"origin":27067,"position":0},"title":"Recolectores particulares de basura exigen que Ayuntamiento les resuelva la operatividad de su negocio","author":"ariadna","date":"agosto 25, 2022","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Maira Ric\u00e1rdez Luna *Para evitar que nuevamente corrieran sus desechos en Plaza de la Danza el Municipio determin\u00f3 el cierre de calles de acceso, los recolectores se han instalado en plant\u00f3n Recolectores particulares de basura adheridos a la Confederaci\u00f3n Nacional de Industriales de Metales y Recicladores (Conimer) respaldados\u2026","rel":"","context":"En &quot;Imagen&quot;","block_context":{"text":"Imagen","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/imagen\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":27686,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2022\/09\/06\/catem-merece-sanciones-estatales-y-federales-por-tirar-sus-desechos-en-riberas-senala-neri-informa-que-esta-avanzado-el-tramite-respecto-al-nuevo-terreno-para-el-tiradero-municipal-buscan-uno-mas\/","url_meta":{"origin":27067,"position":1},"title":"CATEM merece sanciones estatales y federales por tirar sus desechos en Riberas se\u00f1ala Neri; informa que est\u00e1 avanzado el tr\u00e1mite respecto al nuevo terreno para el tiradero municipal, buscan uno m\u00e1s","author":"ariadna","date":"septiembre 6, 2022","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Maira Ric\u00e1rdez Luna Lo que CATEM est\u00e1 haciendo al verter en las riberas del rio toda la basura que cobra por recoger, y al ser este un espacio p\u00fablico en plena ciudad de Oaxaca, el hecho constituye un atentado contra la salud que urge de soluci\u00f3n, reconoci\u00f3 el\u2026","rel":"","context":"En &quot;Imagen&quot;","block_context":{"text":"Imagen","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/imagen\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":27326,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2022\/08\/19\/de-manera-arbitraria-catem-descargo-toneladas-de-sus-desechos-en-riberas-del-atoyac\/","url_meta":{"origin":27067,"position":2},"title":"De manera arbitraria, CATEM descarg\u00f3 toneladas de sus desechos en Riberas del Atoyac","author":"ariadna","date":"agosto 19, 2022","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Maira Ric\u00e1rdez Adheridos a la Confederaci\u00f3n Aut\u00f3noma de Trabajadores y Empleados de M\u00e9xico (C.A.T.E.M.), recolectores privados de basura ponen en riesgo la salud de toda la ciudadan\u00eda, pues pese a que el problema es generalizado, y no hay a la fecha un tiradero municipal definido, ellos decidieron este\u2026","rel":"","context":"En &quot;Imagen&quot;","block_context":{"text":"Imagen","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/imagen\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":27016,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2022\/07\/29\/en-los-3-meses-que-fijaron-para-el-cierre-quienes-tienen-en-su-poder-el-basurero-en-zaachila-busca-oaxaca-solucion-emergente\/","url_meta":{"origin":27067,"position":3},"title":"En los 3 meses que fijaron para el cierre quienes tienen en su poder el basurero en Zaachila busca Oaxaca soluci\u00f3n emergente","author":"ariadna","date":"julio 29, 2022","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Maira Ric\u00e1rdez *El Ayuntamiento busca terreno y adquirir\u00e1 compactadora de basura El Presidente Municipal de Oaxaca de Ju\u00e1rez, Francisco Mart\u00ednez Neri, dijo en entrevista que en estos tres meses que determinaron como tregua los colonos que tienen en su poder el tiradero de Zaachila, el Ayuntamiento de Oaxaca\u2026","rel":"","context":"En &quot;Imagen&quot;","block_context":{"text":"Imagen","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/imagen\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":27467,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2022\/08\/24\/llego-a-oaxaca-prensa-que-compactara-entre-6-y-8-tons-diarias-de-basura-mientras-la-gran-prensa-que-procesara-25-tons-por-hora-de-toda-la-ciudad-esta-en-proceso-de-construccion\/","url_meta":{"origin":27067,"position":4},"title":"Lleg\u00f3 a Oaxaca prensa que compactar\u00e1 entre 6 y 8 tons. diarias de basura, mientras la gran prensa que procesar\u00e1 25 tons. por hora de toda la ciudad, est\u00e1 en proceso de construcci\u00f3n","author":"ariadna","date":"agosto 24, 2022","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Maira Ric\u00e1rdez Est\u00e1 ya en Oaxaca la prensa vertical adquirida por el Municipio capitalino, cuya funci\u00f3n ser\u00e1 la compactaci\u00f3n de entre 6 y 8 toneladas diarias de desechos colectados por los barrenderos de la ciudad, igual que los encargados de parques y jardines; la idea es que una\u2026","rel":"","context":"En &quot;Al Cierre&quot;","block_context":{"text":"Al Cierre","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/al-cierre\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":27323,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2022\/08\/19\/comerciantes-de-las-calles-de-oaxaca-exigen-garantias-al-municipio\/","url_meta":{"origin":27067,"position":5},"title":"Comerciantes de las calles de Oaxaca exigen garant\u00edas al Municipio","author":"ariadna","date":"agosto 19, 2022","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Maira Ric\u00e1rdez\u00a0 Comerciantes adheridos a distintas organizaciones mercantiles, marcharon la ma\u00f1ana de este mi\u00e9rcoles, del Mercado \"Benito Ju\u00e1rez\" al Palacio Municipal de Oaxaca de Ju\u00e1rez. Denunciaron hostigamiento por parte de inspectores municipales, adem\u00e1s exigen respeto a espacios que han tenido en la v\u00eda p\u00fablica desde hace varios a\u00f1os,\u2026","rel":"","context":"En &quot;Imagen&quot;","block_context":{"text":"Imagen","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/imagen\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/27067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/comments?post=27067"}],"version-history":[{"count":1,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/27067\/revisions"}],"predecessor-version":[{"id":27070,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/27067\/revisions\/27070"}],"wp:attachment":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/media?parent=27067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/categories?post=27067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/tags?post=27067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}