{"id":27078,"date":"2022-08-04T13:23:47","date_gmt":"2022-08-04T18:23:47","guid":{"rendered":"https:\/\/redaccionoaxaca.com\/?p=27078"},"modified":"2022-08-04T13:23:47","modified_gmt":"2022-08-04T18:23:47","slug":"oaxaca-con-deficit-de-5-626-profesionales-de-salud-requiere-de-2-775-5-mdp-para-equipar-hospitales-murat-jara-y-directores-de-salud-supervisan-unidades","status":"publish","type":"post","link":"https:\/\/redaccionoaxaca.com\/index.php\/2022\/08\/04\/oaxaca-con-deficit-de-5-626-profesionales-de-salud-requiere-de-2-775-5-mdp-para-equipar-hospitales-murat-jara-y-directores-de-salud-supervisan-unidades\/","title":{"rendered":"Oaxaca con d\u00e9ficit de 5, 626 profesionales de salud; requiere de 2, 775. 5 mdp  para equipar hospitales; Murat, Jara y directores de Salud supervisan unidades"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>#Redacci\u00f3nOaxaca<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>#Oaxaca<\/strong><\/p>\n<p><strong>Jaime GUERRERO<\/strong><\/p>\n<p style=\"text-align: justify;\">El gobernador del Estado, Alejandro Murat Hinojosa, su par electo, Salom\u00f3n Jara Cruz; el director del Instituto de Salud para el Bienestar (INSABI), Juan Antonio Ferrer Aguilar; del Instituto Mexicano del Seguro Social (IMSSE), Zoe Robledo Aburto; y Instituto de Seguridad y Servicios Sociales de los Trabajadores del Estado (ISSSTE), Pedro Zenteno Santaella, recorren la red hospitalaria del Valle Central.<\/p>\n<p style=\"text-align: justify;\">En en el inventario de necesidades de equipamiento e infraestructura del sistema oaxaque\u00f1o de salud, se detect\u00f3 un d\u00e9ficit de 5 mil 626 profesionales de salud y en un primer c\u00e1lculo indica que para el proceso de transici\u00f3n al IMSS-Bienestar se requiere de una inversi\u00f3n para infraestructura y equipamiento de 2 mil 775. 5 millones de pesos.<\/p>\n<p style=\"text-align: justify;\">Tambi\u00e9n, de cara al proceso de entrega recepci\u00f3n de la administraci\u00f3n gubernamental que entrar\u00e1 en funciones el pr\u00f3ximo 1 de noviembre, Murat Hinojosa, junto con los directores del sistema de salud del pa\u00eds muestran al pr\u00f3ximo gobernador, el Estado en el que se encuentra la red hospitalaria que administra el Estado.<\/p>\n<p style=\"text-align: justify;\">En un primer momento, los gobernadores constitucional y electo se reunieron con los funcionarios federales en el palacio de gobierno para exponer la situaci\u00f3n del sistema de salud y posteriormente supervisaron el hospital civil Aurelio Valdivieso, ubicado al norte de la capital.<\/p>\n<p style=\"text-align: justify;\">Posteriormente supervisan el Hospital de la Ni\u00f1ez Oaxaque\u00f1a, enseguida el Hospital General de la Mujer y el Ni\u00f1o Oaxaque\u00f1o.<\/p>\n<p style=\"text-align: justify;\">El objetivo, es ampliar el Programa IMSS-Bienestar en Oaxaca, como lo ha planteado el presidente, Andr\u00e9s Manuel L\u00f3pez Obrador.<\/p>\n<p style=\"text-align: justify;\">Murat Hinojosa, inform\u00f3 que en esta reuni\u00f3n se traz\u00f3 la ruta que habr\u00e1 de seguirse para \u201catender las principales necesidades del sector Salud, considerando cuatro rubros: infraestructura, personal, abasto de medicamentos y equipo m\u00e9dico\u201d.<\/p>\n<p style=\"text-align: justify;\">Por su parte, el titular del IMSS inform\u00f3 que en octubre de 2021 se llev\u00f3 a cabo un inventario de necesidades de equipamiento e infraestructura del sistema oaxaque\u00f1o de salud, en el que se visitaron 874 unidades de primer nivel y 40 hospitales tanto de segundo como de tercer nivel.<\/p>\n<p style=\"text-align: justify;\">Entre los principales hallazgos se detect\u00f3 un d\u00e9ficit en el n\u00famero de personal que se necesita para cubrir todos los turnos, se trata de 5 mil 626 profesionales de salud, de los cuales 927 son m\u00e9dicos generales, 822 m\u00e9dicos y m\u00e9dicas especialistas, 3 mil 656 personal de enfermer\u00eda y 221 de param\u00e9dicos y que est\u00e1n en la parte de atenci\u00f3n m\u00e9dica.En infraestructura, en Oaxaca hay 38 hospitales, de los cuales 16 son hospitales generales, de los cuales 3 cuentan con unidades de cuidados intensivos, 4 con unidades de cuidados intensivos neonatales; y 19 hospitales integrales, 2 hospitales m\u00f3viles y 1 psiqui\u00e1trico.<\/p>\n<p style=\"text-align: justify;\">De 31 quir\u00f3fanos, 23 son funcionales, de 22 salas donde se llevan acabo los partos, solamente 16 funcionan.<\/p>\n<p style=\"text-align: justify;\">Respecto al equipamiento, se identific\u00f3 que en el primer nivel de atenci\u00f3n hay un deficit de 13 mil 573 equipo que van desde equipos menores hasta esterilizadores de vapor, estuches de vapor. En el segundo nivel el deficit de equipamiento es de 8 mil 788 equipos que van de tomograf\u00edas hasta de rayos equis y ventiladores.<\/p>\n<p style=\"text-align: justify;\">De acuerdo con informaci\u00f3n del IMSS, un primer c\u00e1lculo indica que para el proceso de transici\u00f3n se requiere de una inversi\u00f3n para infraestructura y equipamiento que suma mil 596 millones de pesos, a los que se adicionan mil 179 millones de pesos necesarios para cubrir la n\u00f3mina de especialistas para todos los turnos.<\/p>\n<p style=\"text-align: justify;\">Tan solo para 927 m\u00e9dicos general se requiere de una inversi\u00f3n de 236.3 millones de pesos; para 822 m\u00e9dicos especialistas 311.1 millones de pesos; para 3 mil 656 enfermeras 592.1 millones de pesos; para 221 param\u00e9dicos, 39.9 millones de pesos; para los 13 mil 573 equipos de primer nivel, 230.9 millones de pesos; para 8 mil 788 equipos de segundo nivel, 720.4 millones de pesos.<\/p>\n<p style=\"text-align: justify;\">Mientras que para las 206 acciones de infraestructura 644.8 millones de pesos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO El gobernador del Estado, Alejandro Murat Hinojosa, su par electo, Salom\u00f3n Jara Cruz; el director del Instituto de Salud para el Bienestar (INSABI), Juan Antonio Ferrer Aguilar; del Instituto Mexicano del Seguro Social (IMSSE), Zoe Robledo Aburto; y Instituto de Seguridad y Servicios Sociales de los Trabajadores del Estado (ISSSTE), Pedro [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5,3,6],"tags":[],"class_list":{"0":"post-27078","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-imagen","7":"category-mesa-de-redaccion","8":"category-tendencias"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9Ynjw-72K","jetpack-related-posts":[{"id":27081,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2022\/08\/04\/supervisan-alejandro-murat-salomon-jara-y-titulares-del-sector-salud-federal-hospitales-de-oaxaca\/","url_meta":{"origin":27078,"position":0},"title":"Supervisan Alejandro Murat, Salom\u00f3n Jara y titulares del Sector Salud federal hospitales de Oaxaca","author":"ariadna","date":"agosto 4, 2022","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca \u25cf Recorrieron los Hospitales \u201cDr. Aurelio Valdivieso\u201d, de la Ni\u00f1ez Oaxaque\u00f1a, Alta Especialidad y de la Mujer y Ni\u00f1o Oaxaque\u00f1o \u25cf El Mandatario Estatal se\u00f1al\u00f3 que queda claro que para su gobierno la salud ha sido prioridad \u25cf El titular del IMSS apunt\u00f3 que el objetivo de este\u2026","rel":"","context":"En &quot;Imagen&quot;","block_context":{"text":"Imagen","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/imagen\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2022\/08\/IMG-20220804-WA0085-300x200.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":28645,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2023\/04\/03\/avanzan-estrategia-para-implementar-imss-bienestar-en-oaxaca\/","url_meta":{"origin":27078,"position":1},"title":"Avanzan estrategia para implementar IMSS-Bienestar en Oaxaca","author":"ariadna","date":"abril 3, 2023","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca \u2022 El director general del Seguro Social, Zo\u00e9 Robledo, indic\u00f3 que Oaxaca ser\u00e1 la primera entidad en incorporarse al Modelo IMSS-Bienestar para el segundo trimestre del a\u00f1o. \u2022 Salom\u00f3n Jara Cruz, gobernador de Oaxaca, destac\u00f3 que existe voluntad pol\u00edtica del gobierno federal para conseguir un mejor servicio de\u2026","rel":"","context":"En &quot;Imagen&quot;","block_context":{"text":"Imagen","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/imagen\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2023\/04\/IMG-20230403-WA0187-300x187.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":17579,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2021\/03\/17\/diputados-autorizan-a-murat-entregar-hospital-y-descuento-de-2832-mdp-de-participaciones-para-saldar-deudos-con-issste\/","url_meta":{"origin":27078,"position":2},"title":"Diputados autorizan a Murat, entregar Hospital y descuento de 2,832 mdp de participaciones para saldar deudos con ISSSTE.","author":"ariadna","date":"marzo 17, 2021","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO La LXIV Legislatura autoriz\u00f3 al Gobernador del Estado, Alejandro Murat Hinojosa, desincorporar del patrimonio del Estado una superficie de 25 mil 814.333 metros cuadrados y la construcci\u00f3n que ocupa el \u201cHospital General de la Mujer y el Ni\u00f1o Oaxaque\u00f1o\u201d para otorgarlo en \u201cDaci\u00f3n de Pago\u201d al\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":22108,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2021\/11\/06\/eugenia-ruiz-davila-nueva-directora-del-hospital-general-doctor-aurelio-valdivieso\/","url_meta":{"origin":27078,"position":3},"title":"Eugenia Ruiz D\u00e1vila, nueva directora del  Hospital General \u201cDoctor Aurelio Valdivieso\u201d.","author":"ariadna","date":"noviembre 6, 2021","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca La Licenciada en Enfermer\u00eda y Doctora en Salud P\u00fablica, result\u00f3 ganadora por su excelente formaci\u00f3n y asumir\u00e1 el cargo el pr\u00f3ximo 16 de noviembre Fueron siete las y los aspirantes a ocupar la Direcci\u00f3n del Hospital Civil La Convocatoria emitida por los SSO fue p\u00fablica, abierta y transparente\u2026","rel":"","context":"En &quot;Imagen&quot;","block_context":{"text":"Imagen","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/imagen\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2021\/11\/SSO-3-300x169.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":33102,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2024\/08\/26\/acepta-gobernador-salomon-jara-renuncia-de-alma-lilia-velasco-hernandez-a-la-secretaria-de-salud\/","url_meta":{"origin":27078,"position":4},"title":"Acepta Gobernador Salom\u00f3n Jara renuncia de Alma Lilia Velasco Hern\u00e1ndez a la Secretar\u00eda de Salud","author":"ariadna","date":"agosto 26, 2024","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca \u2022 Efr\u00e9n Emmanuel Jarqu\u00edn Gonz\u00e1lez queda como encargado del despacho de la dependencia Oaxaca de Ju\u00e1rez, Oax. 26 de agosto del 2024.- El Gobernador del Estado Salom\u00f3n Jara Cruz inform\u00f3 que la ma\u00f1ana de este lunes acept\u00f3 la renuncia de Alma Lilia Velasco Hern\u00e1ndez al cargo de secretaria\u2026","rel":"","context":"En &quot;Imagen&quot;","block_context":{"text":"Imagen","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/imagen\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":10058,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2020\/01\/13\/fundacion-proveera-medicamentos-a-hospital-de-la-ninez-murat-ofrece-coordinacion-con-amlo-para-revertir-deficit-en-sso\/","url_meta":{"origin":27078,"position":5},"title":"Fundaci\u00f3n proveer\u00e1 medicamentos a Hospital de la Ni\u00f1ez; Murat ofrece coordinaci\u00f3n con AMLO para revertir d\u00e9ficit en SSO.","author":"ariadna","date":"enero 13, 2020","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO El Gobernador Alejandro Murat Hinojosa, desestim\u00f3 desabasto de medicamentos en los hospitales de Oaxaca e inform\u00f3 que se garantizar\u00e1 el abasto de medicamentos en el Hospital de la Ni\u00f1ez, por medio de una fundaci\u00f3n. Adem\u00e1s, adelant\u00f3 que en la visita a Oaxaca del Presidente Andr\u00e9s Manuel\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/27078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/comments?post=27078"}],"version-history":[{"count":1,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/27078\/revisions"}],"predecessor-version":[{"id":27080,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/27078\/revisions\/27080"}],"wp:attachment":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/media?parent=27078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/categories?post=27078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/tags?post=27078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}