{"id":27081,"date":"2022-08-04T17:07:23","date_gmt":"2022-08-04T22:07:23","guid":{"rendered":"https:\/\/redaccionoaxaca.com\/?p=27081"},"modified":"2022-08-04T17:07:31","modified_gmt":"2022-08-04T22:07:31","slug":"supervisan-alejandro-murat-salomon-jara-y-titulares-del-sector-salud-federal-hospitales-de-oaxaca","status":"publish","type":"post","link":"https:\/\/redaccionoaxaca.com\/index.php\/2022\/08\/04\/supervisan-alejandro-murat-salomon-jara-y-titulares-del-sector-salud-federal-hospitales-de-oaxaca\/","title":{"rendered":"Supervisan Alejandro Murat, Salom\u00f3n Jara y titulares del Sector Salud federal hospitales de Oaxaca"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>#Redacci\u00f3nOaxaca<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>#Oaxaca<\/strong><\/p>\n<p>\u25cf <em>Recorrieron los Hospitales \u201cDr. Aurelio Valdivieso\u201d, de la Ni\u00f1ez Oaxaque\u00f1a, Alta Especialidad y de la Mujer y Ni\u00f1o Oaxaque\u00f1o<\/em><\/p>\n<p style=\"text-align: justify;\"><em>\u25cf El Mandatario Estatal se\u00f1al\u00f3 que queda claro que para su gobierno la salud ha sido prioridad<\/em><\/p>\n<p style=\"text-align: justify;\"><em>\u25cf El titular del IMSS apunt\u00f3 que el objetivo de este recorrido es resolver los temas de salud de manera integral y en equipo en beneficio de la poblaci\u00f3n oaxaque\u00f1a<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Oaxaca de Ju\u00e1rez, Oax. 4 de agosto del 2022.-<\/strong> El gobernador Alejandro Murat Hinojosa, junto con el gobernador electo, Salom\u00f3n Jara Cruz, as\u00ed como los titulares de la Secretar\u00eda de Salud federal, del Institutito Mexicano del Seguro Social (IMSS), Instituto de Salud para el Bienestar (INSABI), el Instituto de Seguridad y Servicios Sociales de los Trabajadores del Estado (ISSSTE) y de la Comisi\u00f3n Coordinadora de Institutos de Salud y Hospitales de Alta Especialidades, recorrieron y supervisaron diversas unidades de salud que atienden a la poblaci\u00f3n oaxaque\u00f1a.<\/p>\n<p style=\"text-align: justify;\">Entre ellas el Hospital General \u201cDr. Aurelio Valdivieso\u201d, el de la Ni\u00f1ez Oaxaque\u00f1a, el de Alta Especialidad y el de la Mujer y Ni\u00f1o Oaxaque\u00f1o.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-27082 aligncenter\" src=\"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2022\/08\/IMG-20220804-WA0085-300x200.jpg?resize=300%2C200&#038;ssl=1\" alt=\"\" width=\"300\" height=\"200\" \/><\/p>\n<p style=\"text-align: justify;\">En esta gira de trabajo asistieron el secretario de Salud del Gobierno Federal, Jorge Alcocer Varela, los titulares del Instituto Mexicano del Seguro Social (IMSS), Zo\u00e9 Robledo; del Instituto de Seguridad y Servicios Sociales para los Trabajadores del Estado (ISSSTE), Pedro Zenteno Santaella; del Instituto de Salud para el Bienestar (Insabi), Juan Antonio Ferrer Aguilar.<\/p>\n<p style=\"text-align: justify;\">As\u00ed como de la Comisi\u00f3n Coordinadora de Institutos de Salud y Hospitales de Alta Especialidades, Gustavo Reyes Ter\u00e1n; la secretaria de Salud de Oaxaca, Virginia S\u00e1nchez R\u00edos y el secretario general de la Secci\u00f3n 35 del Sindicato Nacional de Trabajadores de la Secretar\u00eda de Salud (SNTSA), Mario F\u00e9lix Pacheco, entre otros funcionarios estatales.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-27083 aligncenter\" src=\"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2022\/08\/IMG-20220804-WA0093-300x200.jpg?resize=300%2C200&#038;ssl=1\" alt=\"\" width=\"300\" height=\"200\" \/><\/p>\n<p style=\"text-align: justify;\">En este encuentro, el gobernador del Estado, Alejandro Murat Hinojosa, se\u00f1al\u00f3 que hoy se est\u00e1 dando el paso para ir construyendo de manera coordinada la salud que las y los oaxaque\u00f1os quieren, por lo que extern\u00f3 el agradecimiento de Oaxaca al presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, para dar este paso en equipo; y reiter\u00f3, que el trabajo coordinado da grandes resultados.<\/p>\n<p style=\"text-align: justify;\">\u201cEn nuestro estado, queda claro que la salud es prioridad, por ello en equipo, junto al Gobierno de M\u00e9xico, recorrimos los hospitales de Oaxaca. Hay una propuesta integral que parte de la base trabajadora y su seguridad absoluta, infraestructura, equipamiento y personal, y aprovechar toda la infraestructura de Salud que tiene el estado para que sea de manera eficiente la atenci\u00f3n a la poblaci\u00f3n oaxaque\u00f1a.\u201d, apunt\u00f3 el Mandatario Estatal ante titulares de Salud federal y estatal.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Por su parte, el gobernador electo, Salom\u00f3n Jara, refiri\u00f3 que hay un gran inter\u00e9s del Presidente de M\u00e9xico en la atenci\u00f3n de la salud en el estado y en este recorrido se conoci\u00f3 a detalle el proyecto que tiene el Gobierno Federal para Oaxaca.<\/p>\n<p style=\"text-align: justify;\">Asimismo, reconoci\u00f3 al sector de Salud del Gobierno Federal por su compromiso de trabajar para garantizar la atenci\u00f3n m\u00e9dica de calidad a las ni\u00f1as, ni\u00f1os y mujeres oaxaque\u00f1as. \u201cEl apoyo y la coordinaci\u00f3n ser\u00e1n fundamentales para atender el enorme rezago en el que se encuentra nuestro sistema de salud\u201d.<\/p>\n<p style=\"text-align: justify;\">En tamto, el director general del Instituto Mexicano del Seguro Social (IMSS), Zo\u00e9 Robledo Aburto, expres\u00f3 que el objetivo de la visita a los nosocomios oaxaque\u00f1os es resolver los temas de salud de manera integral y en equipo en beneficio de la poblaci\u00f3n oaxaque\u00f1a.<\/p>\n<p style=\"text-align: justify;\">\u201cEs un encargo del Presidente de la Rep\u00fablica que la poblaci\u00f3n oaxaque\u00f1a independientemente de la adscripci\u00f3n que tenga a cualquier instancia de seguridad social o no la tenga, pueda tener acceso a servicios de tercer nivel y que seamos las instituciones que encontremos los dise\u00f1os para lograrlos\u201d, apunt\u00f3 en conferencia de prensa ante medios oaxaque\u00f1os.<\/p>\n<p style=\"text-align: justify;\">Asimismo, extern\u00f3 que previamente al recorrido, sostuvieron una reuni\u00f3n de trabajo en la que se abord\u00f3 el tema de atenci\u00f3n a las instalaciones de Salud de 38 municipios de la regi\u00f3n de la Costa que resultaron afectadas por el hurac\u00e1n \u00c4gatha el pasado mes de mayo \u2013acci\u00f3n prioritaria tambi\u00e9n del Presidente de M\u00e9xico-, en la que se acord\u00f3 iniciar con los procesos de compra de equipos e infraestructura que requieren dichas unidades, misma que tendr\u00e1 una inversi\u00f3n de m\u00e1s de 700 millones de pesos en m\u00e1s de 100 unidades de primer nivel, siete hospitales de la regi\u00f3n y un hospital del IMSS Bienestar.<\/p>\n<p style=\"text-align: justify;\">\u201cLa gran ense\u00f1anza de la pandemia fue que se puede trabajar de manera integral, en equipo y que no sea la poblaci\u00f3n quienes sigan cargando con el costo con un sistema de Salud fragmentado. Nos da mucho gusto que estemos trabajando en una coordinaci\u00f3n completa con el gobierno de transici\u00f3n y con el equipo del Gobierno del Estado, porque esto es algo que tendr\u00e1 una continuidad en beneficio de las y los oaxaque\u00f1os\u201d, agreg\u00f3.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-27084 aligncenter\" src=\"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2022\/08\/IMG-20220804-WA0090-300x200.jpg?resize=300%2C200&#038;ssl=1\" alt=\"\" width=\"300\" height=\"200\" \/><\/p>\n<p style=\"text-align: justify;\">Tambi\u00e9n dijo que se requiere una inversi\u00f3n mayor a los 3 mil millones de pesos para acciones de equipamiento de primer nivel de atenci\u00f3n, que es donde se deber\u00edan de resolver el 80% de los padecimientos de los pacientes y que no tenga que referirse al \u00e1rea hospitalaria.<\/p>\n<p style=\"text-align: justify;\">En tanto, el director general del ISSSTE, Pedro Zenteno Santaella, resalt\u00f3 que la instituci\u00f3n a su cargo est\u00e1 en la mejor disposici\u00f3n de ayudar en este modelo de ISSSTE Bienestar, porque es la integraci\u00f3n del sector, algo in\u00e9dito en el pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>#Redacci\u00f3nOaxaca #Oaxaca \u25cf Recorrieron los Hospitales \u201cDr. Aurelio Valdivieso\u201d, de la Ni\u00f1ez Oaxaque\u00f1a, Alta Especialidad y de la Mujer y Ni\u00f1o Oaxaque\u00f1o \u25cf El Mandatario Estatal se\u00f1al\u00f3 que queda claro que para su gobierno la salud ha sido prioridad \u25cf El titular del IMSS apunt\u00f3 que el objetivo de este recorrido es resolver los temas [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5,6,1],"tags":[],"class_list":{"0":"post-27081","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-imagen","7":"category-tendencias","8":"category-uncategorized"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9Ynjw-72N","jetpack-related-posts":[{"id":27078,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2022\/08\/04\/oaxaca-con-deficit-de-5-626-profesionales-de-salud-requiere-de-2-775-5-mdp-para-equipar-hospitales-murat-jara-y-directores-de-salud-supervisan-unidades\/","url_meta":{"origin":27081,"position":0},"title":"Oaxaca con d\u00e9ficit de 5, 626 profesionales de salud; requiere de 2, 775. 5 mdp  para equipar hospitales; Murat, Jara y directores de Salud supervisan unidades","author":"ariadna","date":"agosto 4, 2022","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO El gobernador del Estado, Alejandro Murat Hinojosa, su par electo, Salom\u00f3n Jara Cruz; el director del Instituto de Salud para el Bienestar (INSABI), Juan Antonio Ferrer Aguilar; del Instituto Mexicano del Seguro Social (IMSSE), Zoe Robledo Aburto; y Instituto de Seguridad y Servicios Sociales de los\u2026","rel":"","context":"En &quot;Imagen&quot;","block_context":{"text":"Imagen","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/imagen\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":28645,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2023\/04\/03\/avanzan-estrategia-para-implementar-imss-bienestar-en-oaxaca\/","url_meta":{"origin":27081,"position":1},"title":"Avanzan estrategia para implementar IMSS-Bienestar en Oaxaca","author":"ariadna","date":"abril 3, 2023","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca \u2022 El director general del Seguro Social, Zo\u00e9 Robledo, indic\u00f3 que Oaxaca ser\u00e1 la primera entidad en incorporarse al Modelo IMSS-Bienestar para el segundo trimestre del a\u00f1o. \u2022 Salom\u00f3n Jara Cruz, gobernador de Oaxaca, destac\u00f3 que existe voluntad pol\u00edtica del gobierno federal para conseguir un mejor servicio de\u2026","rel":"","context":"En &quot;Imagen&quot;","block_context":{"text":"Imagen","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/imagen\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2023\/04\/IMG-20230403-WA0187-300x187.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":34706,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2024\/12\/07\/jara-y-sheinbaum-inauguran-centro-de-salud-docente-del-imss-bienestar-en-santiago-astata\/","url_meta":{"origin":27081,"position":2},"title":"Jara y Sheinbaum inauguran Centro de Salud Docente del IMSS-Bienestar en Santiago Astata","author":"ariadna","date":"diciembre 7, 2024","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO La Presidenta de M\u00e9xico, Claudia Sheinbaum Pardo, inaugur\u00f3 el Centro de Salud Docente con Servicios Ampliados de Santiago Astata, Oaxaca, que brindar\u00e1 m\u00e1s de 24 mil consultas de medicina general y servicios m\u00e9dicos integrales, con lo cual se consolida al IMSS Bienestar como un sistema de\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2024\/12\/IMG-20241207-WA0146-300x225.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":34844,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2024\/12\/17\/ayuden-a-no-bloquear-y-hacer-de-oaxaca-un-lugar-donde-el-turismo-visitantes-y-familias-puedan-caminar-gobernador-a-trabajadores-de-salud\/","url_meta":{"origin":27081,"position":3},"title":"Ayuden a NO bloquear y hacer de Oaxaca un lugar donde el turismo, visitantes y familias, puedan caminar: Gobernador a trabajadores de Salud","author":"ariadna","date":"diciembre 17, 2024","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO El Gobernador de Oaxaca, Salom\u00f3n Jara Cruz, pidi\u00f3 a las trabajadores del sector salud que,\u00a0 sitiaron m\u00e1s de 20 puntos carretero, cruceros y centros comerciales, este martes, a ayudarlo a NO bloquear, NO interrumpir las v\u00edas de comunicaci\u00f3n y hacer del Estado, un lugar, donde el\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":7754,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2019\/07\/25\/persiste-deficit-de-1-mil-700-mdp-en-sistema-de-salud-de-oaxaca-aun-sin-culminarse-30-hospitales-que-dejaron-uro-y-cue-murat\/","url_meta":{"origin":27081,"position":4},"title":"Persiste d\u00e9ficit de 1 mil 700 mdp en sistema de Salud de Oaxaca;\u00a0  a\u00fan sin culminarse 30 hospitales que dejaron URO y Cu\u00e9: Murat.","author":"jaime","date":"julio 25, 2019","format":false,"excerpt":"\u00a0 #Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO\u00a0 El gobernador Alejandro Murat Hinojosa, confirm\u00f3 que a\u00fan prevalece un d\u00e9ficit financiero del Sector Salud, del orden 1 mil 700 millones de pesos, principalmente en salarios de m\u00e1s de 15 mil trabajadores. En medio de ese panorama adverso, anunci\u00f3 la nueva visita del Presidente, Andr\u00e9s\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":20977,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2021\/09\/20\/video-lopez-obrador-se-compromete-con-trabajadores-eventuales-de-salud-sera-el-22-de-septiembre-que-representantes-del-insabi-imss-y-secretaria-de-salud-determinen-como-sera-la-contratacion-de-pers\/","url_meta":{"origin":27081,"position":5},"title":"VIDEO: L\u00f3pez Obrador se compromete con trabajadores eventuales de salud; ser\u00e1 el 22 de septiembre que representantes del INSABI, IMSS y Secretar\u00eda de Salud determinen como ser\u00e1 la contrataci\u00f3n de personal m\u00e9dico de Oaxaca.","author":"ariadna","date":"septiembre 20, 2021","format":"video","excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Ariadna Mendoza Concluye la mesa de di\u00e1logo entre trabajadores de Salud y el presidente de la rep\u00fablica, Andr\u00e9s Manuel L\u00f3pez Obrador, en d\u00f3nde el secretario general del Frente Nacional Trabajadores de Salud de la Rep\u00fablica Mexicana en Oaxaca, Ram\u00f3n Segura Arenas, expuso algunos de los temas planteados; entre\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/27081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/comments?post=27081"}],"version-history":[{"count":2,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/27081\/revisions"}],"predecessor-version":[{"id":27086,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/27081\/revisions\/27086"}],"wp:attachment":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/media?parent=27081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/categories?post=27081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/tags?post=27081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}