{"id":27405,"date":"2022-08-22T19:53:05","date_gmt":"2022-08-23T00:53:05","guid":{"rendered":"https:\/\/redaccionoaxaca.com\/?p=27405"},"modified":"2022-08-22T19:53:05","modified_gmt":"2022-08-23T00:53:05","slug":"deuda-publica-se-redujo-de-4-3-a-3-5-y-se-entregaran-finanzas-sanas-a-sjc-murat-en-su-camino-por-la-presidencia-afirma-que-ivett-es-su-mejor-activo","status":"publish","type":"post","link":"https:\/\/redaccionoaxaca.com\/index.php\/2022\/08\/22\/deuda-publica-se-redujo-de-4-3-a-3-5-y-se-entregaran-finanzas-sanas-a-sjc-murat-en-su-camino-por-la-presidencia-afirma-que-ivett-es-su-mejor-activo\/","title":{"rendered":"Deuda p\u00fablica se redujo de 4.3% a 3.5% y se entregaran finanzas sanas a SJC:   Murat; en su camino por la presidencia, afirma que Ivett es su mejor activo"},"content":{"rendered":"<p><strong>#Redacci\u00f3nOaxaca<\/strong><\/p>\n<p><strong>#Oaxaca<\/strong><\/p>\n<p><strong>Jaime GUERRERO<\/strong><\/p>\n<p style=\"text-align: justify;\">A tres de meses de culminar su mandato, el gobernador, Alejandro Murat Hinojosa, afirm\u00f3 que entregar\u00e1 finanzas sanas a su par electo, Salom\u00f3n Jara Cruz, quien asumir\u00e1 el cargo el pr\u00f3ximo 1 diciembre.<\/p>\n<p style=\"text-align: justify;\">Por lo pronto, el proceso de entrega-recepci\u00f3n, avanza de forma preliminar sin contratiempos en plena comunicaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">A diferencia de las finanzas quebradas que recibi\u00f3 del pol\u00e9mico ex gobernador, Gabino Cu\u00e9 Monteagudo, el gobernador saliente, destac\u00f3 que hoy Oaxaca, de acuerdo al sem\u00e1foro de la Secretar\u00eda de Hacienda y Cr\u00e9dito y P\u00fablico, est\u00e1 en verde en sus indicadores.<\/p>\n<p style=\"text-align: justify;\">Las finanzas se van a entregar como no hab\u00edamos tenido en varios sexenios y eso es reflejo del orden financiero que hemos tenido\u201d, apunt\u00f3.<\/p>\n<p style=\"text-align: justify;\">Murat Hinojosa, report\u00f3 que su administraci\u00f3n acab\u00f3 de pagar la deuda p\u00fablica a corto plazo, mientras que toda la deuda gubernamental y deuda p\u00fablica se redujo de 4.3 por ciento a 3.5 por ciento.<\/p>\n<p style=\"text-align: justify;\">En todos los \u00e1mbitos financieros Oaxaca sale fortalecido. De la misma forma, destac\u00f3 que todas las calificadoras, entre ellas, Moodys, le subieron calificaci\u00f3n a Oaxaca.<\/p>\n<p style=\"text-align: justify;\">En tanto, evit\u00f3 polemizar sobre aquellos funcionarios que no cumplieron su cometido y tendr\u00edan que asumir las consecuencias de sus actos.<\/p>\n<p style=\"text-align: justify;\">Murat Hinojosa, destac\u00f3 que su gobierno ha trabajado para cumplir en todos los \u00e1mbitos y ser\u00e1n otras instancias las que decidan sobre los particulares.<\/p>\n<p style=\"text-align: justify;\">\u201c<em>Si Oaxaca tiene finanzas sanas. Si Oaxaca tiene obra y tiene los indicadores positivos es porque este gobierno ha buscado darle resultados a los oaxaque\u00f1os<\/em>\u201d, ataj\u00f3.<\/p>\n<p style=\"text-align: justify;\">En el caso de las obras, asegur\u00f3 que todas las obras anunciadas se culminaran, entre ellas, la supercarretera a la costa, el circuito interior, el Centro Cultural y el Centro de Congresos de Huatulco.<\/p>\n<p style=\"text-align: justify;\">Las obras se cumplieron casi en su totalidad.<\/p>\n<p style=\"text-align: justify;\">Presumi\u00f3 en combate a la pobreza se canalizaron casi 7 mil millones de pesos para obras de infraestructuras social, hospitales, caminos, carreteras.<\/p>\n<p style=\"text-align: justify;\">Respecto a su aspiraci\u00f3n presidencial, dijo que ha subido en las encuestas de preferencia electoral y una vez que salga a recorrer el pa\u00eds, seguir\u00e1 subiendo.<\/p>\n<p style=\"text-align: justify;\">Y en medio de la pol\u00e9mica entorno su esposa Ivett Mor\u00e1n, por la presentaci\u00f3n de su l\u00ednea de ropa con textiles de pueblos y comunidades ind\u00edgenas, desestim\u00f3 esas cr\u00edticas y destac\u00f3 que la directora honoraria del DIF, es mujer activo por el trabajo que hace.<\/p>\n<p style=\"text-align: justify;\">\u201c<em>Es el mejor activo que tengo yo y sin duda estos 6 a\u00f1os es una de grandes ciudadanas que ha aportado a Oaxaca y as\u00ed lo seguir\u00e1 haciendo\u201d<\/em>, asent\u00f3.<\/p>\n<p style=\"text-align: justify;\">En tanto, destac\u00f3 que el INEGI, CONEVAL, el SESSP y la Gobernabilidad que vive Oaxaca, son claros ejemplos que se dan resultados.<\/p>\n<p style=\"text-align: justify;\">\u201c<em>M\u00e1s all\u00e1 de espejitos, vamos a proponer un modelo Oaxaca\u201d<\/em>, destac\u00f3.<\/p>\n<p style=\"text-align: justify;\">En esa perspectiva, tambi\u00e9n emplaz\u00f3 al poder legislativo para realizar una conversaci\u00f3n para realizar una serie de reformas del c\u00f3digo penal porque hoy se tiene normas validas que son ineficaces y carecen de enfoque a las victimas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO A tres de meses de culminar su mandato, el gobernador, Alejandro Murat Hinojosa, afirm\u00f3 que entregar\u00e1 finanzas sanas a su par electo, Salom\u00f3n Jara Cruz, quien asumir\u00e1 el cargo el pr\u00f3ximo 1 diciembre. Por lo pronto, el proceso de entrega-recepci\u00f3n, avanza de forma preliminar sin contratiempos en plena comunicaci\u00f3n. A diferencia [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4,7],"tags":[],"class_list":{"0":"post-27405","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-agenda-politica","7":"category-al-cierre"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9Ynjw-781","jetpack-related-posts":[{"id":8511,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2019\/09\/19\/uro-y-cue-dejaron-deuda-basura-por-40-mil-mdp-habra-finanzas-sanas-afirma-murat\/","url_meta":{"origin":27405,"position":0},"title":"URO y Cu\u00e9 dejaron deuda basura por  40 mil mdp; \u201chabr\u00e1 finanzas sanas\u201d, afirma Murat.","author":"ariadna","date":"septiembre 19, 2019","format":"video","excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO La deuda p\u00fablica heredadas por los ex gobernadores Ulises Ruiz Ortiz y Gabino Cu\u00e9 Monteagudo, estimada en 40 mil millones de pesos, son deuda basura, debido a que se solicitaron financiamientos ante instituciones bancarias para gasto corriente y en algunos casos ser\u00edan para obras de infraestructura,\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":28130,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2022\/10\/05\/vamos-a-contar-cada-peso-cada-silla-salomon-jara-en-arranque-de-proceso-de-transicion-con-murat-se-heredara-finanzas-sanas-amh\/","url_meta":{"origin":27405,"position":1},"title":"\u201cVamos a contar cada peso, cada silla\u201d: Salom\u00f3n Jara en arranque  de proceso de transici\u00f3n con Murat; se heredar\u00e1 finanzas sanas: AMH","author":"ariadna","date":"octubre 5, 2022","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO El gobernador saliente de Oaxaca -emanado del Partido Revolucionario Institucional (PRI)- Alejandro Murat Hinojosa y el mandatario electo por el Partido Movimiento de Regeneraci\u00f3n Nacional (Morena), Salom\u00f3n Jara Cruz, iniciaron este mi\u00e9rcoles de manera formal el proceso de entrega recepci\u00f3n para dar paso a la transici\u00f3n\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":10457,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2020\/02\/05\/autopistas-libramiento-sur-cc-y-agroparque-cambiaran-rostro-de-oaxaca-vmtg-proximo-gobernador-tendra-finanzas-sanas-promete\/","url_meta":{"origin":27405,"position":2},"title":"Autopistas, Libramiento Sur, CC y Agroparque, cambiar\u00e1n rostro de Oaxaca: VMTG; pr\u00f3ximo Gobernador tendr\u00e1 finanzas sanas, promete.","author":"ariadna","date":"febrero 5, 2020","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO Inversiones por m\u00e1s de 15 mil millones de pesos, disminuci\u00f3n de la deuda p\u00fablica, finanzas sanas en los tres primeros a\u00f1os, y 4 proyectos de infraestructura estrat\u00e9gicos a ejecutarse en los pr\u00f3ximos dos a\u00f1os en la administraci\u00f3n del gobernador, Alejandro Murat Hinojosa, presumi\u00f3 el titular de\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4396,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2018\/12\/12\/cae-3-5-pib-de-oaxaca-empero-finanzas-estan-sanas-y-deuda-publica-no-rebasa-11-mil-855-mdp-gallardo\/","url_meta":{"origin":27405,"position":3},"title":"Cae 3.5 PIB de Oaxaca, empero, finanzas est\u00e1n sanas  y deuda p\u00fablica no rebasa 11 mil 855 mdp: Gallardo","author":"jaime","date":"diciembre 12, 2018","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO Pese a que el Producto Interno Bruto (PIB), cay\u00f3 3.5 por ciento, Jorge Gallardo Casas, tesorero del Gobernador, Alejandro Murat Hinojosa, afirm\u00f3 que las finanzas del Estado est\u00e1n sanas, estables, transparentes y sostuvo que la deuda p\u00fablica a largo plazo no rebasa los 11 mil 855\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":14721,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2020\/10\/13\/presupuesto-de-oaxaca-para-2021-sera-conservador-murat-finanzas-preve-tijerazo-por-5-mil-900-mdp\/","url_meta":{"origin":27405,"position":4},"title":"Presupuesto de Oaxaca para 2021 ser\u00e1 conservador:  Murat; Finanzas prev\u00e9 \u201ctijerazo\u201d por 5 mil 900 mdp.","author":"ariadna","date":"octubre 13, 2020","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO El Gobernador del Estado, Alejandro Murat Hinojosa, anticip\u00f3 que el presupuesto de Oaxaca para el ejercicio fiscal 2021, ser\u00e1 conservador y con ello, proyect\u00f3 que en medio de la crisis econ\u00f3mica nacional que ha impactado a la entidad, no ser\u00e1 un hist\u00f3rico presupuesto como el que\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4903,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2019\/01\/10\/vicente-mendoza-a-finanzas-mariana-nassar-a-semovi-gallardo-enrolado-a-oficina\/","url_meta":{"origin":27405,"position":5},"title":"Vicente Mendoza a Finanzas; Mariana Nassar  a Semovi; Gallardo enrolado a Oficina","author":"jaime","date":"enero 10, 2019","format":"video","excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO El Gobernador del Estado, Alejandro Murat Hinojosa, oficializ\u00f3 cambios en dos de Secretarias de Gabinete, la de Finanzas y en la de Movilidad (Semovi), como parte de los ajustes en su estructura administrativa de Gobierno. De acuerdo al mandatario, los movimientos buscan fortalecer la coordinaci\u00f3n entre\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/27405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/comments?post=27405"}],"version-history":[{"count":1,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/27405\/revisions"}],"predecessor-version":[{"id":27407,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/27405\/revisions\/27407"}],"wp:attachment":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/media?parent=27405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/categories?post=27405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/tags?post=27405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}