{"id":35549,"date":"2025-02-08T21:50:47","date_gmt":"2025-02-09T03:50:47","guid":{"rendered":"https:\/\/redaccionoaxaca.com\/?p=35549"},"modified":"2025-02-08T21:50:47","modified_gmt":"2025-02-09T03:50:47","slug":"presentan-agenda-para-las-juventudes-oaxaquenas-en-el-poder-legislativo","status":"publish","type":"post","link":"https:\/\/redaccionoaxaca.com\/index.php\/2025\/02\/08\/presentan-agenda-para-las-juventudes-oaxaquenas-en-el-poder-legislativo\/","title":{"rendered":"Presentan Agenda para las Juventudes Oaxaque\u00f1as en el Poder Legislativo"},"content":{"rendered":"<p style=\"text-align: justify;\"><em>* Fue suscrita la Carta Compromiso con diversas asociaciones civiles juveniles, la cual integra las principales problem\u00e1ticas y propuestas de soluci\u00f3n de este sector de la poblaci\u00f3n<\/em><\/p>\n<p style=\"text-align: justify;\"><em>* El Presidente de la Jucopo mencion\u00f3 que despu\u00e9s de muchos a\u00f1os el Congreso local abre sus puertas para que las voces de las y los j\u00f3venes sean escuchadas<\/em><\/p>\n<p style=\"text-align: justify;\">San Raymundo Jalpan, Oax., a 08 de febrero de 2025.- Para generar las condiciones que garanticen el bienestar y el pleno ejercicio de los derechos de las personas j\u00f3venes de la entidad, a trav\u00e9s de la escucha activa de sus inquietudes, aspiraciones y necesidades, plantear soluciones para garantizar el bienestar y reducir las brechas de desigualdad, la precarizaci\u00f3n, el estigma y criminalizaci\u00f3n, se present\u00f3 en el Congreso del Estado la Agenda para las Juventudes Oaxaque\u00f1as.<\/p>\n<p style=\"text-align: justify;\">En este contexto se firm\u00f3 una Carta Compromiso por parte del vocal de Capacitaci\u00f3n de la Junta Local del Instituto Nacional Electoral (INE) en Oaxaca, Jorge Alejos Victoria, el presidente de la Junta de Coordinaci\u00f3n Pol\u00edtica (Jucopo), diputado Benjam\u00edn Viveros Montalvo y las diputadas Jimena Yamil Arroyo Ju\u00e1rez, Karla Clarissa Bornios Pel\u00e1ez, Sandra Daniela Taurino Jim\u00e9nez, Vanessa Rub\u00ed Ojeda Mej\u00eda y el congresista Isaac L\u00f3pez L\u00f3pez; as\u00ed como representantes de asociaciones juveniles.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-35550 aligncenter\" src=\"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/02\/Screenshot_20250208-214629_Facebook-300x207.jpg?resize=300%2C207&#038;ssl=1\" alt=\"\" width=\"300\" height=\"207\" \/><\/p>\n<p style=\"text-align: justify;\">Este documento contiene las problem\u00e1ticas que las y los j\u00f3venes manifestaron en los foros realizados al interior del estado, las propuestas de soluci\u00f3n a trav\u00e9s de la incidencia en pol\u00edticas p\u00fablicas y los compromisos con este sector por parte de la C\u00e1mara de representantes populares, en aras de lograr una sociedad m\u00e1s justa y con mayores oportunidades.<\/p>\n<p style=\"text-align: justify;\">El evento que reuni\u00f3 a la juventud, asociaciones juveniles, diputadas, diputados, funcionariado p\u00fablico en el \u00e1mbito estatal y federal, fue inaugurado por la congresista del Grupo Parlamentario de Morena, Sandra Daniela Taurino Jim\u00e9nez, quien destac\u00f3 que el Sector Juvenil hoy en d\u00eda son el centro de la pol\u00edtica p\u00fablica, y que en el Poder Legislativo las puertas est\u00e1n abiertas para que sus voces sean escuchadas.<\/p>\n<p style=\"text-align: justify;\">Al presentar la importancia de la Agenda de las Juventudes con Perspectivas Regionales, Erika Jazm\u00edn Ruiz L\u00f3pez, quien es una de las cuatro j\u00f3venes para liderar el proyecto Juventud Act\u00faa MX del INE en la entidad, mencion\u00f3 que son tres los temas principales a nivel nacional de suma importancia para esta poblaci\u00f3n: la precariedad laboral, la violencia de g\u00e9nero y la salud mental.<\/p>\n<p style=\"text-align: justify;\">Dijo que en el estado se han realizado ocho foros con la participaci\u00f3n de mujeres y hombres de 18 a 29 a\u00f1os en donde se identificaron problem\u00e1ticas en materia de Educaci\u00f3n Intercultural y el Acceso a las Tecnolog\u00edas; la Precariedad en Empleos; la Violencia e Inseguridad; y Embarazos a temprana edad.<\/p>\n<p style=\"text-align: justify;\">La legisladora Jimena Yamil Arroyo Ju\u00e1rez, que preside la Comisi\u00f3n Permanente de Ni\u00f1ez, Adolescencia y Juventudes, sostuvo que la Agenda suscrita representa una oportunidad hist\u00f3rica para situar a las juventudes en el lugar que les pertenece liderando un camino para un M\u00e9xico m\u00e1s justo e igualitario en el que sus derechos humanos sean respetados, promovidos y reconocidos.<\/p>\n<p style=\"text-align: justify;\">Por su parte, el Presidente de la Jucopo y tambi\u00e9n Coordinador del Grupo Parlamentario de Morena, destac\u00f3 que con la firma de la Agenda para las Juventudes y el compromiso con las organizaciones de la sociedad civil se continuar\u00e1 trabajando para que la perspectiva de las y los j\u00f3venes sea una realidad desde el ejercicio legislativo y que los nuevos programas sociales como Mi Primera Chamba, Tarjeta Joven e Inscripci\u00f3n Cero puedan ser elevados a rango constitucional, con la finalidad de abonar al bienestar de quienes hab\u00edan sido discriminados, marginados y olvidados, \u201cpero ahora son tomados en cuenta, escuchados y atendidos\u201d, subray\u00f3.<\/p>\n<p style=\"text-align: justify;\">Y destac\u00f3 que el Congreso del Estado es un espacio que escucha y atiende a las juventudes, marcando un antes y un despu\u00e9s para transformar las propuestas en acciones concretas \u201cporque su entusiasmo, diligencia y amor a Oaxaca nos motivan d\u00eda a d\u00eda a trabajar con mayor \u00edmpetu para consolidar el segundo piso de la Cuarta Transformaci\u00f3n\u201d.<\/p>\n<p style=\"text-align: justify;\">Mencion\u00f3 que actualmente con el relevo generacional que distingue al Poder Legislativo se est\u00e1n dejando atr\u00e1s las malas pr\u00e1cticas de la politiquer\u00eda, donde los actores pol\u00edticos priorizaban sus intereses personales o de grupo sobre el bienestar com\u00fan o el servicio p\u00fablico.<\/p>\n<p style=\"text-align: justify;\">Esta actividad tambi\u00e9n cont\u00f3 con la participaci\u00f3n de la representante de 100 X OAXACA, Sara Zenaida Clavel Guzm\u00e1n; de J\u00f3venes por el Arte y el Deporte, Antonio de Jes\u00fas L\u00f3pez Garc\u00eda; del Colegio Jur\u00eddico Universitario, Soledad Bravo Soriano; el vocal de Capacitaci\u00f3n de la Junta Local del INE, Jorge Alejos Victoria; y la directora del Instituto de la Juventud del Estado de Oaxaca (Injeo), Samantha Anah\u00ed Mota V\u00e1squez.<\/p>\n<p style=\"text-align: justify;\">De igual forma de integrantes de la Sexag\u00e9sima Sexta Legislatura local, las congresistas: Dennis Cruz Guti\u00e9rrez, M\u00f3nica Bel\u00e9n L\u00f3pez Javier, Mar\u00eda Eulalia Velasco Ram\u00edrez y Mar\u00eda Francisca Antonio Santiago.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>* Fue suscrita la Carta Compromiso con diversas asociaciones civiles juveniles, la cual integra las principales problem\u00e1ticas y propuestas de soluci\u00f3n de este sector de la poblaci\u00f3n * El Presidente de la Jucopo mencion\u00f3 que despu\u00e9s de muchos a\u00f1os el Congreso local abre sus puertas para que las voces de las y los j\u00f3venes sean [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4,7],"tags":[],"class_list":{"0":"post-35549","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-agenda-politica","7":"category-al-cierre"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9Ynjw-9fn","jetpack-related-posts":[{"id":32421,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2024\/06\/27\/capacitan-en-el-congreso-local-a-la-juventud-para-impulsar-iniciativas-legislativas\/","url_meta":{"origin":35549,"position":0},"title":"Capacitan en el Congreso local a la juventud para impulsar iniciativas legislativas","author":"ariadna","date":"junio 27, 2024","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca \u2022 Se busca inspirar a las y los j\u00f3venes para que se conviertan en agentes de cambio en sus comunidades. San Raymundo Jalpan, Oax. 27 de junio de 2024.- Con el prop\u00f3sito de darle las herramientas necesarias a la juventud para poder realizar las iniciativas legislativas que ayuden\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":36045,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2025\/03\/12\/avala-congreso-de-oaxaca-reforma-constitucional-para-garantizar-apoyo-economico-a-las-y-los-jovenes\/","url_meta":{"origin":35549,"position":1},"title":"Avala Congreso de Oaxaca reforma constitucional para garantizar apoyo econ\u00f3mico a las y los j\u00f3venes","author":"ariadna","date":"marzo 12, 2025","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca * Esta ley brinda un salario m\u00ednimo a personas entre 18 y 29 a\u00f1os * Se busca capacitar a las y los j\u00f3venes en empresas y negocios San Raymundo Jalpan, Oax., a 12 de marzo de 2025.- En Sesi\u00f3n Extraordinaria, la Sexag\u00e9sima Sexta Legislatura del Estado aval\u00f3 con\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":38215,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2025\/09\/11\/viveros-montalvo-presenta-iniciativa-para-expedir-la-ley-para-el-bienestar-de-las-juventudes-oaxaquenas\/","url_meta":{"origin":35549,"position":2},"title":"Viveros Montalvo presenta iniciativa para expedir la Ley para el Bienestar de las Juventudes Oaxaque\u00f1as","author":"ariadna","date":"septiembre 11, 2025","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca * De ser aprobada, su aplicaci\u00f3n corresponder\u00e1 a todas las autoridades estatales y municipales * Tiene por objetivo promover y garantizar el goce, ejercicio, respeto, protecci\u00f3n, sanci\u00f3n y promoci\u00f3n de los derechos humanos de las y los j\u00f3venes * Plantea la creaci\u00f3n del Sistema para el Bienestar de\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/09\/Screenshot_20250911_145954_Facebook-scaled.jpg?fit=1200%2C797&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/09\/Screenshot_20250911_145954_Facebook-scaled.jpg?fit=1200%2C797&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/09\/Screenshot_20250911_145954_Facebook-scaled.jpg?fit=1200%2C797&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/09\/Screenshot_20250911_145954_Facebook-scaled.jpg?fit=1200%2C797&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/09\/Screenshot_20250911_145954_Facebook-scaled.jpg?fit=1200%2C797&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":30459,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2024\/02\/10\/llama-congreso-a-reforzar-la-seguridad-en-los-municipios-donde-operan-los-bancos-bienestar\/","url_meta":{"origin":35549,"position":3},"title":"Llama Congreso a reforzar la seguridad en los municipios donde operan los Bancos Bienestar","author":"ariadna","date":"febrero 10, 2024","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca \u2022 Se busca garantizar la integridad de las y los adultos mayores. San Raymundo Jalpan, Oax. 09 de febrero de 2024.- El H. Congreso del Estado de Oaxaca solicita operativos constantes de seguridad en los municipios donde operan los Bancos Bienestar, con el prop\u00f3sito de garantizar la integridad\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":34778,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2024\/12\/12\/diputado-de-morena-propone-elevar-a-rango-constitucional-programas-sociales-de-jovenes-y-mujeres-jefas-de-familia-de-oaxaca\/","url_meta":{"origin":35549,"position":4},"title":"Diputado de Morena propone elevar a rango constitucional, programas sociales de j\u00f3venes y mujeres jefas de familia de Oaxaca","author":"ariadna","date":"diciembre 12, 2024","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO El diputado de Morena, Juan Marcelino S\u00e1nchez Valdivieso, present\u00f3 una iniciativa de reforma al art\u00edculo 12 de la carta magna de Oaxaca, para elevar a rango constitucional, los programas sociales otorgados a j\u00f3venes y a las mujeres jefas de familia en situaci\u00f3n de vulnerabilidad. La propuesta\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":34485,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2024\/11\/20\/rasuradora-y-sanciones-en-el-congreso-de-oaxaca-anuncia-presidente\/","url_meta":{"origin":35549,"position":5},"title":"Rasuradora y sanciones en el Congreso de Oaxaca, anuncia Presidente","author":"ariadna","date":"noviembre 20, 2024","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO El Presidente de la Junta de Coordinaci\u00f3n Pol\u00edtica del Congreso del Estado, Benjam\u00edn Viveros Montalvo, anunci\u00f3 que habr\u00e1 amonestaciones p\u00fablicas a las y los diputados locales que incumplan con su c\u00f3digo de \u00e9tica que aprobar\u00e1n. De paso, anuncia la reducci\u00f3n de la estructura del Congreso. Bajar\u00e1n\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/35549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/comments?post=35549"}],"version-history":[{"count":1,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/35549\/revisions"}],"predecessor-version":[{"id":35553,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/35549\/revisions\/35553"}],"wp:attachment":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/media?parent=35549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/categories?post=35549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/tags?post=35549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}