{"id":35981,"date":"2025-03-06T21:12:15","date_gmt":"2025-03-07T03:12:15","guid":{"rendered":"https:\/\/redaccionoaxaca.com\/?p=35981"},"modified":"2025-03-06T21:12:15","modified_gmt":"2025-03-07T03:12:15","slug":"proponen-sancionar-penalmente-a-quien-mediante-la-ia-genere-o-modifique-contenido-sexual-en-perjuicio-de-una-persona","status":"publish","type":"post","link":"https:\/\/redaccionoaxaca.com\/index.php\/2025\/03\/06\/proponen-sancionar-penalmente-a-quien-mediante-la-ia-genere-o-modifique-contenido-sexual-en-perjuicio-de-una-persona\/","title":{"rendered":"Proponen sancionar penalmente a quien mediante la IA genere o modifique contenido sexual en perjuicio de una persona"},"content":{"rendered":"<p><strong>#Redacci\u00f3nOaxaca<\/strong><\/p>\n<p><strong>#Oaxaca<\/strong><\/p>\n<p style=\"text-align: justify;\">* <em>Se busca fortalecer la protecci\u00f3n de las v\u00edctimas y ampliar las causales de este delito<\/em><\/p>\n<p style=\"text-align: justify;\"><em>* La violencia digital vulnera la dignidad de las personas y profundiza la desigualdad<\/em><\/p>\n<p style=\"text-align: justify;\">San Raymundo Jalpan, Oax., a 06 de marzo de 2025. \u2013 Con el prop\u00f3sito de respetar, proteger y garantizar el derecho a la privacidad e intimidad de toda persona, la diputada Biaani Palomec Enr\u00edquez plante\u00f3 a la LXVI Legislatura local sancionar en el C\u00f3digo Penal del Estado a quien o quienes utilicen Inteligencia Artificial (IA) para crear, exponer, distribuir, difundir, exhibir, reproducir, transmitir, comercializar, ofertar, intercambiar y\/o compartir im\u00e1genes, audios o videos de contenido sexual \u00edntimo de una persona, sin su consentimiento, a trav\u00e9s de cualquier medio tecnol\u00f3gico.<\/p>\n<p style=\"text-align: justify;\">En Sesi\u00f3n Ordinaria, la representante popular del Partido del Trabajo (PT), se\u00f1al\u00f3 que la IA es una herramienta poderosa que ha transformado a la sociedad y que su uso es en varios \u00e1mbitos, como en la educaci\u00f3n, la productividad y en innumerables actividades diarias, sin embargo, tambi\u00e9n ha sido empleada indebidamente con fines il\u00edcitos como la creaci\u00f3n de im\u00e1genes y videos falsos que se distribuyen sin el consentimiento de las v\u00edctimas.<\/p>\n<p style=\"text-align: justify;\">\u201cEste tipo de violencia digital vulnera la dignidad de las personas, profundiza la desigualdad y el miedo en espacios donde deber\u00edamos sentirnos seguras\u201d, dijo.<\/p>\n<p style=\"text-align: justify;\">Refiri\u00f3 que el debate actual no es sobre el uso de la tecnolog\u00eda, sino sobre la responsabilidad penal de quienes la manipulan para crear hechos falsos con apariencia real, para da\u00f1ar, de ah\u00ed, que su propuesta propone reformar y adicionar los p\u00e1rrafos cuarto y quinto del art\u00edculo 249 del C\u00f3digo Penal del Estado para ampliar las causales del delito de violaci\u00f3n a la intimidad sexual.<\/p>\n<p style=\"text-align: justify;\">De tal forma que esta conducta se sancionar\u00e1 de cuatro a ocho a\u00f1os de prisi\u00f3n y se impondr\u00e1 una multa de mil a dos mil veces el valor diario de la Unidad de Medida y Actualizaci\u00f3n (UMA) vigente al momento de que se cometa el delito, el cual se perseguir\u00e1 con querella.<\/p>\n<p style=\"text-align: justify;\">Palomec Enr\u00edquez destac\u00f3 que, en el marco de la conmemoraci\u00f3n del D\u00eda Internacional de la Mujer, se debe actuar y responder con firmeza ante esta nueva amenaza a la dignidad de las personas, como es el caso de la denominada \u201cdeepfakes\u201d (medios visuales o de audio manipulados o sint\u00e9ticos que parecen aut\u00e9nticos mediante t\u00e9cnicas de IA), que perpetua la violencia digital.<\/p>\n<p style=\"text-align: justify;\">Por ello \u00abproteger a las mujeres en el \u00e1mbito digital, es un paso m\u00e1s en nuestra lucha por la justicia y la igualdad\u201d, subray\u00f3.<\/p>\n<p style=\"text-align: justify;\">Mencion\u00f3 que, a nivel Federal, la Ley Olimpia es un precedente contra la lucha de la violencia digital, cuyo movimiento fue impulsado por Olimpia Coral Melo tras ser v\u00edctima de la difusi\u00f3n de contenido \u00edntimo sin su consentimiento. Y, en consecuencia, Oaxaca cuenta con un marco legal que sanciona la distribuci\u00f3n no autorizada de este tipo de material.<\/p>\n<p style=\"text-align: justify;\">Y desde entonces se han realizado esfuerzos legislativos para poder fortalecer esta normativa, incluyendo la incorporaci\u00f3n de mecanismos de denuncias m\u00e1s accesibles y la ampliaci\u00f3n del tipo penal para sancionar nuevas formas de este tipo de violencia.<\/p>\n<p style=\"text-align: justify;\">Es de resaltar que en el documento de dictamen se entender\u00e1 por IA a las aplicaciones, programas o tecnolog\u00eda que analice fotograf\u00edas, audios o videos, y ofrece ajustes autom\u00e1ticos para hacerles alteraciones o modificaciones.<\/p>\n<p style=\"text-align: justify;\">La iniciativa a la que se sumaron diputadas y diputados de diversos partidos pol\u00edticos fue turnada para su estudio y dictamen a la Comisi\u00f3n Permanente de Administraci\u00f3n y Procuraci\u00f3n de Justicia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>#Redacci\u00f3nOaxaca #Oaxaca * Se busca fortalecer la protecci\u00f3n de las v\u00edctimas y ampliar las causales de este delito * La violencia digital vulnera la dignidad de las personas y profundiza la desigualdad San Raymundo Jalpan, Oax., a 06 de marzo de 2025. \u2013 Con el prop\u00f3sito de respetar, proteger y garantizar el derecho a la [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4,7],"tags":[],"class_list":{"0":"post-35981","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-agenda-politica","7":"category-al-cierre"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9Ynjw-9ml","jetpack-related-posts":[{"id":39190,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2025\/11\/21\/desde-el-congreso-local-buscan-tipificar-conductas-delictivas-cometidas-con-inteligencia-artificial-ia\/","url_meta":{"origin":35981,"position":0},"title":"Desde el Congreso local buscan tipificar conductas delictivas cometidas con Inteligencia Artificial (IA)","author":"ariadna","date":"noviembre 21, 2025","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca * La Iniciativa propuesta por el diputado del PRI, Javier Casique Z\u00e1rate contempla sancionar a quien use esta herramienta para manipular contenido, falsificar, cometer fraude, ejercer violencia digital y violar los derechos de autor * Se busca proteger a la ciudadan\u00eda frente a estas amenazas emergentes San Raymundo\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/11\/Screenshot_20251121_090531_Facebook-scaled.jpg?fit=1200%2C882&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/11\/Screenshot_20251121_090531_Facebook-scaled.jpg?fit=1200%2C882&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/11\/Screenshot_20251121_090531_Facebook-scaled.jpg?fit=1200%2C882&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/11\/Screenshot_20251121_090531_Facebook-scaled.jpg?fit=1200%2C882&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/11\/Screenshot_20251121_090531_Facebook-scaled.jpg?fit=1200%2C882&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":15368,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2020\/11\/23\/aprueban-en-oaxaca-14-anos-de-carcel-a-quien-difunda-pornografia-infantil-en-redes-sociales\/","url_meta":{"origin":35981,"position":1},"title":"Aprueban en Oaxaca, 14 a\u00f1os de c\u00e1rcel a  quien difunda pornograf\u00eda infantil en redes sociales.","author":"ariadna","date":"noviembre 23, 2020","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO El Congreso de Oaxaca, aprob\u00f3 una serie de reformas al C\u00f3digo Penal del Estado, para sancionar de 9 a 14 a\u00f1os de prisi\u00f3n y multa de 700 a 900 veces el valor de la unidad de medida de actualizaci\u00f3n a quien difunda contenido de \u00edndole sexual,\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":7567,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2019\/07\/10\/establecen-en-oaxaca-carcel-de-8-anos-y-multa-de-168-mil-pesos-a-quienes-cometan-sextorcion-y-sexting\/","url_meta":{"origin":35981,"position":2},"title":"Establecen en Oaxaca, c\u00e1rcel de 8 a\u00f1os y multa de 168 mil pesos, a quienes cometan \u201csextorci\u00f3n\u201d y sexting","author":"denise","date":"julio 10, 2019","format":false,"excerpt":"#Redacci\u00f3nOaxaca Jaime GUERRERO\u00a0 La LXIV Legislatura, reform\u00f3 el C\u00f3digo Penal para tipificar Delitos contra la Intimidad Sexual en Oaxaca, para sancionar a aquella persona que por cualquier medio divulgue, comparta, distribuya, publique y\/o solicite im\u00e1genes, audios o videos de una persona desnuda parcial o totalmente de contenido \u00edntimo, er\u00f3tico o\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":32269,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2024\/06\/19\/reforma-congreso-el-codigo-penal-para-tipificar-y-sancionar-el-abuso-sexual-infantil\/","url_meta":{"origin":35981,"position":3},"title":"Reforma Congreso el C\u00f3digo Penal para tipificar y sancionar el abuso sexual infantil","author":"ariadna","date":"junio 19, 2024","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca \u2022 Cero tolerancia a la violencia sexual contra las ni\u00f1as, ni\u00f1os y adolescentes. San Raymundo Jalpan, Oax. 19 de junio de 2024.- La LXV Legislatura local reform\u00f3 el C\u00f3digo Penal de Oaxaca, para tipificar y sancionar el delito de abuso sexual infantil en el estado. En sesi\u00f3n extraordinaria,\u2026","rel":"","context":"En &quot;Imagen&quot;","block_context":{"text":"Imagen","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/imagen\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":32776,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2024\/07\/26\/legisla-h-congreso-del-estado-de-oaxaca-para-prevenir-y-sancionar-el-acoso-sexual-en-espacios-publicos\/","url_meta":{"origin":35981,"position":4},"title":"Legisla H. Congreso del Estado de Oaxaca para prevenir y sancionar el acoso sexual en espacios p\u00fablicos","author":"ariadna","date":"julio 26, 2024","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca \u2022 El Pleno aprob\u00f3 dos reformas propuestas por la diputada Mar\u00eda Luisa Matus Fuentes. San Raymundo Jalpan, Oax. 26 de julio de 2024.- El Pleno de la LXV Legislatura local aprob\u00f3 dos decretos por los cuales se reforman diversas disposiciones de la Ley Estatal de Acceso de las\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2024\/07\/FB_IMG_1722021209039-300x200.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":21118,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2021\/09\/26\/aumenta-castigo-a-quien-practique-el-matrimonio-infantil-para-cometer-actos-delictuosos\/","url_meta":{"origin":35981,"position":5},"title":"Aumenta castigo a quien practique el matrimonio infantil para cometer actos delictuosos.","author":"ariadna","date":"septiembre 26, 2021","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Comunicado San Raymundo Jalpan, Oax. 26 de septiembre 2021.- La LXIV Legislatura del Estado, aprob\u00f3 castigar hasta con 15 a\u00f1os de c\u00e1rcel, a quien obligue a contraer matrimonio a una persona menor de edad a cambio de dinero, para prostituirla o esclavizarla. Lo anterior, al adicionar un segundo\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/35981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/comments?post=35981"}],"version-history":[{"count":1,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/35981\/revisions"}],"predecessor-version":[{"id":35983,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/35981\/revisions\/35983"}],"wp:attachment":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/media?parent=35981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/categories?post=35981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/tags?post=35981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}