{"id":35984,"date":"2025-03-07T08:13:30","date_gmt":"2025-03-07T14:13:30","guid":{"rendered":"https:\/\/redaccionoaxaca.com\/?p=35984"},"modified":"2025-03-07T08:13:30","modified_gmt":"2025-03-07T14:13:30","slug":"mitla-crece-con-educacion-inauguran-extension-del-instituto-tecnologico-de-oaxaca","status":"publish","type":"post","link":"https:\/\/redaccionoaxaca.com\/index.php\/2025\/03\/07\/mitla-crece-con-educacion-inauguran-extension-del-instituto-tecnologico-de-oaxaca\/","title":{"rendered":"Mitla crece con educaci\u00f3n: Inauguran extensi\u00f3n del Instituto Tecnol\u00f3gico de Oaxaca"},"content":{"rendered":"<p><strong>#Redacci\u00f3nOaxaca<\/strong><\/p>\n<p><strong>#Oaxaca<\/strong><\/p>\n<p><strong>Hugo Velasco<\/strong><\/p>\n<p style=\"text-align: justify;\">En un hecho sin precedentes para la educaci\u00f3n en la regi\u00f3n, el presidente municipal de la Villa de Mitla, Esa\u00fa L\u00f3pez Quero, dio inicio oficial a las actividades del Instituto Tecnol\u00f3gico de Oaxaca, Extensi\u00f3n Mitla. Acompa\u00f1ado de autoridades educativas del Gobierno del Estado, el edil destac\u00f3 la importancia de este proyecto, que arranca con dos ingenier\u00edas: Civil y Gesti\u00f3n Empresarial.<\/p>\n<p style=\"text-align: justify;\">Las clases se impartir\u00e1n en las instalaciones del CECyTE plantel Mitla mientras avanzan las gestiones para la adquisici\u00f3n de un terreno propio. L\u00f3pez Quero inform\u00f3 que ya han entablado pl\u00e1ticas con autoridades ejidales y comunales para la compra de un predio de 10 hect\u00e1reas, donde se prev\u00e9 iniciar la construcci\u00f3n del campus en 2025.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-35986 aligncenter\" src=\"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/03\/unnamed-1-300x169.jpg?resize=300%2C169&#038;ssl=1\" alt=\"\" width=\"300\" height=\"169\" \/><\/p>\n<p style=\"text-align: justify;\">La apertura de esta instituci\u00f3n representa un avance significativo para los j\u00f3venes de Mitla y comunidades cercanas como Matatl\u00e1n, San Dionisio y la regi\u00f3n mixe, quienes ahora tendr\u00e1n la oportunidad de acceder a educaci\u00f3n superior sin necesidad de trasladarse a la capital del estado.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s del impacto acad\u00e9mico, la llegada del Instituto Tecnol\u00f3gico de Oaxaca a Mitla tambi\u00e9n impulsar\u00e1 la econom\u00eda local, generando empleos y fomentando el desarrollo en distintos sectores.<\/p>\n<p style=\"text-align: justify;\">Con este arranque, la educaci\u00f3n tecnol\u00f3gica en Oaxaca da un paso adelante, acercando m\u00e1s oportunidades a la juventud y fortaleciendo el crecimiento de la regi\u00f3n.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-35987 aligncenter\" src=\"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/03\/unnamed-2-300x169.jpg?resize=300%2C169&#038;ssl=1\" alt=\"\" width=\"300\" height=\"169\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>#Redacci\u00f3nOaxaca #Oaxaca Hugo Velasco En un hecho sin precedentes para la educaci\u00f3n en la regi\u00f3n, el presidente municipal de la Villa de Mitla, Esa\u00fa L\u00f3pez Quero, dio inicio oficial a las actividades del Instituto Tecnol\u00f3gico de Oaxaca, Extensi\u00f3n Mitla. Acompa\u00f1ado de autoridades educativas del Gobierno del Estado, el edil destac\u00f3 la importancia de este proyecto, [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5,3,870],"tags":[],"class_list":{"0":"post-35984","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-imagen","7":"category-mesa-de-redaccion","8":"category-obras-publicas"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9Ynjw-9mo","jetpack-related-posts":[{"id":24409,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2022\/03\/08\/sala-superior-del-tepjf-tumbo-triunfo-a-presidente-electo-de-mitla-por-rebasar-gasto-de-campana-pero-segego-lo-impone-para-gobernar\/","url_meta":{"origin":35984,"position":0},"title":"Sala Superior del TEPJF tumb\u00f3 triunfo a Presidente electo de Mitla por rebasar gasto de campa\u00f1a, pero Segego lo impone para Gobernar.","author":"ariadna","date":"marzo 8, 2022","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO No hubo impedimento jur\u00eddico, pol\u00edtico, electoral ni mucho menos de la Sala Superior del Tribunal Electoral del Poder Judicial de la Federaci\u00f3n (#TEPJF) -qui\u00e9n le hab\u00eda anulado su triunfo por rebase de tope de gastos de campa\u00f1a- para que Esa\u00fa L\u00f3pez Quero, gobierne San Pablo Villa\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":24459,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2022\/03\/10\/congreso-pide-a-murat-imparcialidad-en-eleccion-de-mitla-tras-designar-a-edil-depuesto-por-tepjf-como-comisionado\/","url_meta":{"origin":35984,"position":1},"title":"Congreso pide a Murat imparcialidad en elecci\u00f3n  de Mitla tras designar a edil depuesto por TEPJF como Comisionado.","author":"ariadna","date":"marzo 10, 2022","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO Por mayor\u00eda de votos, la LXV Legislatura, exhort\u00f3 al Gobernador del Estado, Alejandro Murat Hinojosa, a garantizar gobernabilidad e imparcialidad durante el proceso electoral extraordinario de concejal\u00edas del ayuntamiento de San Pablo Villa de Mitla, tras la designaci\u00f3n de Esa\u00fa L\u00f3pez Quero como Comisionado Municipal y\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":23383,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2022\/01\/10\/por-actos-anticipados-de-campana-multan-a-candidato-del-pri-en-mitla\/","url_meta":{"origin":35984,"position":2},"title":"Por actos anticipados de campa\u00f1a,   multan a candidato del PRI en Mitla.","author":"ariadna","date":"enero 10, 2022","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO El Pleno del Tribunal Electoral del Estado de Oaxaca (#TEEO) impuso una multa de 150 Unidades de Medida y Actualizaci\u00f3n (#UMAS) a Esa\u00fa L\u00f3pez Quero, ex candidato a presidente municipal de San Pablo Villa de Mitla, por la comisi\u00f3n de actos anticipados de campa\u00f1a. Mediante procedimientos\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":20825,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2021\/09\/13\/ratificado-como-municipe-elector-presidente-de-mitla-convoca-a-sus-ex-rivales-a-trabajar-en-paz-e-impulsar-la-economia-de-la-villa\/","url_meta":{"origin":35984,"position":3},"title":"Ratificado como Mun\u00edcipe Elector, Presidente de Mitla convoca a sus ex rivales a trabajar en paz e impulsar la econom\u00eda de la Villa.","author":"ariadna","date":"septiembre 13, 2021","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Maira Ric\u00e1rdez *Salud y reactivaci\u00f3n econ\u00f3mica, proyectos neur\u00e1lgicos de su trienio; propondr\u00e1 al INAH luz y sonido para la zona arqueol\u00f3gica, conciertos culturales y art\u00edsticos Soy oficialmente el Presidente electo del grandioso Municipio de la Villa de Mitla, afirm\u00f3 Esau L\u00f3pez Quero, quien tras varios meses de litigio\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":23033,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2021\/12\/22\/video-sala-superior-del-tepjf-anula-eleccion-en-mitla-ordena-al-ieepco-realizar-comicio-extraordinario\/","url_meta":{"origin":35984,"position":4},"title":"VIDEO: Sala Superior del TEPJF anula elecci\u00f3n en Mitla, ordena al IEEPCO realizar comicio extraordinario.","author":"ariadna","date":"diciembre 22, 2021","format":"video","excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO Por mayor\u00eda, la Sala Superior del Tribunal Electoral del Poder Judicial de la Federaci\u00f3n (#TEPJF), anul\u00f3 la elecci\u00f3n de concejal\u00edas del Municipio de San Pablo Villa de Mitla por rebase de tope de gastos de campa\u00f1a y orden\u00f3 al Instituto Estatal Electoral y de Participaci\u00f3n Ciudadana\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":35319,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2025\/01\/25\/sheinbaum-inaugura-la-carretera-mitla-tehuantepec\/","url_meta":{"origin":35984,"position":5},"title":"SHEINBAUM INAUGURA LA CARRETERA MITLA \u2013 TEHUANTEPEC","author":"ariadna","date":"enero 25, 2025","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO Este viernes, la Presidenta de M\u00e9xico, Claudia Sheinbaum Pardo, inaugur\u00f3 la carretera Mitla-Tehuantepec, tramo Llano Crucero-San Juan Lachixila. Despues de 18 a\u00f1os, se pone en operaci\u00f3n sus 169 kil\u00f3metros (km), reduciendo as\u00ed el tiempo de traslado de 4 horas y media a 2 horas y media\u2026","rel":"","context":"En &quot;Mesa de Redacci\u00f3n&quot;","block_context":{"text":"Mesa de Redacci\u00f3n","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/mesa-de-redaccion\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/35984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/comments?post=35984"}],"version-history":[{"count":1,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/35984\/revisions"}],"predecessor-version":[{"id":35988,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/35984\/revisions\/35988"}],"wp:attachment":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/media?parent=35984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/categories?post=35984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/tags?post=35984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}