{"id":36083,"date":"2025-03-14T11:43:53","date_gmt":"2025-03-14T17:43:53","guid":{"rendered":"https:\/\/redaccionoaxaca.com\/?p=36083"},"modified":"2025-03-14T11:43:53","modified_gmt":"2025-03-14T17:43:53","slug":"firmes-las-elecciones-de-agentes-municipales-en-oaxaca-de-juarez-4-ya-electas-7-van-eleccion-en-guadalupe-victoria-va-persona-administradora","status":"publish","type":"post","link":"https:\/\/redaccionoaxaca.com\/index.php\/2025\/03\/14\/firmes-las-elecciones-de-agentes-municipales-en-oaxaca-de-juarez-4-ya-electas-7-van-eleccion-en-guadalupe-victoria-va-persona-administradora\/","title":{"rendered":"Firmes las elecciones de Agentes Municipales en Oaxaca de Ju\u00e1rez. 4 ya electas, 7 van elecci\u00f3n; en Guadalupe Victoria va persona administradora"},"content":{"rendered":"<p><strong>#Redacci\u00f3nOaxaca<\/strong><\/p>\n<p><strong>#Oaxaca<\/strong><\/p>\n<p><strong>Jaime GUERRERO<\/strong><\/p>\n<p style=\"text-align: justify;\">El Presidente del municipio de Oaxaca de Ju\u00e1rez, Raymundo Chagoya Villanueva, confirm\u00f3 que las elecciones de agentes municipales est\u00e1n firmes, cumpliendo con todos los principios constitucionales en materia electoral, de paridad, alternancia y equidad de g\u00e9nero.<\/p>\n<p style=\"text-align: justify;\">A unas horas de la nueva jornada electoral municipal, inform\u00f3 que, respecto al procedimiento de elecciones por planilla en siete agencias, siguen firmes y en el caso de la impugnaci\u00f3n a la convocatoria en Santa Rosa, la Xalapa del Tribunal Electoral del Poder Judicial de la Federaci\u00f3n, dej\u00f3 firme, la convocatoria.<\/p>\n<p style=\"text-align: justify;\">Ese \u00f3rgano jurisdiccional desestim\u00f3 los agravios presentados y avalados por el Tribunal Electoral del Estado de Oaxaca que, adem\u00e1s se presentaron de forma extempor\u00e1nea, cinco d\u00edas despu\u00e9s.<\/p>\n<p style=\"text-align: justify;\">La fecha de la elecci\u00f3n en Santa Rosa, ser\u00e1 determinada en sesi\u00f3n de cabildo y est\u00e1 programada para este 15 de marzo.<\/p>\n<p style=\"text-align: justify;\">En un segundo plano, chagoya Villanueva, destac\u00f3 que en las elecciones por usos y costumbres que en general se celebraron sin mayores incidentes, est\u00e1n ya culminados en cuatro de las cinco agencias.<\/p>\n<p style=\"text-align: justify;\">En el caso de la Agencia de Guadalupe Victoria, confirm\u00f3 que, la Comisi\u00f3n de gobierno y territorio, recibi\u00f3 una acta notarial en la cual tanto la gente municipal, como el secretario de la mesa, se\u00f1alan que no se termin\u00f3 el proceso de elecci\u00f3n y se presentaron hechos aislados de violencia.<\/p>\n<p style=\"text-align: justify;\">Por lo tanto, la Comisi\u00f3n de Gobierno, anular\u00e1 el proceso electoral en Guadalupe Victoria y se designar\u00e1 a una persona administradora por 60 d\u00edas y de existir las condiciones se convocar\u00e1 a nuevas elecciones.<\/p>\n<p style=\"text-align: justify;\">La persona administradora, se encargar\u00e1 de todos los procesos administrativos, debido a que es importante continuar con la priorizaci\u00f3n de obras para dar paso a la estabilidad.<\/p>\n<p style=\"text-align: justify;\">En tanto, Chagoya Villanueva, confirm\u00f3 que, tomar\u00e1 protesta al cargo a los agentes municipales de cuatro agencias que se rigen por los usos y costumbres:<\/p>\n<p style=\"text-align: justify;\">Trinidad de Viguera, Donaj\u00ed, San Luis Beltr\u00e1n y Montoya.<\/p>\n<p style=\"text-align: justify;\">En el caso de las agencias que se eligen mediante planillas, el Alcalde Capitalino, inform\u00f3 que no existen contratiempos para que se celebren este 15 de marzo.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s de la elecci\u00f3n en la Agencia de Santa Rosa, este 15 de marzo, se celebrar\u00e1n elecciones en Cinco se\u00f1ores, Candiani, Pueblo, nuevo, Dolores, San Mart\u00edn, y San Juan Chapultepec.<\/p>\n<p style=\"text-align: justify;\">En medio de los procesos electorales en las agencias que conforman el municipio de de Oaxaca de Juarez, Chagoya Villanueva, llam\u00f3 a la civilidad y concordia para generar estabilidad y paz.<\/p>\n<p style=\"text-align: justify;\">M\u00e1s all\u00e1 de pasiones, afinidades, filias o fobias, destac\u00f3 que el proyecto com\u00fan es el municipio de Oaxaca de Juarez.<\/p>\n<p style=\"text-align: justify;\">Asegur\u00f3 que su administraci\u00f3n est\u00e1 abocada al di\u00e1logo con todos y todas las actoras.<\/p>\n<p style=\"text-align: justify;\">Chagoya Villanueva, refiri\u00f3 que para los procesos electorales en las agencias, se capacit\u00f3 a los funcionarios electorales municipales y dan seguimiento puntual con la Secretar\u00eda de Gobierno.<\/p>\n<p style=\"text-align: justify;\">El municipe, apost\u00f3 a la participaci\u00f3n en el \u00e1nimo democr\u00e1tico y las vecinas y vecinos salgan a elegir a agentes municipales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO El Presidente del municipio de Oaxaca de Ju\u00e1rez, Raymundo Chagoya Villanueva, confirm\u00f3 que las elecciones de agentes municipales est\u00e1n firmes, cumpliendo con todos los principios constitucionales en materia electoral, de paridad, alternancia y equidad de g\u00e9nero. A unas horas de la nueva jornada electoral municipal, inform\u00f3 que, respecto al procedimiento de [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4,7,5],"tags":[],"class_list":{"0":"post-36083","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-agenda-politica","7":"category-al-cierre","8":"category-imagen"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9Ynjw-9nZ","jetpack-related-posts":[{"id":35870,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2025\/02\/27\/municipio-de-oaxaca-de-juarez-ajustara-convocatoria-de-agentes-municipales-en-cumplimiento-de-la-resolucion-del-teeo\/","url_meta":{"origin":36083,"position":0},"title":"Municipio de Oaxaca de Ju\u00e1rez ajustar\u00e1 convocatoria de agentes municipales en cumplimiento de la resoluci\u00f3n del TEEO","author":"ariadna","date":"febrero 27, 2025","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca \u2022 Se reforzar\u00e1n los principios de alternancia, competitividad y paridad de g\u00e9nero en el proceso electoral. \u2022 Se emitir\u00e1 una nueva convocatoria para fortalecer la equidad, alternancia y participaci\u00f3n efectiva en la elecci\u00f3n de agentes municipales. Oaxaca de Ju\u00e1rez, Oax., 27 de febrero de 2025.- En cumplimiento de\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/02\/IMG-20250227-WA0053-232x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":13398,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2020\/07\/15\/sala-xalapa-tumba-4-presidentes-municipales-de-oaxaca-y-deja-firmes-a-10-en-san-antonio-de-la-cal-se-cae-edil\/","url_meta":{"origin":36083,"position":1},"title":"Sala Xalapa tumba 4 Presidentes Municipales de Oaxaca  y deja firmes a 10; en San Antonio de la Cal se cae edil.","author":"ariadna","date":"julio 15, 2020","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO La Sala Regional Xalapa del Tribunal Electoral del Poder Judicial de la Federaci\u00f3n (TEPJF) 14 impugnaciones a 14 las elecciones de concejales de ayuntamientos de Oaxaca, que se rigen por sistemas normativos internos. En sesi\u00f3n no presencial, ante la emergencia sanitaria provocada por el virus SARS-CoV2\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":22876,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2021\/12\/10\/video-gobernador-de-oaxaca-alista-designacion-de-comisionados-en-municipios-que-no-tendran-concejalias-electas-el-1-de-enero\/","url_meta":{"origin":36083,"position":2},"title":"VIDEO: Gobernador de Oaxaca alista designaci\u00f3n de comisionados  en municipios que no tendr\u00e1n concejal\u00edas electas el 1 de enero.","author":"ariadna","date":"diciembre 10, 2021","format":"video","excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO El Gobernador del Estado, Alejandro Murat Hinojosa, anunci\u00f3 que alista la designaci\u00f3n de los comisionados para los municipios donde no se celebraron elecci\u00f3n de concejal\u00edas por nulidad de los tribunales electorales y la no celebraci\u00f3n de las elecciones ordinarias el pasado 6 de junio. Y es\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3267,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2018\/10\/15\/teeo-deja-firmes-elecciones-de-cuilapam-y-tetepec\/","url_meta":{"origin":36083,"position":3},"title":"TEEO deja firmes elecciones de Cuilapam y Tetepec","author":"jaime","date":"octubre 15, 2018","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO Por unanimidad de votos el Pleno del Tribunal Electoral del Estado de Oaxaca, confirm\u00f3 la elecci\u00f3n de autoridades de los municipios Cuilapam de Guerrero y Santiago Tetepec. Al resolver el expediente RIN\/EA\/21\/2018 y acumulado, los Magistrados confirmaron los resultados consignados en el acta de c\u00f3mputo municipal,\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":22867,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2021\/12\/09\/elecciones-extraordinarias-en-6-municipios-y-1-diputacion-de-oaxaca-hasta-6-de-marzo-de-2022-acuerdan-ine-ieepco-alistan-comisionados\/","url_meta":{"origin":36083,"position":4},"title":"Elecciones extraordinarias en 6 municipios y 1 diputaci\u00f3n de Oaxaca,  hasta 6 de marzo de 2022, acuerdan INE-IEEPCO; alistan comisionados.","author":"ariadna","date":"diciembre 9, 2021","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO El Instituto Nacional Electoral (#INE) y el Instituto Estatal Electoral y de Participaci\u00f3n Ciudadana de Oaxaca (#IEEPCO), acordaron que la jornada electoral para las elecciones extraordinarias de concejal\u00edas en 6 ayuntamientos y 1 diputaci\u00f3n local vacate -hasta el momento firmes por decretos y sentencias de tribunales-\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":35863,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2025\/02\/26\/teeo-tumba-convocatoria-de-eleccion-de-agentes-municipales-de-pueblo-nuevo-san-juan-chapultepec-dolores-y-cinco-senores-por-vulnerar-paridad-y-alternancia-de-genero\/","url_meta":{"origin":36083,"position":5},"title":"TEEO tumba convocatoria de elecci\u00f3n de agentes municipales de Pueblo Nuevo, San Juan Chapultepec, Dolores y Cinco Se\u00f1ores por vulnerar paridad y alternancia de g\u00e9nero","author":"ariadna","date":"febrero 26, 2025","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO El pleno del Tribunal Electoral del Estado de Oaxaca (TEEO), revoc\u00f3 la convocatoria de elecci\u00f3n en cuatro agencias del municipio de Oaxaca de Ju\u00e1rez que no se rigen por usos y costumbres, por vulnerar el principio de paridad y alternancia de g\u00e9nero. De acuerdo a las\u2026","rel":"","context":"En &quot;Al Cierre&quot;","block_context":{"text":"Al Cierre","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/al-cierre\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/36083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/comments?post=36083"}],"version-history":[{"count":1,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/36083\/revisions"}],"predecessor-version":[{"id":36085,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/36083\/revisions\/36085"}],"wp:attachment":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/media?parent=36083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/categories?post=36083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/tags?post=36083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}