{"id":36120,"date":"2025-03-17T14:20:37","date_gmt":"2025-03-17T20:20:37","guid":{"rendered":"https:\/\/redaccionoaxaca.com\/?p=36120"},"modified":"2025-03-17T14:20:37","modified_gmt":"2025-03-17T20:20:37","slug":"el-consejo-ciudadano-de-la-ddhpo-debe-ser-conformado-por-personas-con-un-perfil-integro-y-libre-de-antecedentes-de-incumplimiento-de-obligaciones-familiares","status":"publish","type":"post","link":"https:\/\/redaccionoaxaca.com\/index.php\/2025\/03\/17\/el-consejo-ciudadano-de-la-ddhpo-debe-ser-conformado-por-personas-con-un-perfil-integro-y-libre-de-antecedentes-de-incumplimiento-de-obligaciones-familiares\/","title":{"rendered":"El Consejo Ciudadano de la DDHPO debe ser conformado por personas con un perfil \u00edntegro y libre de antecedentes de incumplimiento de obligaciones familiares"},"content":{"rendered":"<p><strong>#Redacci\u00f3nOaxaca<\/strong><\/p>\n<p><strong>#Oaxaca<\/strong><\/p>\n<p style=\"text-align: justify;\"><em>* Mediante la iniciativa de ley se busca fortalecer la \u00e9tica y responsabilidad sociales de este \u00f3rgano colegiado<\/em><\/p>\n<p style=\"text-align: justify;\"><em>* La medida contribuye a consolidar un Estado m\u00e1s justo y equitativo, donde la ni\u00f1ez y adolescencia sean la prioridad en todas las esferas sociales<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>San Raymundo Jalpan, Oax., a 17 de marzo de 2025.<\/strong>&#8211; Con el prop\u00f3sito de incorporar en la Ley de la Defensor\u00eda de los Derechos Humanos del Pueblo de Oaxaca (DDHPO) como requisito que las personas que aspiren a ser integrantes del Consejo Ciudadano no deber\u00e1n estar inscritas en el Registro de Deudores Alimentarios Morosos y en el Registro Nacional de Personas Sancionadas en Materia de Violencia Pol\u00edtica contra las Mujeres en raz\u00f3n de G\u00e9nero, integrantes de la Comisi\u00f3n Permanente de Derechos Humanos de la LXVI Legislatura local presentaron una iniciativa en la materia.<\/p>\n<p style=\"text-align: justify;\">Por ello, se plantea reformar las fracciones V y VI; adicionar la fracci\u00f3n VII al art\u00edculo 27 SEPTIES de la DDHPO, para que quienes integren el Consejo Ciudadano cuenten con un perfil \u00edntegro y libre de antecedentes de incumplimiento de obligaciones familiares.<\/p>\n<p style=\"text-align: justify;\">La propuesta suscrita por el diputado que presidente el referido \u00f3rgano legislativo Isaac L\u00f3pez L\u00f3pez, as\u00ed como las diputadas que lo conforman: Cecilia Olivia Cruz Merl\u00edn, Analy Peral Vivar, Dulce Bel\u00e9n Uribe Mendoza y Elisa Zepeda Lagunas, est\u00e1 alineada con los principios de equidad de g\u00e9nero, protecci\u00f3n de la infancia y fortalecimiento de la cultural de responsabilidad parental, con miras a la consolidaci\u00f3n de instituciones m\u00e1s confiables y comprometidas con el bienestar social.<\/p>\n<p style=\"text-align: justify;\">Al hacer uso de la palabra en tribuna el representante popular Isaac L\u00f3pez L\u00f3pez destac\u00f3 que, la defensa y promoci\u00f3n de las garant\u00edas individuales requiere que quienes integran los \u00f3rganos encargados de su protecci\u00f3n sean personas con una trayectoria intachable, \u00e9tica y comprometida con los valores de justicia, igualdad y responsabilidad social.<\/p>\n<p style=\"text-align: justify;\">\u201c<em>Este requisito no solo busca elevar los est\u00e1ndares \u00e9ticos de quienes ocupan este cargo, sino que tambi\u00e9n pretende enviar un mensaje claro sobre la importancia de garantizar los derechos de las ni\u00f1as, ni\u00f1os y adolescentes, pues alguien que defienda los derechos humanos no puede, en su vida privada, ser omiso con una obligaci\u00f3n tan b\u00e1sica como en sustento de sus hijas e hijos\u201d,<\/em> subray\u00f3.<\/p>\n<p style=\"text-align: justify;\">Y es que refiri\u00f3 que uno de los derechos fundamentales m\u00e1s vulnerados en la actualidad es el de la alimentaci\u00f3n en las infancias y adolescencias, lo que constituye una forma de violencia econ\u00f3mica y patrimonial que afecta el desarrollo y bienestar de esta poblaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Por ello consider\u00f3 que Oaxaca debe dar un paso firme y alinear su marco jur\u00eddico con las reformas nacionales que sancionan a quienes incumplen con sus obligaciones alimentarias.<\/p>\n<p style=\"text-align: justify;\">Record\u00f3 que el 26 de mayo de 2023 el Pleno de 65 Legislatura del Congreso del Estado aprob\u00f3 el decreto enviado por el Congreso de la Uni\u00f3n, por el cual se reformaron los art\u00edculos 38 y 102 de la Constituci\u00f3n Pol\u00edtica de M\u00e9xico, en donde se establece que una persona no podr\u00e1 ser registrada como candidata a cualquier cargo de elecci\u00f3n popular u ocupar un empleo, cargo o comisi\u00f3n en el servicio p\u00fablico por tener sentencia de haber cometido alg\u00fan delito contra las mujeres o ser deudor alimentario.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>#Redacci\u00f3nOaxaca #Oaxaca * Mediante la iniciativa de ley se busca fortalecer la \u00e9tica y responsabilidad sociales de este \u00f3rgano colegiado * La medida contribuye a consolidar un Estado m\u00e1s justo y equitativo, donde la ni\u00f1ez y adolescencia sean la prioridad en todas las esferas sociales San Raymundo Jalpan, Oax., a 17 de marzo de 2025.&#8211; [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4,7,5],"tags":[],"class_list":{"0":"post-36120","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-agenda-politica","7":"category-al-cierre","8":"category-imagen"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9Ynjw-9oA","jetpack-related-posts":[{"id":380,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2018\/06\/15\/congreso-elije-a-consejo-ciudadano-de-la-ddhpo-afines-a-partidos-y-politicos\/","url_meta":{"origin":36120,"position":0},"title":"Congreso elije a Consejo Ciudadano de la DDHPO, afines a Partidos y Pol\u00edticos","author":"gaby","date":"junio 15, 2018","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO Luego de un mes de mantener en la congeladora la designaci\u00f3n, la LXIII Legislatura, eligi\u00f3 a nuevos integrantes del Consejo Ciudadano de la Defensor\u00eda de los Derechos Humanos del Pueblo de Oaxaca (DDHPO). En sesi\u00f3n extraordinaria, los diputados aprobaron la repartici\u00f3n de cuotas partidarias en ese\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":35035,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2025\/01\/09\/desde-el-congreso-se-trabaja-en-la-proteccion-de-los-derechos-humanos\/","url_meta":{"origin":36120,"position":1},"title":"Desde el Congreso se trabaja en la protecci\u00f3n de los derechos humanos","author":"ariadna","date":"enero 9, 2025","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca * La DDHPO inform\u00f3 al Congreso del Estado, sobre la importancia de la integraci\u00f3n del Consejo Ciudadano de este \u00f3rgano aut\u00f3nomo San Raymundo Jalpan, Oax., a 09 de enero de 2025.- En sesi\u00f3n ordinaria, la Comisi\u00f3n Permanente de Derechos Humanos de la LXVI Legislatura local reafirm\u00f3 su compromiso\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":31206,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2024\/04\/11\/consejo-ciudadano-de-busqueda-de-personas-desaparecidas-de-oaxaca-reportan-600-casos\/","url_meta":{"origin":36120,"position":2},"title":"Consejo ciudadano de b\u00fasqueda de personas  desaparecidas de Oaxaca, reportan 600 casos","author":"ariadna","date":"abril 11, 2024","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO En Oaxaca existe un rezago en la investigaci\u00f3n de 600 carpetas por casos de desapariciones de personas, reportaron integrantes del Consejo Estatal Ciudadano de B\u00fasqueda de Personas Desaparecidas para el Estado. Este mi\u00e9rcoles, en sesi\u00f3n ordinaria del pleno de la LXV Legislatura, integrantes del Consejo Estatal\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":29273,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2023\/09\/07\/morena-y-sus-aliados-reforman-ley-de-desaparicion-de-personas-de-oaxaca-para-permitir-que-ex-lideres-de-partidos-politicos-y-ex-servidores-publicos-integren-consejo-ciudadano-busqueda\/","url_meta":{"origin":36120,"position":3},"title":"Morena y sus aliados reforman Ley de Desaparici\u00f3n de Personas de Oaxaca, para permitir que ex l\u00edderes de partidos pol\u00edticos y ex servidores p\u00fablicos integren Consejo Ciudadano B\u00fasqueda","author":"ariadna","date":"septiembre 7, 2023","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO El Pleno de la 65 Legislatura, reform\u00f3 la Ley en Materia de Desaparici\u00f3n de Personas para el Estado de Oaxaca, para permitir que ex l\u00edderes de partidos pol\u00edticos y ex servidores p\u00fablicos formen parte del Consejo Estatal Ciudadano en Materia de b\u00fasqueda de personas. En la\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":24304,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2022\/03\/01\/ddhpo-pide-a-gobiernos-garantizar-seguridad-para-evitar-que-por-violencia-se-enrarezcan-elecciones-de-oaxaca\/","url_meta":{"origin":36120,"position":4},"title":"DDHPO pide a Gobiernos garantizar seguridad para evitar que por violencia se enrarezcan elecciones de Oaxaca.","author":"ariadna","date":"marzo 1, 2022","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO Tras el ataque con fuego a una de las sedes del Instituto Estatal Electoral y de Participaci\u00f3n Ciudadana de Oaxaca (#IEEPCO), la Defensor\u00eda de los Derechos Humanos del Pueblo de Oaxaca (#DDHPO) llam\u00f3 a todos los niveles de gobierno a garantizar las condiciones adecuadas en el\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":31639,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2024\/05\/07\/ieepco-devuelve-pluri-1-a-morena-por-orden-del-teeo\/","url_meta":{"origin":36120,"position":5},"title":"IEEPCO devuelve pluri 1 a Morena por orden del TEEO","author":"ariadna","date":"mayo 7, 2024","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO Tras la sentencia del Tribunal Electoral del Estado de Oaxaca (TEEO), el Consejo General del Instituto Estatal Electoral y de Participaci\u00f3n Ciudadana de Oaxaca (IEEPCO), aprob\u00f3 el registro de Kelly Jannet Cabrera Gonz\u00e1lez, como candidata propietaria a diputada local Plurinominal en el lugar 1 de la\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/36120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/comments?post=36120"}],"version-history":[{"count":1,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/36120\/revisions"}],"predecessor-version":[{"id":36122,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/36120\/revisions\/36122"}],"wp:attachment":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/media?parent=36120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/categories?post=36120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/tags?post=36120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}