{"id":36795,"date":"2025-05-12T16:42:43","date_gmt":"2025-05-12T22:42:43","guid":{"rendered":"https:\/\/redaccionoaxaca.com\/?p=36795"},"modified":"2025-05-12T16:42:43","modified_gmt":"2025-05-12T22:42:43","slug":"en-un-mismo-dia-se-fugo-un-reo-y-otros-dos-mueren-en-el-penal-de-tanivet-oaxaca-sspc","status":"publish","type":"post","link":"https:\/\/redaccionoaxaca.com\/index.php\/2025\/05\/12\/en-un-mismo-dia-se-fugo-un-reo-y-otros-dos-mueren-en-el-penal-de-tanivet-oaxaca-sspc\/","title":{"rendered":"En un mismo d\u00eda, se fug\u00f3 un reo y otros dos mueren en el penal de Tanivet, Oaxaca: SSPC"},"content":{"rendered":"<p><strong>#Redacci\u00f3nOaxaca<\/strong><\/p>\n<p><strong>#Oaxaca<\/strong><\/p>\n<p><strong>Jaime GUERRERO<\/strong><\/p>\n<p style=\"text-align: justify;\">La madrugada del pasado viernes 9 de mayo se fug\u00f3 del Penal de Mediana Seguridad de Tanivet, Oaxaca, una Persona Privada de su Libertad (PPL) de nombre Amin G\u00f3mez Bautista, cuya habilidad de herrero le permiti\u00f3 mayor facilidad de vencer los barrotes para poder huir pero dej\u00f3 en entredicho el sistema de vigilancia por parte de los custodios.<\/p>\n<p style=\"text-align: justify;\">Simult\u00e1neamente, en hechos distintos, dos reos m\u00e1s murieron: uno por un paro cardiaco y otro se suicido.<\/p>\n<p style=\"text-align: justify;\">Seg\u00fan la versi\u00f3n oficial, el PPL Amin se encontraba a\u00fan por la noche anterior en el pase de lista, sin embargo, en el pase de lista de las 6:00 horas de la ma\u00f1ana ya no estaba.<\/p>\n<p style=\"text-align: justify;\">El Subsecretario de Prevenci\u00f3n y Reinserci\u00f3n Social de la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana de Oaxaca, Roberto Claudio Castillo Ram\u00edrez, confirm\u00f3 que en el caso de Amin, los custodios realzaron una b\u00fasqueda, tanto interna como externa.<\/p>\n<p style=\"text-align: justify;\">Al interior del penal se revisaron todos los n\u00f3dulos, las \u00e1reas; mientras al exterior en todo el per\u00edmetro.<\/p>\n<p style=\"text-align: justify;\">Hasta la fecha se lleva acabo la b\u00fasqueda de la persona privada de la libertad de nombre Amin, procesado por el delito de robo a casa habitaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Castillo Ram\u00edrez, confirm\u00f3 que, el perfil de Amin es de ocupaci\u00f3n de herrero, lo que le dio la \u201chabilidad sistem\u00e1tica\u201d de vencer los barrotes.<\/p>\n<p style=\"text-align: justify;\">En la ma\u00f1ana de ese mismo viernes, a las ocho de la ma\u00f1ana, se report\u00f3 una emergencia m\u00e9dica en el m\u00f3dulo 12, donde una persona se encontraba pr\u00e1cticamente inconsciente.<\/p>\n<p style=\"text-align: justify;\">En consecuencia se activ\u00f3 el protocolo de emergencia m\u00e9dica, se le pudo reanimar y se solicit\u00f3 de manera inmediata la ex carcelaci\u00f3n m\u00e9dica al hospital rural del IMSS-Bienestar 36<\/p>\n<p style=\"text-align: justify;\">En esa cl\u00ednica fue atendido, \u201cpero desafortunadamente fallece en el hospital por causa de muerte por un paro cardiorespiratorio secundario a infarto agudo al miocardio\u201d.<\/p>\n<p style=\"text-align: justify;\">Ese fue el diagn\u00f3stico de muerte que report\u00f3 Castillo Ram\u00edrez.<\/p>\n<p style=\"text-align: justify;\">Desafortunadamente, dijo, dentro del umbral de la b\u00fasqueda de Amin, quien se fug\u00f3, se present\u00f3 la muerte de otro PPL por el paro cardiaco.<\/p>\n<p style=\"text-align: justify;\">No todo acab\u00f3 ah\u00ed. A las 5:45 de la tarde, cuando el Personal de Custodia entregaba los alimentos en el \u00e1rea de observatorio, PPL\u2019S, gritaban.<\/p>\n<p style=\"text-align: justify;\">En respuesta, un custodio se acerca y en la celda n\u00famero 12, descubri\u00f3 a una persona privada de su libertad \u201cque desafortunadamente se priva de la vida. Se cuelga con un mecate, y desafortunadamente muere\u201d.<\/p>\n<p style=\"text-align: justify;\">Castillo Ram\u00edrez, afirm\u00f3 que la necropsia de ley, se cuenta con un certificado de defunci\u00f3n que establece lesiones auto infringidas intencionalmente causadas por asfixia mec\u00e1nica por ahorcadura.<\/p>\n<p style=\"text-align: justify;\">El Subsecretario de Prevenci\u00f3n y Reinserci\u00f3n Social, concedi\u00f3 que, cada uno de estos eventos ocurren dentro de 24 horas dentro del penal.<\/p>\n<p style=\"text-align: justify;\">Sin embargo, afirm\u00f3 que, no est\u00e1n conectados o no son conexos como tal, como lo hicieron ver varias publicaciones en redes sociales que partieron de la g\u00e9nesis del operativo de b\u00fasqueda del reo fugado Amin.<\/p>\n<p style=\"text-align: justify;\">Castillo Ram\u00edrez, explic\u00f3 que derivado de la fuga de Amin, se clasifica el delito de evasi\u00f3n de reos, por ello, las personas identificadas como C.C.I.,Subdirector de Seguridad Penitenciaria; P.E.R.J, Inspector; A.A.L, Custodio Penitenciario y H.J.R.V, Custodio Penitenciario, fueron presentadas ante el ministerio p\u00fablico por su presunta participaci\u00f3n en la fuga de Amin G\u00f3mez Bautista.<\/p>\n<p style=\"text-align: justify;\">Asimismo, fue cesado el director del penal.<\/p>\n<p style=\"text-align: justify;\">\u201cEs un delito que yo me permitir\u00eda decirle es que es un delito de comisi\u00f3n por omisi\u00f3n que se\u00f1ala la ley penal. La persona custodia o los encargados de los establecimientos penales tenemos un deber del cuidado de las personas privadas de su libertad, pero sobretodo del cumplimiento de ejecuci\u00f3n de la penal\u201d.<\/p>\n<p style=\"text-align: justify;\">Por ello, se pusieron a disposici\u00f3n a cinco personas que llevaban a cargo servicios de custodia, tambi\u00e9n hubo responsabilidades administrativas del director del centro penitenciario, quien ya fue cesado.<\/p>\n<p style=\"text-align: justify;\">Ahora corresponder\u00e1 a la Fiscal\u00eda del Estado, realizar las indagatorias y determinar si son o no responsables de la fuga del reo.<\/p>\n<p style=\"text-align: justify;\">Castillo Ram\u00edrez, afirm\u00f3 que cuenta con todos los elementos probatorios, documentales id\u00f3neos para acreditar la versi\u00f3n respecto a que la fuga y las muertes de reos no est\u00e1s conectadas.<\/p>\n<p style=\"text-align: justify;\">A la par, la Fiscal\u00eda General del Estado, est\u00e1 llevando una investigaci\u00f3n en cada uno de estos casos.<\/p>\n<p style=\"text-align: justify;\">Castillo Ram\u00edrez, argument\u00f3 que la versi\u00f3n oficial se emiti\u00f3 d\u00edas posteriores a los hechos, debido a que recabaron la informaci\u00f3n con la que pudieran sustentar la veracidad de los hechos en torno al penal de Tanivet.<\/p>\n<p style=\"text-align: justify;\">El pasado 4 de abril, otro preso identificado como \u00d3scar Mario \u201cN\u201d, acusado de homicidio, tambi\u00e9n logr\u00f3 fugarse del centro penitenciario tras haber sido trasladado a una visita m\u00e9dica en un hospital de la zona.<\/p>\n<p style=\"text-align: justify;\">Fuentes oficiales informan que \u00d3scar \u201cN\u201d logr\u00f3 escapar con la ayuda de un c\u00f3mplice que le facilit\u00f3 un arma y un veh\u00edculo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO La madrugada del pasado viernes 9 de mayo se fug\u00f3 del Penal de Mediana Seguridad de Tanivet, Oaxaca, una Persona Privada de su Libertad (PPL) de nombre Amin G\u00f3mez Bautista, cuya habilidad de herrero le permiti\u00f3 mayor facilidad de vencer los barrotes para poder huir pero dej\u00f3 en entredicho el sistema [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5,3,6],"tags":[],"class_list":{"0":"post-36795","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-imagen","7":"category-mesa-de-redaccion","8":"category-tendencias"},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9Ynjw-9zt","jetpack-related-posts":[{"id":36777,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2025\/05\/09\/detendios-4-personas-por-fuga-del-reo-del-penal-de-tanivet-fgeo\/","url_meta":{"origin":36795,"position":0},"title":"Detendios 4 personas por fuga del reo del penal de Tanivet; FGEO","author":"ariadna","date":"mayo 9, 2025","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Oaxaca de Ju\u00e1rez a 09 de mayo de 2025.- La Fiscal\u00eda General del Estado de Oaxaca (FGEO) tiene en calidad de detenidas a cuatro personas, por quienes se investiga su nivel de responsabilidad en la fuga de una Persona Privada de la Libertad (PPL) que estaba internada en\u2026","rel":"","context":"En &quot;Al Cierre&quot;","block_context":{"text":"Al Cierre","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/al-cierre\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/05\/IMG-20250509-WA0225-300x175.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":14921,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2020\/10\/26\/confirma-murat-cierre-del-penal-de-ixcotel-ppl-fueron-trasladados-a-tanivet\/","url_meta":{"origin":36795,"position":1},"title":"Confirma Murat cierre del penal de Ixcotel; PPL fueron trasladados a Tanivet.","author":"ariadna","date":"octubre 26, 2020","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO El Gobernador, Alejandro Murat Hinojosa, confirm\u00f3 el cierre del Penal de Santa Mar\u00eda Ixcotel, ubicado en Santa Luc\u00eda del Camino y que las Personas Privadas de su Libertad (PPL), fueron trasladados al penal de media seguridad Tanivet en Tlacolula de Matamoros. El mandatario confirm\u00f3 que desde\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2020\/10\/IMG-20201026-WA0056-300x200.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":14937,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2020\/10\/26\/video-sedena-es-propietaria-del-penal-de-ixcotel-tras-cierre-su-destino-podria-ser-educativo-deportivo-y-cultural-murat\/","url_meta":{"origin":36795,"position":2},"title":"VIDEO: SEDENA es propietaria del Penal de Ixcotel, tras cierre su destino podr\u00eda ser educativo, deportivo y cultural: Murat.","author":"ariadna","date":"octubre 26, 2020","format":"video","excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO El Gobernador, Alejandro Murat Hinojosa, desestim\u00f3 que el complejo que albergaba el Penal de Santa Mar\u00eda Ixcotel, se ocupe para la edificaci\u00f3n de un complejo inmobiliario o comercial. Tras el cierre definitivo del penal que por m\u00e1s de 57 a\u00f1os sirvi\u00f3 para que personas privadas de\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2020\/10\/IMG-20201026-WA0160-300x200.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":9871,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2020\/01\/03\/reubican-a-todos-los-internos-del-penal-de-pochutla\/","url_meta":{"origin":36795,"position":3},"title":"REUBICAN A TODOS LOS INTERNOS DEL PENAL DE POCHUTLA.","author":"ariadna","date":"enero 3, 2020","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca La madrugada de este viernes m\u00e1s de 200 internos del penal de San Pedro #Pochutla fueron trasladados al Centro de Reinserci\u00f3n Social de #Tanivet,\u00a0en #Tlacolula. El operativo coordinado por la Secretar\u00eda de Seguridad P\u00fablica de #Oaxaca a trav\u00e9s de la Direcci\u00f3n General de Reinserci\u00f3n Social concluy\u00f3 sin incidentes\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2020\/01\/IMG-20200103-WA0015-300x225.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12743,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2020\/06\/09\/muere-recluso-en-el-centro-penitenciario-varonil-de-tanivet\/","url_meta":{"origin":36795,"position":4},"title":"Muere recluso en el Centro Penitenciario Varonil de Tanivet.","author":"ariadna","date":"junio 9, 2020","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Comunicado La Secretar\u00eda de Seguridad P\u00fablica de Oaxaca (SSPO), a trav\u00e9s de la Subsecretar\u00eda de Prevenci\u00f3n y Reinserci\u00f3n Social, confirma el deceso de una Persona Privada de la Libertad (PPL) en el Centro Penitenciario Varonil de Tanivet; cuya causa de muerte ser\u00e1 determinada por las autoridades competentes. Se\u2026","rel":"","context":"En &quot;Al Cierre&quot;","block_context":{"text":"Al Cierre","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/al-cierre\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":30758,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2024\/03\/05\/ultima-hora-juez-de-control-del-penal-de-tanivet-vincula-a-proceso-a-diputado-pri-oaxaca-del-congreso-oaxaca-gustavo-diaz-s-por-un-presunto-homicidio-seguira-preso\/","url_meta":{"origin":36795,"position":5},"title":"\u00daLTIMA HORA: Juez de control del Penal de Tanivet, vincula a proceso a diputado PRI Oaxaca del Congreso Oaxaca, Gustavo D\u00edaz S., por un presunto homicidio. Seguir\u00e1 preso","author":"ariadna","date":"marzo 5, 2024","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Y es que, por el presunto delito de homicidio de otra persona, la FISCALIA de Oaxaca, di\u00f3 cumpliment\u00f3 a una nueva orden de aprehensi\u00f3n contra el diputado local del Partido Revolucionario Institucional (PRI), Gustavo D\u00edaz S\u00e1nchez, quien en enero del 2023, recibi\u00f3 una condena de 105 a\u00f1os en\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/36795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/comments?post=36795"}],"version-history":[{"count":1,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/36795\/revisions"}],"predecessor-version":[{"id":36797,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/36795\/revisions\/36797"}],"wp:attachment":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/media?parent=36795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/categories?post=36795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/tags?post=36795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}