{"id":36798,"date":"2025-05-12T21:08:01","date_gmt":"2025-05-13T03:08:01","guid":{"rendered":"https:\/\/redaccionoaxaca.com\/?p=36798"},"modified":"2025-05-12T21:08:01","modified_gmt":"2025-05-13T03:08:01","slug":"para-despresurizar-el-hospital-civil-de-oaxaca-colegio-de-medicos-especialistas-ofrecen-consultas-gratis","status":"publish","type":"post","link":"https:\/\/redaccionoaxaca.com\/index.php\/2025\/05\/12\/para-despresurizar-el-hospital-civil-de-oaxaca-colegio-de-medicos-especialistas-ofrecen-consultas-gratis\/","title":{"rendered":"Para despresurizar el Hospital Civil de Oaxaca, Colegio de M\u00e9dicos Especialistas, ofrecen consultas gratis"},"content":{"rendered":"<p><strong>#Redacci\u00f3nOaxaca<\/strong><\/p>\n<p><strong>#Oaxaca<\/strong><\/p>\n<p><strong>Jaime GUERRERO<\/strong><\/p>\n<p style=\"text-align: justify;\">En medio de las carencias en el sistema de Salud de Oaxaca -ahora a cargo del IMSS Bienestar- que, ha dado paso a casos de mala atenci\u00f3n a pacientes, el Colegio M\u00e9dico de Oaxaca \u201cDr. Aurelio Valdivieso\u201d, ofrece consultas gratuitas y un convenio de colaboraci\u00f3n con el Hospital Civil, para atenci\u00f3n de segundo nivel a la poblaci\u00f3n m\u00e1s vulnerable.<\/p>\n<p style=\"text-align: justify;\">La Presidenta de ese colegio, Ofelia P\u00e9rez Pacheco, asegur\u00f3 que el Colegio M\u00e9dico de Oaxaca cubre todas las especialidades m\u00e9dicas a trav\u00e9s de sus agremiados, por lo que est\u00e1n en di\u00e1logo con el Gobierno del Estado y el Hospital Civil para apoyarlos con las consultas m\u00e9dicas.<\/p>\n<p style=\"text-align: justify;\">No obstante, no hay un acuerdo oficial firmado.<\/p>\n<p style=\"text-align: justify;\">Por lo pronto, P\u00e9rez Pacheco, afirm\u00f3 que la propuesta la han presentado al al Secretario de Salud y al Ayuntamiento de Oaxaca de Ju\u00e1rez.<\/p>\n<p style=\"text-align: justify;\">El objetivo es apoyar a la poblaci\u00f3n ante la situaci\u00f3n de salud p\u00fablica que atraviesa la entidad.<\/p>\n<p style=\"text-align: justify;\">Mientras sean tomados en cuenta, prometi\u00f3 que, realizar\u00e1n diferentes actividades que coadyuven a la mejora y prevenci\u00f3n de enfermedades.<\/p>\n<p style=\"text-align: justify;\">\u201cCon un sector salud deficiente, nosotros como Colegio nos enfocaremos a promover la prevenci\u00f3n de enfermedades, ense\u00f1arles a los padres de familia cu\u00e1les son las banderas rojas y cu\u00e1ndo se requiere del contacto con el primer m\u00e9dico de cabecera. Nuestra prioridad es la prevenci\u00f3n\u201d.<\/p>\n<p style=\"text-align: justify;\">Recalc\u00f3 que, a trav\u00e9s del colegio pueden ofrecer consultas de m\u00e9dicos especialistas como ginec\u00f3logos, cirujanos, dermat\u00f3logos, ultrasonidos, cardi\u00f3logos, pediatr\u00edas, hemat\u00f3logos, entre otras especialidades.<\/p>\n<p style=\"text-align: justify;\">P\u00e9rez Pacheco, destac\u00f3 que est\u00e1n congregados en diferentes colegios y el Colegio M\u00e9dico de Oaxaca a la cabeza, \u201cestamos en la mejor disposici\u00f3n, y le hemos hecho saber a nuestro secretario de salud, lo hemos hecho saber al Hospital Civil que cuenta con nosotros, los conocimientos para poder apoyar en todo lo que nosotros podamos hacer\u201d, expuso.<\/p>\n<p style=\"text-align: justify;\">Por lo pronto, est\u00e1n en el proceso de concretar un convenio para que el colegiado puedan llegar a ofrecer consultas.<\/p>\n<p style=\"text-align: justify;\">P\u00e9rez Pacheco, destac\u00f3 que, el Hospital Civil da atenci\u00f3n a la poblaci\u00f3n m\u00e1s vulnerable, la igual que el hospital regional de especialidad.<\/p>\n<p style=\"text-align: justify;\">Explico que en el caso de hospital de especialidades, ah\u00ed se alberga a los especialistas, \u201centonces es lo \u00fanico que tenemos pues es Hospital Civil y justamente ya no queremos que lleguen pacientes, queremos que la poblaci\u00f3n sana que todas las familias est\u00e9n buscando salud, no tratando la enfermedad, eso es muy importante\u201d.<\/p>\n<p style=\"text-align: justify;\">A juicio de P\u00e9rez Pacheco se tiene que, desahogar la atenci\u00f3n en el Hospital Civil.<\/p>\n<p style=\"text-align: justify;\">Destac\u00f3 que la Federaci\u00f3n nacional de colegios m\u00e9dicos, est\u00e1n haciendo mucho \u00e9nfasis en la prevenci\u00f3n de las enfermedades.<\/p>\n<p style=\"text-align: justify;\">Antes, anunci\u00f3 que el pr\u00f3ximo 19 y 20 de mayo realizar\u00e1n el Congreso de Pediatr\u00eda \u201cCartilla Nacional de Salud\u201c.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO En medio de las carencias en el sistema de Salud de Oaxaca -ahora a cargo del IMSS Bienestar- que, ha dado paso a casos de mala atenci\u00f3n a pacientes, el Colegio M\u00e9dico de Oaxaca \u201cDr. Aurelio Valdivieso\u201d, ofrece consultas gratuitas y un convenio de colaboraci\u00f3n con el Hospital Civil, para atenci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[7,5,3],"tags":[],"class_list":{"0":"post-36798","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-al-cierre","7":"category-imagen","8":"category-mesa-de-redaccion"},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9Ynjw-9zw","jetpack-related-posts":[{"id":7534,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2019\/07\/08\/colegio-de-pediatras-logra-biblioteca-ludica-bilingue-en-la-sierra-mixe-del-estado\/","url_meta":{"origin":36798,"position":0},"title":"Colegio de Pediatras logra biblioteca l\u00fadica biling\u00fce en la Sierra Mixe del Estado","author":"denise","date":"julio 8, 2019","format":"video","excerpt":"A partir de los recursos donados por el Consejo Nacional de Pediatr\u00eda Mexicana (CONAPEME), cuyo registro es en todo el pa\u00eds, pero a partir de gestiones del Colegio de Pediatria en Oaxaca, la construcci\u00f3n de una biblioteca en Los Mixes, en el estado de Oaxaca, es una realidad; la localidad\u2026","rel":"","context":"En &quot;Tendencias&quot;","block_context":{"text":"Tendencias","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/tendencias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1781,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2018\/08\/03\/se-desarrollara-en-oaxaca-xx-congreso-estatal-de-pediatria-el-gremio-reconoce-en-la-capacitacion-el-factor-decisivo-para-evitar-errores-humanos-que-pueden-derivar-en-muerte\/","url_meta":{"origin":36798,"position":1},"title":"Se desarrollar\u00e1 en Oaxaca XX Congreso Estatal de Pediatr\u00eda; el gremio reconoce en la capacitaci\u00f3n el factor decisivo para evitar errores humanos que pueden derivar en muerte","author":"denise","date":"agosto 3, 2018","format":false,"excerpt":"#Redacci\u00f3nOaxaca MairaRic\u00e1rdez En un esfuerzo coordinado, los cerca de 280 miembros del Colegio de Pediatr\u00eda del Estado preparan lo necesario para la realizaci\u00f3n del XX Congreso Estatal del Colegio de Pediatr\u00eda, del 09 al 11 de agosto en el Hotel Fort\u00edn Plaza de esta ciudad, mismo que traer\u00e1 a esta\u2026","rel":"","context":"En &quot;Tendencias&quot;","block_context":{"text":"Tendencias","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/tendencias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":23488,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2022\/01\/17\/en-oaxaca-el-covid-omicron-apenas-esta-incubandose-hay-cientos-de-casos-en-ninos-por-ser-quienes-no-estan-vacunados-alerta-ex-pdte-del-colegio-de-pediatria-del-estado\/","url_meta":{"origin":36798,"position":2},"title":"En Oaxaca el covid omicr\u00f3n apenas est\u00e1 incub\u00e1ndose, hay cientos de casos en ni\u00f1os por ser quienes no est\u00e1n vacunados, alerta ex Pdte. del Colegio de Pediatr\u00eda del Estado.","author":"ariadna","date":"enero 17, 2022","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Maira Ric\u00e1rdez El covid es un fen\u00f3meno pol\u00edtico y social que vino a poner en jaque al mundo y por ende al pa\u00eds, hace un a\u00f1o en estas fechas estaban abarrotados espacios donde vend\u00edan ox\u00edgeno o en su momento tambi\u00e9n, las agencias funerarias; hoy d\u00eda lo que m\u00e1s\u2026","rel":"","context":"En &quot;Imagen&quot;","block_context":{"text":"Imagen","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/imagen\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":12063,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2020\/04\/28\/pediatras-y-medicos-del-estado-son-llamados-a-integrar-un-archivo-de-cuentos-y-narraciones-que-muestre-el-acompanamiento-a-la-mente-y-alma-de-ninos-en-tiempos-de-covid19\/","url_meta":{"origin":36798,"position":3},"title":"Pediatras y m\u00e9dicos del Estado son llamados a integrar un archivo de cuentos y narraciones que muestre el acompa\u00f1amiento a la mente y alma de ni\u00f1os en tiempos de COVID19.","author":"ariadna","date":"abril 28, 2020","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Maira Ric\u00e1rdez La Confederaci\u00f3n Nacional de Pediatr\u00eda de M\u00e9xico (Conapeme) Cap\u00edtulo Oaxaca convoc\u00f3 a los m\u00e9dicos Oaxaque\u00f1os con enfoque a la atenci\u00f3n en ni\u00f1os, pero con apertura a recibir material de m\u00e9dicos generales y otras especialidades -al tener todos alguna vez contacto con ni\u00f1os y ni\u00f1as-, a participar\u2026","rel":"","context":"En &quot;Mesa de Redacci\u00f3n&quot;","block_context":{"text":"Mesa de Redacci\u00f3n","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/mesa-de-redaccion\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":36694,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2025\/05\/02\/tragedia-en-colegio-francoise-dolto-ocho-ninos-sufren-quemaduras-de-segundo-grado\/","url_meta":{"origin":36798,"position":4},"title":"Tragedia en Colegio Francoise Dolto: ocho ni\u00f1os sufren quemaduras de segundo grado","author":"ariadna","date":"mayo 2, 2025","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO La celebraci\u00f3n del D\u00eda del Ni\u00f1o en el Colegio Francoise Dolto, termin\u00f3 en tragedia la noche del pasado martes 29 de abril, luego de que una fogata mal manejada durante un campamento provocara una explosi\u00f3n de fuego que dej\u00f3 a varios menores y a un directivo\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":36730,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2025\/05\/06\/realiza-ieepo-suspension-del-colegio-francoise-dolto-brinda-apoyo-a-madres-y-padres-de-familia\/","url_meta":{"origin":36798,"position":5},"title":"Realiza IEEPO suspensi\u00f3n del Colegio Francoise Dolto; brinda apoyo a madres y padres de familia","author":"ariadna","date":"mayo 6, 2025","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca \u2022\u00a0 Se expedir\u00e1 la documentaci\u00f3n oficial necesaria, incluyendo boletas, constancias y certificados, para que el alumnado pueda ingresar a otros planteles Oaxaca de Ju\u00e1rez, Oax. 6 de mayo de 2025.- Como parte de las acciones para salvaguardar los derechos y el bienestar de escolares, el Instituto Estatal de\u2026","rel":"","context":"En &quot;Imagen&quot;","block_context":{"text":"Imagen","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/imagen\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/36798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/comments?post=36798"}],"version-history":[{"count":1,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/36798\/revisions"}],"predecessor-version":[{"id":36800,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/36798\/revisions\/36800"}],"wp:attachment":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/media?parent=36798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/categories?post=36798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/tags?post=36798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}