{"id":37044,"date":"2025-05-27T21:49:35","date_gmt":"2025-05-28T03:49:35","guid":{"rendered":"https:\/\/redaccionoaxaca.com\/?p=37044"},"modified":"2025-05-27T21:49:35","modified_gmt":"2025-05-28T03:49:35","slug":"presidente-del-congreso-de-oaxaca-llaman-a-utilizar-material-de-apoyo-en-eleccion-judicial-y-piden-a-magisterio-permitir-jornada-electoral","status":"publish","type":"post","link":"https:\/\/redaccionoaxaca.com\/index.php\/2025\/05\/27\/presidente-del-congreso-de-oaxaca-llaman-a-utilizar-material-de-apoyo-en-eleccion-judicial-y-piden-a-magisterio-permitir-jornada-electoral\/","title":{"rendered":"Presidente del Congreso de Oaxaca llaman a utilizar material de apoyo en elecci\u00f3n judicial y piden a magisterio permitir jornada electoral"},"content":{"rendered":"<p><strong>#Redacci\u00f3nOaxaca<\/strong><\/p>\n<p><strong>#Oaxaca<\/strong><\/p>\n<p><strong>Jaime GUERRERO<\/strong><\/p>\n<p style=\"text-align: justify;\">El Presidente de la Junta de Coordinaci\u00f3n Pol\u00edtica (JUCOPO) de la LXVI Legislatura de Oaxaca, Benjam\u00edn Viveros Montalvo, recomend\u00f3 a la ciudadan\u00eda \u201cllevar material de apoyo\u201d con los nombres de las y los candidatos por los que votar\u00edan en la Elecci\u00f3n Judicial del pr\u00f3ximo 1 de junio.<\/p>\n<p style=\"text-align: justify;\">En tanto, el coordinador de la bancada de Morena, pidi\u00f3 al Magisterio, permitir la celebraci\u00f3n de los comicios extraordinarios, en los que se habr\u00e1 de elegir jueces, magistrados y ministros de la Suprema Corte de Justicia de la Naci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">De acuerdo a Viveros Montalvo, existe el \u00e1nimo por parte de los ciudadanos para salir a votar este 1 de junio.<\/p>\n<p style=\"text-align: justify;\">Aun cuando los aval\u00f3, neg\u00f3 que los materiales de apoyo -acordeones-, se utilicen para inducir el sufragio a favor de candidatas y candidatos.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, asegur\u00f3 que tras el recorrido que realizaron sus pares para promover la votaci\u00f3n, las y los oaxaque\u00f1os tienen el \u00e1nimo de participar; sin embargo lament\u00f3 que el INE no haya informado sobre el tema.<\/p>\n<p style=\"text-align: justify;\">\u201cAntes de esta reforma los ciudadanos no votaban directamente para la renovaci\u00f3n del Poder Judicial, la elecci\u00f3n del voto directo fortalece la democracia y el sistema de justicia\u201d, expuso el Viveros Montalvo quien reiter\u00f3 su llamado al magisterio para permitir la realizaci\u00f3n de esta actividad.<\/p>\n<p style=\"text-align: justify;\">El diputado pidi\u00f3 que las y los ciudadanos salgan a votar apoyados de material de apoyo -acordeones- \u201cen los tel\u00e9fonos celulares, en una libreta, una hoja que les permita acompa\u00f1arse de ello en las urnas el pr\u00f3ximo 1 de junio.<\/p>\n<p style=\"text-align: justify;\">\u201cVamos a guardarlo y repasar nuestro material de apoyo para que el d\u00eda de la jornada podamos entrar a las urnas y votar, esto est\u00e1 aprobado por el INE\u201d, dijo.<\/p>\n<p style=\"text-align: justify;\">De acuerdo a Viveros Montalvo, pa jornada electoral del 1 de junio tiene como centro la elecci\u00f3n de nuevos integrantes del Poder Judicial de la Federaci\u00f3n, gracias a la reforma constitucional impulsada por la Cuarta Transformaci\u00f3n que establece la elecci\u00f3n popular para jueces, magistrados y ministros de la Suprema Corte de Justicia de la Naci\u00f3n; un hecho qu\u00e9 calific\u00f3 como hist\u00f3rico en M\u00e9xico.<\/p>\n<p style=\"text-align: justify;\">Argument\u00f3 que el pueblo no votaba directamente por los miembros del Poder Judicial.<\/p>\n<p style=\"text-align: justify;\">\u201cLa elecci\u00f3n a trav\u00e9s del voto directo fortalece la democracia y el sistema de justicia por las siguientes razones:<br \/>\n-Impacto directo en la justicia: Las y los jueces, magistrados y ministros toman decisiones que impactan la vida de los ciudadanos en \u00e1reas como seguridad, derechos humanos, econom\u00eda y sociedad. Participar en su elecci\u00f3n permite influir en la forma en que se imparte justicia\u201d, expuso:<\/p>\n<p style=\"text-align: justify;\">Destac\u00f3 que habr\u00e1 el Fortalecimiento de la democracia y la rendici\u00f3n de cuentas; Combate a la corrupci\u00f3n y la impunidad; Garant\u00eda de derechos y libertades; Legitimidad de las instituciones.<\/p>\n<p style=\"text-align: justify;\">A juicio de Viveros Montalvo, los conservadores buscan desinformar al pueblo queriendo preservar sus privilegios,<\/p>\n<p style=\"text-align: justify;\">As\u00ed, a cinco d\u00edas de la jornada electoral, explic\u00f3 que como primer paso es importante conocer la ubicaci\u00f3n de las casillas de votaci\u00f3n en el micrositio del Instituto Nacional electoral.<\/p>\n<p style=\"text-align: justify;\">Record\u00f3 que la ciudadan\u00eda recibir\u00e1n 6 boletas de distintos colores, cada una correspondiente a un cargo espec\u00edfico dentro del Poder Judicialcomo:<\/p>\n<p style=\"text-align: justify;\">Ministras y ministros de la Suprema Corte de Justicia de la Naci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Magistraturas del Tribunal de Disciplina Judicial.<\/p>\n<p style=\"text-align: justify;\">Magistraturas de la Sala Superior del Tribunal Electoral.<\/p>\n<p style=\"text-align: justify;\">Magistraturas de las Salas Regionales.<\/p>\n<p style=\"text-align: justify;\">Magistradas y magistrados de circuito. Juezas y jueces de distrito.<\/p>\n<p style=\"text-align: justify;\">En cada boleta, las y los candidatos estar\u00e1n organizados en dos columnasMujeres a la izquierda y Hombres a la derecha.<\/p>\n<p style=\"text-align: justify;\">Cada candidato tiene un n\u00famero de identificaci\u00f3n que los distingue. Para votar, se escribe el n\u00famero de las o los candidatos de su elecci\u00f3n en los espacios designados para posteriormente colocar las seis boletas en la urna.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO El Presidente de la Junta de Coordinaci\u00f3n Pol\u00edtica (JUCOPO) de la LXVI Legislatura de Oaxaca, Benjam\u00edn Viveros Montalvo, recomend\u00f3 a la ciudadan\u00eda \u201cllevar material de apoyo\u201d con los nombres de las y los candidatos por los que votar\u00edan en la Elecci\u00f3n Judicial del pr\u00f3ximo 1 de junio. En tanto, el coordinador [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4,7,6],"tags":[],"class_list":{"0":"post-37044","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-agenda-politica","7":"category-al-cierre","8":"category-tendencias"},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9Ynjw-9Du","jetpack-related-posts":[{"id":37447,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2025\/07\/15\/oaxaca-renovara-poder-judicial-legislativo-y-concejalias-en-152-municipios-de-partidos-politicos\/","url_meta":{"origin":37044,"position":0},"title":"Oaxaca renovar\u00e1 Poder Judicial, Legislativo y concejal\u00edas en 152 municipios de Partidos Pol\u00edticos","author":"ariadna","date":"julio 15, 2025","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO El Presidente de la Junta de Coordinaci\u00f3n Pol\u00edtica del Congreso del Estado, Benjam\u00edn Viveros Montalvo, confirm\u00f3 que en 2027, empatar\u00e1n elecciones de jueces y magistraturas del Tribunal Superior de Justicia con la elecci\u00f3n de concejal\u00edas en 153 municipios de las v\u00eda de partidos pol\u00edticos, diputaciones locales\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":25728,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2022\/05\/23\/video-morena-pide-a-uif-investigar-a-chedraui-por-entrega-de-tarjetas-con-500-pesos-que-hace-el-pri-en-oaxaca-anuncian-brigada-cazamapaches\/","url_meta":{"origin":37044,"position":1},"title":"VIDEO: Morena pide a UIF investigar a Chedraui por entrega de tarjetas con 500 pesos que hace el PRI en Oaxaca; anuncian brigada \u201ccazamapaches\u201d","author":"ariadna","date":"mayo 23, 2022","format":"video","excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO La representaci\u00f3n de Morena ante el Instituto Estatal Electoral y de Participaci\u00f3n Ciudadana de Oaxaca (#IEEPCO) y el equipo de campa\u00f1a del candidato a gobernador de ese partido, Salom\u00f3n Jara Cruz, pidi\u00f3 la intervenci\u00f3n de la Unidad de Inteligencia Financiera (#UIF) de la Secretar\u00eda de Hacienda,\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":36341,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2025\/04\/01\/congreso-urge-a-ine-maxima-publicidad-de-eleccion-judicial-y-candidaturas-oaxaquenas\/","url_meta":{"origin":37044,"position":2},"title":"Congreso urge a INE m\u00e1xima publicidad de elecci\u00f3n judicial y candidaturas oaxaque\u00f1as","author":"ariadna","date":"abril 1, 2025","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO Con 30 votos a favor, el pleno del Congreso exhort\u00f3 al Instituto Nacional Electoral (INE) para que realice la m\u00e1xima difusi\u00f3n para que la ciudadan\u00eda conozca la lista de cargos del Poder Judicial de la Federaci\u00f3n que se someten a elecciones en #Oaxaca. A propuesta del\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":35839,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2025\/02\/25\/va-reforma-judicial-de-oaxaca-1-de-junio-solo-se-elegiran-organo-de-disciplina-y-administrativo-jueces-y-magistraturas-del-tsje-en-2027\/","url_meta":{"origin":37044,"position":3},"title":"Va reforma judicial de Oaxaca; 1 de junio solo se elegir\u00e1n \u00d3rgano de Disciplina y Administrativo; jueces y magistraturas del TSJE en 2027","author":"ariadna","date":"febrero 25, 2025","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO Este mi\u00e9rcoles, el Congreso del Estado, aprobar\u00e1 la Reforma al Poder Judicial de Oaxaca, para elegir -el pr\u00f3ximo 1 de junio-, solamente a los integrantes del \u00d3rgano de Disciplina Judicial y el \u00d3rgano Administrativo. En tanto, la elecci\u00f3n de nuevas magistraturas y jueces locales pertenecientes al\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":25075,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2022\/04\/18\/rechazo-a-la-reforma-electrica-ultima-traicion-del-pri-pan-prd-y-mc-benjamin-viveros\/","url_meta":{"origin":37044,"position":4},"title":"Rechazo a la reforma el\u00e9ctrica, \u00faltima traici\u00f3n del PRI, PAN, PRD y MC: Benjam\u00edn Viveros.","author":"ariadna","date":"abril 18, 2022","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO Con su rechazo a la reforma el\u00e9ctrica impulsada por el presidente Andr\u00e9s Manuel L\u00f3pez Obrador y Morena, el PAN, PRI, PRD, MC, han negado a las y los mexicanos su derecho a recuperar la soberan\u00eda sobre nuestros recursos, acus\u00f3 Benjam\u00edn Viveros Montalvo, presidente del Comit\u00e9 Ejecutivo\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":25106,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2022\/04\/20\/rechazo-a-la-reforma-electrica-ultima-traicion-del-pri-pan-prd-y-mc-benjamin-viveros-2\/","url_meta":{"origin":37044,"position":5},"title":"Rechazo a la reforma el\u00e9ctrica, \u00faltima traici\u00f3n del PRI, PAN, PRD y MC: Benjam\u00edn Viveros.","author":"ariadna","date":"abril 20, 2022","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO Con su rechazo a la reforma el\u00e9ctrica impulsada por el presidente Andr\u00e9s Manuel L\u00f3pez Obrador y Morena, el PAN, PRI, PRD, MC, han negado a las y los mexicanos su derecho a recuperar la soberan\u00eda sobre nuestros recursos, acus\u00f3 Benjam\u00edn Viveros Montalvo, presidente del Comit\u00e9 Ejecutivo\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/37044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/comments?post=37044"}],"version-history":[{"count":1,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/37044\/revisions"}],"predecessor-version":[{"id":37046,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/37044\/revisions\/37046"}],"wp:attachment":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/media?parent=37044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/categories?post=37044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/tags?post=37044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}