{"id":41541,"date":"2026-04-14T20:23:47","date_gmt":"2026-04-15T02:23:47","guid":{"rendered":"https:\/\/redaccionoaxaca.com\/?p=41541"},"modified":"2026-04-14T20:23:47","modified_gmt":"2026-04-15T02:23:47","slug":"congreso-de-oaxaca-elige-a-integrantes-de-la-diputacion-permanente-presidira-diputado-de-morena","status":"publish","type":"post","link":"https:\/\/redaccionoaxaca.com\/index.php\/2026\/04\/14\/congreso-de-oaxaca-elige-a-integrantes-de-la-diputacion-permanente-presidira-diputado-de-morena\/","title":{"rendered":"Congreso de Oaxaca elige a integrantes de la Diputaci\u00f3n Permanente; presidir\u00e1 diputado de Morena"},"content":{"rendered":"<p><strong>#Redacci\u00f3nOaxaca<\/strong><\/p>\n<p><strong>#Oaxaca<\/strong><\/p>\n<p><strong>#JaimeGUERRERO<\/strong><\/p>\n<p style=\"text-align: justify;\">Con 34 votos a favor, el Congreso del Estado design\u00f3 este martes al diputado Iv\u00e1n Osael Quiroz Mart\u00ednez como presidente de la Diputaci\u00f3n Permanente, \u00f3rgano que mantendr\u00e1 la actividad parlamentaria durante el receso legislativo.<\/p>\n<p style=\"text-align: justify;\">Con el objetivo de garantizar la continuidad de las labores parlamentarias, se llev\u00f3 a cabo la elecci\u00f3n de los integrantes de la Diputaci\u00f3n Permanente, quienes sesionar\u00e1n durante el Primer Periodo de Receso del Segundo A\u00f1o de Ejercicio Legal de la LXVI Legislatura del Congreso del Estado.<\/p>\n<p style=\"text-align: justify;\">Junto a Quiroz Mart\u00ednez fue electa como vicepresidenta la legisladora Sandra Daniela Taurino Jim\u00e9nez, ambos del Grupo Parlamentario de Morena.<\/p>\n<p style=\"text-align: justify;\">Tambi\u00e9n se designaron como secretarias a las diputadas Biaani Palomec Enr\u00edquez, del Grupo Parlamentario del Partido del Trabajo, as\u00ed como las legisladoras Jimena Yamil Arroyo Ju\u00e1rez y Mar\u00eda Francisca Antonio Santiago, ambas del Grupo Parlamentario de Morena.<\/p>\n<p style=\"text-align: justify;\">De igual forma, fueron elegidas las legisladoras Hayde\u00e9 Irma Reyes Soto y Monserat Herrera Ruiz, de Morena, quienes fungir\u00e1n como primera y segunda suplente, respectivamente.<\/p>\n<p style=\"text-align: justify;\">Este procedimiento parlamentario se fundamenta en lo establecido por el art\u00edculo 9 de la Ley Org\u00e1nica del Poder Legislativo de Oaxaca, marco normativo que regula los tiempos de actividad del Congreso.<\/p>\n<p style=\"text-align: justify;\">La ley mandata que la soberan\u00eda estatal debe cumplir con dos periodos ordinarios de sesiones anualmente, el primero comprendido del 15 de noviembre al 15 de abril, y el segundo con fecha de inicio el 1 de julio para concluir el 30 de septiembre.<\/p>\n<p style=\"text-align: justify;\">La Diputaci\u00f3n Permanente asegura que el Congreso del Estado contin\u00fae con los asuntos institucionales y se mantenga la representaci\u00f3n del Poder Legislativo durante el periodo de receso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>#Redacci\u00f3nOaxaca #Oaxaca #JaimeGUERRERO Con 34 votos a favor, el Congreso del Estado design\u00f3 este martes al diputado Iv\u00e1n Osael Quiroz Mart\u00ednez como presidente de la Diputaci\u00f3n Permanente, \u00f3rgano que mantendr\u00e1 la actividad parlamentaria durante el receso legislativo. Con el objetivo de garantizar la continuidad de las labores parlamentarias, se llev\u00f3 a cabo la elecci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":41542,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4,5,6],"tags":[],"class_list":{"0":"post-41541","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-agenda-politica","8":"category-imagen","9":"category-tendencias"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/04\/1-21.jpg?fit=1000%2C600&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9Ynjw-aO1","jetpack-related-posts":[{"id":21317,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2021\/09\/30\/instala-congreso-diputacion-permanente-del-segundo-periodo-de-receso\/","url_meta":{"origin":41541,"position":0},"title":"Instala Congreso Diputaci\u00f3n Permanente del Segundo Periodo de Receso","author":"ariadna","date":"septiembre 30, 2021","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Comunicado San Raymundo Jalpan Oax, 30 de septiembre de 2021.- La LXIV Legislatura del Congreso del Estado de Oaxaca instal\u00f3 la Diputaci\u00f3n Permanente que fungir\u00e1 durante al Segundo Receso del Tercer A\u00f1o de Ejercicio Legal. El \u00f3rgano deliberativo ser\u00e1 presidido por el diputado Mauro Cruz S\u00e1nchez, del Grupo\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":38584,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2025\/10\/07\/realiza-la-diputacion-permanente-del-congreso-de-oaxaca-su-primera-sesion-ordinaria-en-el-segundo-periodo-de-receso-de-la-lxvi-legislatura\/","url_meta":{"origin":41541,"position":1},"title":"Realiza la Diputaci\u00f3n Permanente del Congreso de Oaxaca su primera Sesi\u00f3n Ordinaria en el Segundo Periodo de Receso de la LXVI Legislatura","author":"ariadna","date":"octubre 7, 2025","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca * Se present\u00f3 una Iniciativa de Reforma de Ley y una propuesta de exhorto San Raymundo Jalpan, Oax., a 07 de octubre de 2025.- La Diputaci\u00f3n Permanente del Congreso del Estado encabezada por su presidente, el diputado Juan Marcelino S\u00e1nchez Valdivieso, realiz\u00f3 su primera Sesi\u00f3n Ordinaria en el\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/10\/Screenshot_20251007_191529_Facebook-300x189.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":39136,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2025\/11\/15\/clausura-diputacion-permanente-trabajos-legislativos\/","url_meta":{"origin":41541,"position":2},"title":"Clausura diputaci\u00f3n permanente trabajos legislativos","author":"ariadna","date":"noviembre 15, 2025","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO Este viernes, la Diputaci\u00f3n Permanente de la LXVI Legislatura del Congreso del Estado de Oaxaca declar\u00f3 formalmente clausurados los trabajos del segundo receso del primer a\u00f1o de ejercicio legal, en una sesi\u00f3n presidida por el diputado Juan Marcelino S\u00e1nchez Valdivieso. En el acto de clausura, S\u00e1nchez\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/11\/Clausura-diputados-scaled-1.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/11\/Clausura-diputados-scaled-1.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/11\/Clausura-diputados-scaled-1.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/11\/Clausura-diputados-scaled-1.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/11\/Clausura-diputados-scaled-1.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":33589,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2024\/09\/27\/eligen-a-integrantes-de-la-diputacion-permanente\/","url_meta":{"origin":41541,"position":3},"title":"Eligen a integrantes de la Diputaci\u00f3n Permanente","author":"ariadna","date":"septiembre 27, 2024","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca \u2022 Ser\u00e1 presidida por el legislador Sesul Bola\u00f1os L\u00f3pez. San Raymundo Jalpan, Oax. 26 de septiembre de 2024.- En sesi\u00f3n ordinaria, el Pleno de la LXV Legislatura local eligi\u00f3 a las diputadas y los diputados integrantes de la Diputaci\u00f3n Permanente para el segundo receso del tercer a\u00f1o de\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":38491,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2025\/10\/01\/tras-una-maratonica-sesion-clausuran-segundo-periodo-ordinario-e-instalacion-de-la-diputacion-permanente-en-congreso-de-oaxaca\/","url_meta":{"origin":41541,"position":4},"title":"Tras una marat\u00f3nica sesi\u00f3n, clausuran Segundo Periodo Ordinario e Instalaci\u00f3n de la Diputaci\u00f3n Permanente en Congreso de Oaxaca","author":"ariadna","date":"octubre 1, 2025","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO Con fundamento en los art\u00edculos 9 y 10 de la Ley Org\u00e1nica del Poder Legislativo, el Congreso del Estado de Oaxaca llev\u00f3 a cabo, este 30 de septiembre de 2025, la clausura del Segundo Periodo Ordinario de Sesiones correspondiente al Primer A\u00f1o de Ejercicio Constitucional de\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":41679,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2026\/04\/21\/diputado-ivan-quiroz-destaca-atencion-a-las-causas-como-eje-de-la-estrategia-de-seguridad-en-oaxaca\/","url_meta":{"origin":41541,"position":5},"title":"Diputado Iv\u00e1n Quiroz destaca atenci\u00f3n a las causas como eje de la estrategia de seguridad en Oaxaca","author":"ariadna","date":"abril 21, 2026","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca * Se\u00f1al\u00f3 que el Gobierno del Estado impulsa programas sociales, deporte y recuperaci\u00f3n de espacios p\u00fablicos para prevenir conductas delictivas San Raymundo Jalpan, Oax., a 21 de abril de 2026.- El presidente de la Diputaci\u00f3n Permanente, diputado Iv\u00e1n Osael Quiroz Mart\u00ednez, afirm\u00f3 que la estrategia de seguridad en\u2026","rel":"","context":"En &quot;Imagen&quot;","block_context":{"text":"Imagen","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/imagen\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/04\/Screenshot_20260421_175850_Facebook-scaled.jpg?fit=1200%2C700&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/04\/Screenshot_20260421_175850_Facebook-scaled.jpg?fit=1200%2C700&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/04\/Screenshot_20260421_175850_Facebook-scaled.jpg?fit=1200%2C700&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/04\/Screenshot_20260421_175850_Facebook-scaled.jpg?fit=1200%2C700&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/04\/Screenshot_20260421_175850_Facebook-scaled.jpg?fit=1200%2C700&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/41541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/comments?post=41541"}],"version-history":[{"count":1,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/41541\/revisions"}],"predecessor-version":[{"id":41543,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/41541\/revisions\/41543"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/media\/41542"}],"wp:attachment":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/media?parent=41541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/categories?post=41541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/tags?post=41541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}