{"id":41990,"date":"2026-05-09T11:44:58","date_gmt":"2026-05-09T17:44:58","guid":{"rendered":"https:\/\/redaccionoaxaca.com\/?p=41990"},"modified":"2026-05-09T11:44:58","modified_gmt":"2026-05-09T17:44:58","slug":"directores-de-la-uabjo-rechazan-desinformacion-y-ataques-en-la-contienda-por-la-rectoria-respaldan-a-farid-acevedo-lopez","status":"publish","type":"post","link":"https:\/\/redaccionoaxaca.com\/index.php\/2026\/05\/09\/directores-de-la-uabjo-rechazan-desinformacion-y-ataques-en-la-contienda-por-la-rectoria-respaldan-a-farid-acevedo-lopez\/","title":{"rendered":"Directores de la UABJO rechazan desinformaci\u00f3n y ataques en la contienda por la Rector\u00eda; respaldan a Farid Acevedo L\u00f3pez"},"content":{"rendered":"<p><strong>#Redacci\u00f3nOaxaca<\/strong><\/p>\n<p><strong>#Oaxaca<\/strong><\/p>\n<p><strong>#JaimeGUERRERO<\/strong><\/p>\n<p style=\"text-align: justify;\">Las directoras y directores de escuelas, facultades e institutos de la Universidad Aut\u00f3noma &#8220;Benito Ju\u00e1rez&#8221; de Oaxaca (UABJO) exigieron que el proceso de renovaci\u00f3n de la Rector\u00eda 2026\u20132030 se conduzca con responsabilidad, respeto y apego a la legalidad, y rechazaron cualquier intento de desinformaci\u00f3n, ataques personales o pr\u00e1cticas que vulneren la vida institucional.<\/p>\n<p style=\"text-align: justify;\">En el mismo pronunciamiento, expresaron su respaldo al Mtro. Farid Acevedo L\u00f3pez como candidato a la Rector\u00eda.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"41991\" data-permalink=\"https:\/\/redaccionoaxaca.com\/index.php\/2026\/05\/09\/directores-de-la-uabjo-rechazan-desinformacion-y-ataques-en-la-contienda-por-la-rectoria-respaldan-a-farid-acevedo-lopez\/img-20260509-wa0003\/\" data-orig-file=\"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/IMG-20260509-WA0003.jpg?fit=1280%2C854&amp;ssl=1\" data-orig-size=\"1280,854\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG-20260509-WA0003\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/IMG-20260509-WA0003.jpg?fit=696%2C464&amp;ssl=1\" class=\"size-medium wp-image-41991 aligncenter\" src=\"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/IMG-20260509-WA0003.jpg?resize=300%2C200&#038;ssl=1\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/IMG-20260509-WA0003.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/IMG-20260509-WA0003.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/IMG-20260509-WA0003.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/IMG-20260509-WA0003.jpg?resize=630%2C420&amp;ssl=1 630w, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/IMG-20260509-WA0003.jpg?resize=696%2C464&amp;ssl=1 696w, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/IMG-20260509-WA0003.jpg?resize=1068%2C713&amp;ssl=1 1068w, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/IMG-20260509-WA0003.jpg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: justify;\">En un pronunciamiento conjunto, las y los titulares de las unidades acad\u00e9micas se\u00f1alaron que su apoyo se sustenta en la confianza en un proyecto universitario s\u00f3lido, con visi\u00f3n acad\u00e9mica, capacidad de conducci\u00f3n y compromiso institucional, al tiempo que reconocieron en Acevedo L\u00f3pez el perfil id\u00f3neo para encabezar una nueva etapa de fortalecimiento y consolidaci\u00f3n de la UABJO.<\/p>\n<p style=\"text-align: justify;\">El posicionamiento destaca que la propuesta del Mtro. Farid Acevedo L\u00f3pez se ha distinguido por privilegiar la civilidad, el di\u00e1logo y la construcci\u00f3n de acuerdos, elementos que, a juicio de las y los directores, resultan indispensables para garantizar la gobernabilidad y la estabilidad universitaria.<\/p>\n<p style=\"text-align: justify;\">Las y los firmantes hicieron tambi\u00e9n un llamado a que el proceso de renovaci\u00f3n de la Rector\u00eda se conduzca con responsabilidad, respeto y apego a la legalidad, y expresaron su rechazo a cualquier intento de desinformaci\u00f3n, ataques personales o pr\u00e1cticas que vulneren la vida institucional de la Universidad.<\/p>\n<p style=\"text-align: justify;\">En el mismo texto, las directoras y directores vincularon su respaldo a la candidatura con el compromiso de avanzar en una agenda universitaria centrada en la unidad, la inclusi\u00f3n, la transparencia y la mejora continua de los procesos acad\u00e9micos y administrativos.<\/p>\n<p style=\"text-align: justify;\">Asimismo, reafirmaron su compromiso con la construcci\u00f3n de espacios universitarios libres de violencia, con especial \u00e9nfasis en la erradicaci\u00f3n de la violencia de g\u00e9nero, como parte de una visi\u00f3n de universidad m\u00e1s justa y equitativa.<\/p>\n<p style=\"text-align: justify;\">Al cierre del pronunciamiento, las y los directores reiteraron su decisi\u00f3n de acompa\u00f1ar el proyecto de Acevedo L\u00f3pez hacia la Rector\u00eda, al considerar que representa una oportunidad real para consolidar una gesti\u00f3n con visi\u00f3n de futuro, fortalecimiento de la autonom\u00eda universitaria y compromiso con el desarrollo integral de la comunidad acad\u00e9mica.<\/p>\n<p style=\"text-align: justify;\">La elecci\u00f3n de la Rector\u00eda de la UABJO est\u00e1 programada para el pr\u00f3ximo mi\u00e9rcoles 13 de mayo.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"41992\" data-permalink=\"https:\/\/redaccionoaxaca.com\/index.php\/2026\/05\/09\/directores-de-la-uabjo-rechazan-desinformacion-y-ataques-en-la-contienda-por-la-rectoria-respaldan-a-farid-acevedo-lopez\/img-20260509-wa0004\/\" data-orig-file=\"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/IMG-20260509-WA0004.jpg?fit=1280%2C646&amp;ssl=1\" data-orig-size=\"1280,646\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG-20260509-WA0004\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/IMG-20260509-WA0004.jpg?fit=696%2C351&amp;ssl=1\" class=\"size-medium wp-image-41992 aligncenter\" src=\"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/IMG-20260509-WA0004.jpg?resize=300%2C151&#038;ssl=1\" alt=\"\" width=\"300\" height=\"151\" srcset=\"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/IMG-20260509-WA0004.jpg?resize=300%2C151&amp;ssl=1 300w, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/IMG-20260509-WA0004.jpg?resize=1024%2C517&amp;ssl=1 1024w, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/IMG-20260509-WA0004.jpg?resize=768%2C388&amp;ssl=1 768w, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/IMG-20260509-WA0004.jpg?resize=832%2C420&amp;ssl=1 832w, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/IMG-20260509-WA0004.jpg?resize=696%2C351&amp;ssl=1 696w, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/IMG-20260509-WA0004.jpg?resize=1068%2C539&amp;ssl=1 1068w, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/IMG-20260509-WA0004.jpg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>#Redacci\u00f3nOaxaca #Oaxaca #JaimeGUERRERO Las directoras y directores de escuelas, facultades e institutos de la Universidad Aut\u00f3noma &#8220;Benito Ju\u00e1rez&#8221; de Oaxaca (UABJO) exigieron que el proceso de renovaci\u00f3n de la Rector\u00eda 2026\u20132030 se conduzca con responsabilidad, respeto y apego a la legalidad, y rechazaron cualquier intento de desinformaci\u00f3n, ataques personales o pr\u00e1cticas que vulneren la vida [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":41991,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4,3,6],"tags":[],"class_list":{"0":"post-41990","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-agenda-politica","8":"category-mesa-de-redaccion","9":"category-tendencias"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/IMG-20260509-WA0003.jpg?fit=1280%2C854&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9Ynjw-aVg","jetpack-related-posts":[{"id":41933,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2026\/05\/07\/directores-de-escuelas-y-facultades-de-la-uabjo-respaldan-a-farid-acevedo-y-rechazan-campanas-de-desprestigio\/","url_meta":{"origin":41990,"position":0},"title":"Directores de escuelas y facultades de la #UABJO respaldan a Farid Acevedo y rechazan campa\u00f1as de desprestigio","author":"ariadna","date":"mayo 7, 2026","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca #JaimeGUERRERO M\u00e1s de veinte titulares de unidades acad\u00e9micas de la Universidad Aut\u00f3noma \"Benito Ju\u00e1rez\" de Oaxaca (UABJO) rechazaron las campa\u00f1as de desprestigio, desinformaci\u00f3n y ataques personales que se han registrado durante el proceso de renovaci\u00f3n de la rector\u00eda, y ratificaron su respaldo al Maestro Farid Acevedo L\u00f3pez como\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/images-40.jpeg?fit=678%2C452&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/images-40.jpeg?fit=678%2C452&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/images-40.jpeg?fit=678%2C452&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":41880,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2026\/05\/05\/farid-acevedo-respalda-a-directora-de-medicina-ante-insulto-misogino-de-enrique-martinez-en-campana-por-rectoria-de-la-uabjo\/","url_meta":{"origin":41990,"position":1},"title":"Farid Acevedo respalda a directora de Medicina ante insulto mis\u00f3gino de Enrique Mart\u00ednez en campa\u00f1a por rector\u00eda de la UABJO","author":"ariadna","date":"mayo 5, 2026","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca #JaimeGUERRERO El candidato a rector Farid Acevedo L\u00f3pez expres\u00f3 su respaldo a la doctora Gema Hern\u00e1ndez Bernardino, directora de la Facultad de Medicina y Cirug\u00eda de la Universidad Aut\u00f3noma Benito Ju\u00e1rez de Oaxaca (UABJO), luego de que el tambi\u00e9n aspirante Enrique Antonio Mart\u00ednez Mart\u00ednez la llamara \"maquillista\" de\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/images-37.jpeg?fit=554%2C554&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/images-37.jpeg?fit=554%2C554&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/images-37.jpeg?fit=554%2C554&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":41492,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2026\/04\/13\/universitarios-con-ligas-al-pt-exigen-a-ejecutivo-sacar-las-manos-de-la-uabjo-acusan-imposicion-de-candidato-a-rectoria\/","url_meta":{"origin":41990,"position":2},"title":"Universitarios con ligas al PT, exigen a Ejecutivo sacar las manos de la UABJO; acusan imposici\u00f3n de candidato a rector\u00eda","author":"ariadna","date":"abril 13, 2026","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca #JaimeGUERRERO Un frente de la comunidad universitaria de la Universidad Aut\u00f3noma \u201cBenito Ju\u00e1rez\u201d de Oaxaca (UABJO), encabezado por el aspirante a la rector\u00eda Enrique Mart\u00ednez \u2014ligado al Partido del Trabajo y con antecedentes como candidato a cargos de elecci\u00f3n popular por ese instituto pol\u00edtico\u2014, hizo p\u00fablico este lunes\u2026","rel":"","context":"En &quot;Imagen&quot;","block_context":{"text":"Imagen","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/imagen\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/04\/11-8-scaled.jpg?fit=1200%2C691&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/04\/11-8-scaled.jpg?fit=1200%2C691&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/04\/11-8-scaled.jpg?fit=1200%2C691&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/04\/11-8-scaled.jpg?fit=1200%2C691&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/04\/11-8-scaled.jpg?fit=1200%2C691&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":41268,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2026\/04\/01\/con-etiqueta-hechoenuabjo-farid-acevedo-lopez-se-destapa-oficialmente-para-la-rectoria\/","url_meta":{"origin":41990,"position":3},"title":"Con etiqueta \u201c#HechoEnUABJO\u201d, Farid Acevedo L\u00f3pez se destapa oficialmente para la rector\u00eda","author":"ariadna","date":"abril 1, 2026","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca #JaimeGUERRERO Tres semanas despu\u00e9s de haber renunciado a la Secretar\u00eda de Finanzas del gobierno de Oaxaca, Farid Acevedo L\u00f3pez hizo oficial este mi\u00e9rcoles su aspiraci\u00f3n a la rector\u00eda de la Universidad Aut\u00f3noma \u201cBenito Ju\u00e1rez\u201d de Oaxaca (UABJO). Lo hizo a trav\u00e9s de publicaciones en sus redes sociales en\u2026","rel":"","context":"En &quot;Imagen&quot;","block_context":{"text":"Imagen","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/imagen\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/04\/IMG-20260401-WA0078.jpg?fit=647%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/04\/IMG-20260401-WA0078.jpg?fit=647%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/04\/IMG-20260401-WA0078.jpg?fit=647%2C1200&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":40978,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2026\/03\/13\/renuncia-farid-acevedo-a-la-secretaria-de-finanzas-del-gobierno-de-oaxaca-para-buscar-la-rectoria-de-la-uabjo\/","url_meta":{"origin":41990,"position":4},"title":"Renuncia Farid Acevedo a la Secretar\u00eda de Finanzas del Gobierno de Oaxaca para buscar la rector\u00eda de la UABJO","author":"ariadna","date":"marzo 13, 2026","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca #JaimeGUERRERO Farid Acevedo L\u00f3pez dej\u00f3 este viernes la titularidad de la Secretar\u00eda de Finanzas del gobierno de Oaxaca con el prop\u00f3sito de competir por la rector\u00eda de la Universidad Aut\u00f3noma \u201cBenito Ju\u00e1rez\u201d de Oaxaca (UABJO), confirmaron fuentes del ejecutivo estatal. Hasta el momento se desconoce qui\u00e9n asumir\u00e1 el\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/03\/InShot_20260313_101027802.jpg?fit=1200%2C653&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/03\/InShot_20260313_101027802.jpg?fit=1200%2C653&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/03\/InShot_20260313_101027802.jpg?fit=1200%2C653&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/03\/InShot_20260313_101027802.jpg?fit=1200%2C653&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/03\/InShot_20260313_101027802.jpg?fit=1200%2C653&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":41839,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2026\/04\/30\/farid-acevedo-se-registra-como-candidato-a-la-rectoria-de-la-uabjo-con-respaldo-de-mas-de-25-unidades-academicas\/","url_meta":{"origin":41990,"position":5},"title":"Farid Acevedo se registra como candidato a la rector\u00eda de la UABJO con respaldo de m\u00e1s de 25 unidades acad\u00e9micas","author":"ariadna","date":"abril 30, 2026","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca #JaimeGUERRERO En una demostraci\u00f3n de m\u00fasculo pol\u00edtico, universitario y acad\u00e9mico, Farid Acevedo L\u00f3pez present\u00f3 este jueves su registro como candidato a la rector\u00eda de la UABJO, tras encabezar una multitudinaria marcha Calenda desde Ciudad Universitaria hasta la Facultad de Bellas Artes, acompa\u00f1ado por m\u00e1s de 25 comunidades acad\u00e9micas.\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/04\/Screenshot_20260430_110417_WhatsApp-scaled.jpg?fit=1200%2C663&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/04\/Screenshot_20260430_110417_WhatsApp-scaled.jpg?fit=1200%2C663&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/04\/Screenshot_20260430_110417_WhatsApp-scaled.jpg?fit=1200%2C663&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/04\/Screenshot_20260430_110417_WhatsApp-scaled.jpg?fit=1200%2C663&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/04\/Screenshot_20260430_110417_WhatsApp-scaled.jpg?fit=1200%2C663&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/41990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/comments?post=41990"}],"version-history":[{"count":1,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/41990\/revisions"}],"predecessor-version":[{"id":41993,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/41990\/revisions\/41993"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/media\/41991"}],"wp:attachment":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/media?parent=41990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/categories?post=41990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/tags?post=41990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}