{"id":42040,"date":"2026-05-11T20:12:30","date_gmt":"2026-05-12T02:12:30","guid":{"rendered":"https:\/\/redaccionoaxaca.com\/?p=42040"},"modified":"2026-05-11T20:12:30","modified_gmt":"2026-05-12T02:12:30","slug":"sep-frena-cambios-al-calendario-escolar-ciclo-termina-el-15-de-julio","status":"publish","type":"post","link":"https:\/\/redaccionoaxaca.com\/index.php\/2026\/05\/11\/sep-frena-cambios-al-calendario-escolar-ciclo-termina-el-15-de-julio\/","title":{"rendered":"SEP frena cambios al calendario escolar; ciclo termina el 15 de julio"},"content":{"rendered":"<p><strong>#Redacci\u00f3nOaxaca<\/strong><\/p>\n<p><strong>#Oaxaca<\/strong><\/p>\n<p><strong>Ariadna Mendoza<\/strong><\/p>\n<p style=\"text-align: justify;\">El titular de la Secretar\u00eda de Educaci\u00f3n P\u00fablica, Mario Delgado Carrillo, inform\u00f3 que el calendario escolar 2025-2026 se mantendr\u00e1 sin modificaciones y que el ciclo escolar concluir\u00e1 oficialmente el pr\u00f3ximo 15 de julio, tal como estaba previsto en el acuerdo publicado en el Diario Oficial de la Federaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Durante la Primera Reuni\u00f3n Nacional Plenaria Extraordinaria del Consejo Nacional de Autoridades Educativas (CONAEDU) 2026, la SEP y las secretar\u00edas de Educaci\u00f3n de las 32 entidades federativas acordaron por unanimidad conservar los 185 d\u00edas efectivos de clases para escuelas p\u00fablicas y privadas incorporadas al Sistema Educativo Nacional.<\/p>\n<p style=\"text-align: justify;\">Mario Delgado se\u00f1al\u00f3 que la decisi\u00f3n busca dar certeza a millones de familias mexicanas y garantizar el derecho de ni\u00f1as, ni\u00f1os y adolescentes a una educaci\u00f3n integral, adem\u00e1s de evitar cambios de \u00faltima hora en la organizaci\u00f3n escolar y familiar.<\/p>\n<p style=\"text-align: justify;\">El funcionario federal destac\u00f3 que, pese a mantenerse el calendario oficial, las entidades podr\u00e1n realizar ajustes extraordinarios en casos espec\u00edficos, siempre y cuando se cumpla con los planes y programas de estudio, conforme a lo establecido en la Ley General de Educaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Asimismo, la SEP llam\u00f3 a docentes y familias a reforzar el acompa\u00f1amiento acad\u00e9mico durante el cierre del ciclo escolar, al considerar que esta etapa no s\u00f3lo representa una conclusi\u00f3n administrativa, sino tambi\u00e9n un periodo clave para la evaluaci\u00f3n formativa y el fortalecimiento del aprendizaje de los estudiantes.<\/p>\n<p style=\"text-align: justify;\">En el encuentro nacional tambi\u00e9n se acord\u00f3 mantener al CONAEDU como un espacio de di\u00e1logo y consenso entre autoridades educativas del pa\u00eds, privilegiando la coordinaci\u00f3n entre estados y Federaci\u00f3n para atender los retos del sistema educativo nacional.<\/p>\n<div style=\"width: 696px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-42040-1\" width=\"696\" height=\"1237\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/AQPrZs2XjZ6CQ4qPqzKmYSA353bgNrZO5N8h3xUv2NnJmhIkVvbIbN8eeXobxVElglGedcm5cl95JIXADVoh8RzTgRKhKPggYGTZYvm6tA.mp4?_=1\" \/><a href=\"https:\/\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/AQPrZs2XjZ6CQ4qPqzKmYSA353bgNrZO5N8h3xUv2NnJmhIkVvbIbN8eeXobxVElglGedcm5cl95JIXADVoh8RzTgRKhKPggYGTZYvm6tA.mp4\">https:\/\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/AQPrZs2XjZ6CQ4qPqzKmYSA353bgNrZO5N8h3xUv2NnJmhIkVvbIbN8eeXobxVElglGedcm5cl95JIXADVoh8RzTgRKhKPggYGTZYvm6tA.mp4<\/a><\/video><\/div>\n","protected":false},"excerpt":{"rendered":"<p>#Redacci\u00f3nOaxaca #Oaxaca Ariadna Mendoza El titular de la Secretar\u00eda de Educaci\u00f3n P\u00fablica, Mario Delgado Carrillo, inform\u00f3 que el calendario escolar 2025-2026 se mantendr\u00e1 sin modificaciones y que el ciclo escolar concluir\u00e1 oficialmente el pr\u00f3ximo 15 de julio, tal como estaba previsto en el acuerdo publicado en el Diario Oficial de la Federaci\u00f3n. Durante la Primera [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":42042,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4,3,6],"tags":[],"class_list":{"0":"post-42040","1":"post","2":"type-post","3":"status-publish","4":"format-video","5":"has-post-thumbnail","7":"category-agenda-politica","8":"category-mesa-de-redaccion","9":"category-tendencias","10":"post_format-post-format-video"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/FB_IMG_1778551920389-scaled.jpg?fit=2560%2C1707&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9Ynjw-aW4","jetpack-related-posts":[{"id":41943,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2026\/05\/07\/seccion-22-y-unpf-rechazan-modificaciones-al-calendario-escolar-2025-2026-impulsadas-por-el-mundial-de-futbol\/","url_meta":{"origin":42040,"position":0},"title":"Secci\u00f3n 22 y UNPF rechazan modificaciones al calendario escolar 2025-2026 impulsadas por el Mundial de Futbol","author":"ariadna","date":"mayo 7, 2026","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca #JaimeGUERRERO La Secci\u00f3n 22 del SNTE-CNTE y la Uni\u00f3n Nacional de Padres de Familia (UNPF) rechazaron este mi\u00e9rcoles las modificaciones al calendario escolar 2025-2026 anunciadas por la Secretar\u00eda de Educaci\u00f3n P\u00fablica (SEP) y el CONAEDU, que adelantar\u00edan el cierre del ciclo al 5 de junio bajo el argumento\u2026","rel":"","context":"En &quot;Imagen&quot;","block_context":{"text":"Imagen","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/imagen\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/IMG-20260507-WA0204.jpg?fit=544%2C693&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/IMG-20260507-WA0204.jpg?fit=544%2C693&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/IMG-20260507-WA0204.jpg?fit=544%2C693&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":42047,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2026\/05\/12\/reconocen-desde-el-congreso-del-estado-la-importancia-de-cumplir-con-los-tiempos-oficiales-del-ciclo-escolar\/","url_meta":{"origin":42040,"position":1},"title":"Reconocen desde el Congreso del Estado la importancia de cumplir con los tiempos oficiales del ciclo escolar","author":"ariadna","date":"mayo 12, 2026","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca * La conclusi\u00f3n del ciclo escolar 2025\u20132026 se mantiene para el pr\u00f3ximo 15 de julio San Raymundo Jalpan, Oax., a 12 de mayo de 2026.- En Sesi\u00f3n Ordinaria de la Diputaci\u00f3n Permanente, la diputada Mar\u00eda Francisca Antonio Santiago, integrante del Grupo Parlamentario de Morena, reconoci\u00f3 la reciente determinaci\u00f3n\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/Screenshot_20260512_200128_Facebook-scaled.jpg?fit=1200%2C704&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/Screenshot_20260512_200128_Facebook-scaled.jpg?fit=1200%2C704&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/Screenshot_20260512_200128_Facebook-scaled.jpg?fit=1200%2C704&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/Screenshot_20260512_200128_Facebook-scaled.jpg?fit=1200%2C704&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/Screenshot_20260512_200128_Facebook-scaled.jpg?fit=1200%2C704&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":14279,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2020\/09\/07\/la-seccion-22-del-snte-dio-inicio-este-lunes-con-su-ciclo-escolar-2020-2021-a-dos-semana-de-que-la-secretaria-de-educacion-publica-sep-comenzara-con-el-calendario-oficial\/","url_meta":{"origin":42040,"position":2},"title":"La Secci\u00f3n 22 del SNTE dio inicio este lunes con su ciclo escolar 2020-2021 a dos semana de que la Secretar\u00eda de Educaci\u00f3n P\u00fablica (SEP) comenzar\u00e1 con el\u00a0 calendario oficial.\u00a0","author":"ariadna","date":"septiembre 7, 2020","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Sayra Cruz En una transmici\u00f3n en vivo, la dirigencia encabezada por Eloy L\u00f3pez Hern\u00e1ndez inform\u00f3 que todos los trabajadores de la educaci\u00f3n se suman a la formaci\u00f3n educativa por medio del PTEO y en medio de la pandemia, asegur\u00f3 que la educaci\u00f3n no se va a parar. La\u2026","rel":"","context":"En &quot;Al Cierre&quot;","block_context":{"text":"Al Cierre","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/al-cierre\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":41952,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2026\/05\/08\/seccion-22-fija-el-7-de-julio-como-fecha-oficial-para-clausuras-escolares\/","url_meta":{"origin":42040,"position":3},"title":"Secci\u00f3n 22 fija el 7 de julio como fecha oficial para clausuras escolares","author":"ariadna","date":"mayo 8, 2026","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca La Secci\u00f3n XXII del Sindicato Nacional de Trabajadores de la Educaci\u00f3n (SNTE), a trav\u00e9s de la Secretar\u00eda de Asuntos Profesionales y en coordinaci\u00f3n con el Centro de Estudios y Desarrollo Educativo (CEDES 22), inform\u00f3 que las ceremonias de clausura del ciclo escolar deber\u00e1n realizarse el pr\u00f3ximo 7 de\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-07-at-23.39.33.webp?fit=1200%2C600&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-07-at-23.39.33.webp?fit=1200%2C600&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-07-at-23.39.33.webp?fit=1200%2C600&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-07-at-23.39.33.webp?fit=1200%2C600&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-07-at-23.39.33.webp?fit=1200%2C600&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":37756,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2025\/08\/11\/seccion-22-iniciara-clases-el-25-de-agosto-con-calendario-alternativo\/","url_meta":{"origin":42040,"position":4},"title":"Secci\u00f3n 22 iniciar\u00e1 clases el 25 de agosto con calendario alternativo","author":"ariadna","date":"agosto 11, 2025","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Ariadna Mendoza\u00a0 La Secci\u00f3n 22 de la CNTE anunci\u00f3 que el ciclo escolar 2025-2026 iniciar\u00e1 el\u00a025 de agosto, fecha distinta a la marcada por el calendario oficial de la Secretar\u00eda de Educaci\u00f3n P\u00fablica (SEP), al que calificaron de \u201cimpuesto\u201d y \u201cvertical\u201d. El magisterio inform\u00f3 que su\u00a0calendario alternativo\u00a0responde a\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/08\/Screenshot_20250811_124238_Gallery-scaled.jpg?fit=1200%2C672&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/08\/Screenshot_20250811_124238_Gallery-scaled.jpg?fit=1200%2C672&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/08\/Screenshot_20250811_124238_Gallery-scaled.jpg?fit=1200%2C672&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/08\/Screenshot_20250811_124238_Gallery-scaled.jpg?fit=1200%2C672&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2025\/08\/Screenshot_20250811_124238_Gallery-scaled.jpg?fit=1200%2C672&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":8150,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2019\/08\/26\/con-ley-educativa-de-amlo-arranca-ciclo-escolar-en-oaxaca-ieepo-no-podra-otorgar-plazas-en-el-aire-armonizacion-estatal\/","url_meta":{"origin":42040,"position":5},"title":"Con ley educativa de AMLO arranca ciclo escolar en Oaxaca,  IEEPO no podr\u00e1 otorgar plazas, en el aire armonizaci\u00f3n estatal.","author":"ariadna","date":"agosto 26, 2019","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO Con las reformas constitucionales en materia educativa, del proyecto del Presidente de la Rep\u00fablica, Andr\u00e9s Manuel L\u00f3pez Obrador, arranca el nuevo ciclo escolar lectivo 2019-2020 en el pa\u00eds. Sin embargo, en el caso de Oaxaca, a\u00fan no se realiza la armonizaci\u00f3n de la reforma educativa de\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/42040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/comments?post=42040"}],"version-history":[{"count":1,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/42040\/revisions"}],"predecessor-version":[{"id":42043,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/42040\/revisions\/42043"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/media\/42042"}],"wp:attachment":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/media?parent=42040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/categories?post=42040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/tags?post=42040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}