{"id":43068,"date":"2026-07-15T10:04:53","date_gmt":"2026-07-15T16:04:53","guid":{"rendered":"https:\/\/redaccionoaxaca.com\/?p=43068"},"modified":"2026-07-15T10:04:53","modified_gmt":"2026-07-15T16:04:53","slug":"fiscalia-de-oaxaca-defensa-y-policia-estatal-ejecutan-cateo-en-ejutla-de-crespo-detienen-a-tres-aseguran-armas-y-mas-de-1-4-millones-de-pesos","status":"publish","type":"post","link":"https:\/\/redaccionoaxaca.com\/index.php\/2026\/07\/15\/fiscalia-de-oaxaca-defensa-y-policia-estatal-ejecutan-cateo-en-ejutla-de-crespo-detienen-a-tres-aseguran-armas-y-mas-de-1-4-millones-de-pesos\/","title":{"rendered":"Fiscal\u00eda de Oaxaca, DEFENSA y Polic\u00eda Estatal ejecutan cateo en Ejutla de Crespo; detienen a tres, aseguran armas y m\u00e1s de 1.4 millones de pesos"},"content":{"rendered":"<p><strong>#Redacci\u00f3nOaxaca<\/strong><\/p>\n<p><strong>#Oaxaca<\/strong><\/p>\n<p style=\"text-align: justify;\">* <em>Durante la ejecuci\u00f3n del mandato judicial, los efectivos fueron agredidos con disparos de arma de fuego<\/em><\/p>\n<p style=\"text-align: justify;\">Oaxaca de Ju\u00e1rez, Oax., a 15 de julio de 2026.- Como resultado de los trabajos de investigaci\u00f3n para el combate a los delitos contra la salud, la Fiscal\u00eda General del Estado de Oaxaca (FGEO) ejecut\u00f3 una orden de cateo en Ejutla de Crespo, operativo en el que detuvieron a tres personas y aseguraron armas de fuego, veh\u00edculos, dinero en efectivo y otros objetos constitutivos de delito.<\/p>\n<p style=\"text-align: justify;\">El operativo coordinado se realiz\u00f3 el 11 de julio de 2026, en un inmueble ubicado sobre la carretera al libramiento de Agua del Espino, en el municipio de Ejutla de Crespo, derivado de investigaciones relacionadas con delitos contra la salud.<\/p>\n<p style=\"text-align: justify;\">Al ingresar al inmueble, los efectivos fueron agredidos con disparos de arma de fuego desde el interior de la casa, por lo que, en apego a los protocolos de actuaci\u00f3n, repelieron la agresi\u00f3n y lograron controlar la situaci\u00f3n para dar cumplimiento al mandato judicial.<\/p>\n<p style=\"text-align: justify;\">Como resultado del operativo fueron detenidas tres personas identificadas como P.M.R., E.J.R.L. (hombres) y L.R.L. (mujer), quienes quedaron a disposici\u00f3n de la autoridad competente para que se determine su situaci\u00f3n jur\u00eddica legal.<\/p>\n<p style=\"text-align: justify;\">Durante la diligencia tambi\u00e9n aseguraron diversas armas de fuego largas y cortas, una placa bal\u00edstica, una placa met\u00e1lica con insignias institucionales, una chamarra con leyendas de una corporaci\u00f3n policial, as\u00ed como un mill\u00f3n 456 mil 400 pesos en efectivo.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, fueron aseguradas dos camionetas tipo pickup marca Dodge Ram, una camioneta tipo Ford con alteraciones en sus medios de identificaci\u00f3n, un tractocami\u00f3n con alteraciones en sus numerales y una motocicleta con alteraciones en sus medios de identificaci\u00f3n, as\u00ed como el inmueble donde se ejecut\u00f3 el cateo, el cual qued\u00f3 bajo resguardo.<\/p>\n<p style=\"text-align: justify;\">En el operativo participaron elementos de la Agencia Estatal de Investigaciones (AEI), adscritos a las comandancias de Ocotl\u00e1n, Ejutla de Crespo, Zaachila, Zimatl\u00e1n y Sola de Vega, en coordinaci\u00f3n con la Polic\u00eda Estatal, personal de la Secretar\u00eda de la Defensa Nacional (DEFENSA) y un binomio canino.<\/p>\n<p style=\"text-align: justify;\">La Fiscal\u00eda General del Estado de Oaxaca continuar\u00e1 con las investigaciones para determinar la posible relaci\u00f3n de los objetos asegurados con hechos delictivos y fortalecer las acciones de combate a los delitos de alto impacto en la entidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>#Redacci\u00f3nOaxaca #Oaxaca * Durante la ejecuci\u00f3n del mandato judicial, los efectivos fueron agredidos con disparos de arma de fuego Oaxaca de Ju\u00e1rez, Oax., a 15 de julio de 2026.- Como resultado de los trabajos de investigaci\u00f3n para el combate a los delitos contra la salud, la Fiscal\u00eda General del Estado de Oaxaca (FGEO) ejecut\u00f3 una [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":43069,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[7,3,6],"tags":[],"class_list":{"0":"post-43068","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-al-cierre","8":"category-mesa-de-redaccion","9":"category-tendencias"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/07\/IMG-20260715-WA0036.jpg?fit=1600%2C911&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9Ynjw-bcE","jetpack-related-posts":[{"id":25147,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2022\/04\/20\/doble-feminicidio-en-ejutla-de-crespo-oaxaca\/","url_meta":{"origin":43068,"position":0},"title":"Doble feminicidio en Ejutla de Crespo Oaxaca.","author":"ariadna","date":"abril 20, 2022","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca #MairaRic\u00e1rdezLuna C\u00f3mo Inocencia S. M. De 53 a\u00f1os de edad y como Agustina B. B., De 42, fueron identificadas las mujeres ultimadas pasado el medio d\u00eda de este mi\u00e9rcoles 20 de abril en Ejutla de Crespo, Valles Centrales de Oaxaca. La f\u00e9mina de 53 a\u00f1os era muy conocida\u2026","rel":"","context":"En &quot;Imagen&quot;","block_context":{"text":"Imagen","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/imagen\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2022\/04\/IMG-20220420-WA0114-300x173.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":13170,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2020\/06\/30\/fiscalia-general-efectua-diligente-y-exhaustiva-investigacion-por-feminicidio-de-adolescente-y-homicidio-de-bebe-cometido-en-ejutla-de-crespo\/","url_meta":{"origin":43068,"position":1},"title":"Fiscal\u00eda General efect\u00faa diligente y exhaustiva investigaci\u00f3n por feminicidio de adolescente y homicidio de beb\u00e9, cometido en Ejutla de Crespo.","author":"ariadna","date":"junio 30, 2020","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca *La Fiscal\u00eda General inici\u00f3 carpeta de investigaci\u00f3n por el doble crimen ocurrido el pasado 28 de junio, en el cerro conocido como \"El Mexicano\", jurisdicci\u00f3n de San Miguel Ejutla. *Se investigan todos los m\u00f3viles y se aplicar\u00e1 la Ley con firmeza contra quien o quien resulten responsables; no\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":35227,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2025\/01\/21\/localizan-en-ejutla-de-crespo-vehiculos-de-7-desaparecidos-en-oaxaca-6-tienen-antecedentes-penales-fiscal\/","url_meta":{"origin":43068,"position":2},"title":"Localizan en Ejutla de Crespo veh\u00edculos de 7 desaparecidos en Oaxaca;  6 tienen antecedentes penales: Fiscal","author":"ariadna","date":"enero 21, 2025","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO El Fiscal de Oaxaca, Bernardo Rodr\u00edguez Alamilla, revel\u00f3 que tres de los veh\u00edculos en los que viajaban siete personas desaparecidas cuando se dirig\u00edan a la Costa de Oaxaca, fueron localizados el pasado s\u00e1bado en el municipio de Ejutla de Crespo, en la desviaci\u00f3n hacia la autopista\u2026","rel":"","context":"En &quot;Imagen&quot;","block_context":{"text":"Imagen","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/imagen\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":40432,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2026\/02\/10\/detenida-en-ejutla-de-crespo-oaxaca-enfermera-que-arrastro-y-dio-muerte-a-motociclista-en-iztapalapa-hace-un-mes\/","url_meta":{"origin":43068,"position":3},"title":"Detenida en Ejutla de Crespo Oaxaca, enfermera que arrastr\u00f3 y di\u00f3 muerte a motociclista en Iztapalapa hace un mes","author":"ariadna","date":"febrero 10, 2026","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Maira Ric\u00e1rdez Luna * Se escond\u00eda en domicilios de familiares Oaxaque\u00f1os Los trabajos de investigaci\u00f3n de la Fiscal\u00eda General del Estado de Oaxaca dieron resultados, y la madrugada de este martes la enfermera que arrastr\u00f3 con su veh\u00edculo aproximadamente 1.5 kil\u00f3metros en la Alcald\u00eda Iztapalapa, CDMX a un\u2026","rel":"","context":"En &quot;Al Cierre&quot;","block_context":{"text":"Al Cierre","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/al-cierre\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/02\/IMG-20260210-WA0040.jpg?fit=1080%2C842&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/02\/IMG-20260210-WA0040.jpg?fit=1080%2C842&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/02\/IMG-20260210-WA0040.jpg?fit=1080%2C842&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/02\/IMG-20260210-WA0040.jpg?fit=1080%2C842&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2026\/02\/IMG-20260210-WA0040.jpg?fit=1080%2C842&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":603,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2018\/06\/25\/asesinan-a-emigdio-lopez-avedano-candidato-a-diputado-local-por-el-distrito-21-perteneciente-a-ejutla-de-crespo-y-sola-de-vega\/","url_meta":{"origin":43068,"position":4},"title":"Asesinan a Emigdio L\u00f3pez Aveda\u00f1o, candidato a diputado local por Ejutla de Crespo y Sola de Vega","author":"gaby","date":"junio 25, 2018","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Militantes del partido Movimiento Regeneraci\u00f3n Nacional (Morena) fueron emboscados la tarde de este lunes en San Vicente Coatl\u00e1n, Ejutla de Crespo, en el que se confirma la muerte de Emigdio L\u00f3pez Avenda\u00f1o, candidato de la coalici\u00f3n \"Juntos haremos historia\" a diputado local por el distrito 21, que comprende\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":32282,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2024\/06\/20\/fiscalia-de-oaxaca-detiene-a-8-personas-tras-cateo-realizado-en-zaachila-aseguran-drogas-cartuchos-utiles-armas-de-fuego-chalecos-tacticos-y-dinero-en-efectivo\/","url_meta":{"origin":43068,"position":5},"title":"Fiscal\u00eda de Oaxaca detiene a 8 personas tras cateo realizado en Zaachila; aseguran drogas, cartuchos \u00fatiles, armas de fuego, chalecos t\u00e1cticos y dinero en efectivo","author":"ariadna","date":"junio 20, 2024","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca * Se investiga relaci\u00f3n con una red de personas dedicadas al llamado Pr\u00e9stamo Gota a Gota, el cual es considerado un delito de acuerdo con el C\u00f3digo Penal de Oaxaca Oaxaca de Ju\u00e1rez, Oax. 20 de junio de 2024.-Como parte de la estrategia de seguridad y de investigaci\u00f3n\u2026","rel":"","context":"En &quot;Al Cierre&quot;","block_context":{"text":"Al Cierre","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/al-cierre\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2024\/06\/IMG-20240620-WA0020-225x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/43068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/comments?post=43068"}],"version-history":[{"count":1,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/43068\/revisions"}],"predecessor-version":[{"id":43070,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/43068\/revisions\/43070"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/media\/43069"}],"wp:attachment":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/media?parent=43068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/categories?post=43068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/tags?post=43068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}