{"id":8022,"date":"2019-08-15T19:03:06","date_gmt":"2019-08-16T00:03:06","guid":{"rendered":"http:\/\/redaccionoaxaca.com\/?p=8022"},"modified":"2019-08-15T19:03:06","modified_gmt":"2019-08-16T00:03:06","slug":"por-ilegalidades-cae-magistrado-presidente-del-tribunal-de-justicia-administrativa-de-oaxaca-y-otro-desiste-de-auto-reeleccion","status":"publish","type":"post","link":"https:\/\/redaccionoaxaca.com\/index.php\/2019\/08\/15\/por-ilegalidades-cae-magistrado-presidente-del-tribunal-de-justicia-administrativa-de-oaxaca-y-otro-desiste-de-auto-reeleccion\/","title":{"rendered":"Por ilegalidades, cae magistrado Presidente del Tribunal de  Justicia Administrativa de Oaxaca; y otro desiste de auto-reelecci\u00f3n."},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>#Redacci\u00f3nOaxaca<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>#Oaxaca<\/strong><\/p>\n<p><strong>Jaime GUERRERO<\/strong><\/p>\n<p style=\"text-align: justify;\">Tras ventilarse la serie de ilegalidades del magistrado Presidente del Tribunal de Justicia Administrativa, Adri\u00e1n Quiroga Avenda\u00f1o, y por su franca confrontaci\u00f3n con el Gobernador, Alejandro Murat Hinojosa, siete magistrados de la Sala Superior de ese \u00f3rgano jurisdiccional, tomaron la decisi\u00f3n de destituirlo del cargo y designar a la magistrada Mar\u00eda Elena Villa Carillo, como Presidenta Interina.<br \/>\nY en medio del juego de piezas del tablero de ajedrez de ese \u00f3rgano, el magistrado Hugo Villegas Aquino -quien pretend\u00eda seguir en el cargo por una arbitraria decisi\u00f3n de Quiroga Avenda\u00f1o-, desisti\u00f3 de su juicio de amparo, mediante el cual se pretend\u00eda auto-relegir en el cargo, alegando ante el Congreso del Estado, relecci\u00f3n tacita.<br \/>\nVillegas Aquino, fue electo el pasado el 6 de julio del 2011 -a propuesta del ex gobernador Gabino Cu\u00e9 Monteagudo- como Magistrado integrante del entonces Tribunal de lo Contencioso Administrativo del Estado de Oaxaca, para un periodo de 8 a\u00f1os. No obstante, si cargo venci\u00f3 el pasado 6 de julio de \u00e9ste 2019.<br \/>\nLos magistrados Javier Mart\u00edn Villanueva Hern\u00e1ndez, Ana Mar\u00eda Soledad Cruz Vasconcelos, Pedro Carlos Zamora Mart\u00ednez, Juli\u00e1n Hern\u00e1ndez Carrillo, Abraham Santiago Soriano, Mar\u00eda Mayela Garc\u00eda Maldonado, y Manuel Velasco, hicieron un bloque para destituir a Villegas Aquino y as\u00ed cobrarle la afrenta al Gobernador.<br \/>\nY es que en una clara intromisi\u00f3n a los Poderes del Estado y por intereses econ\u00f3micos-personales, Quiroga Avenda\u00f1o, orden\u00f3 -sin fundamento constitucional- a la LXIV Legislatura, no aprobar o ratificar el nombramiento de Ra\u00fal Palomares Palomino, como Magistrado de ese \u00f3rgano jurisdiccional, propuesto por el Gobernador del Estado, Alejandro Murat Hinojosa, confront\u00e1ndose con el mandatario estatal.<br \/>\nEn un claro conflicto de inter\u00e9s personal a favor de Villegas Aquino, el titular del Tribunal de Justicia Administrativa, literalmente ordena al Poder Legislativo, no hacer caso a Murat Hinojosa.<br \/>\nEn el oficio TJAO\/P\/36\/2019, fechado al 11 de julio, Quiroga Avenda\u00f1o, notific\u00f3 al Congreso del Estado -en base a una interpretaci\u00f3n err\u00f3nea de una jurisprudencia de la Suprema Corte de Justicia de la Naci\u00f3n y basada en una legislaci\u00f3n secundaria anterior a la vigencia que rige el Poder Judicial- que operaba a favor de Villegas Aquino la reelecci\u00f3n t\u00e1cita.<br \/>\nNo obstante, Quiroga Avenda\u00f1o, incurri\u00f3 en violaciones sistem\u00e1ticas a la Constituci\u00f3n Pol\u00edtica, por no verificar la vigencia de las designaciones de las y los magistrados de ese \u00f3rgano jurisdiccional, omisi\u00f3n que constituye una violaci\u00f3n a lo ordenado por la Constituci\u00f3n Pol\u00edtica de Oaxaca, en sus art\u00edculos 101, 102 y 111.<br \/>\nA un mes de su posici\u00f3n encontrada, \u00e9ste jueves, Quiroga Avenda\u00f1o, fue destituido del cargo a 9 meses de fenecer su cargo, por incurrir en presuntas ilegalidades.<br \/>\nDe su lado, el gobernador del estado, Alejandro Murat Hinojosa, pidi\u00f3 a la LXIV Legislatura, aprobar la designaci\u00f3n de Ra\u00fal Palomares Palomino -actual Tesorero de la Secretar\u00eda de Finanzas-, como magistrado de la Sala Superior del Tribunal de Justicia Administrativa.<br \/>\nEn tanto, lanz\u00f3 la convocatoria para la renovaci\u00f3n de una magistratura del Tribunal Superior de Justicia.<br \/>\nFue a trav\u00e9s del oficio GEO\/015\/2019, enviado el pasado 24 de junio, que el mandatario estatal notific\u00f3 al Congreso del Estado de la designaci\u00f3n del ex subsecretario de responsabilidades administrativas y anticorrupci\u00f3n de la Secretar\u00eda de la Contralor\u00eda del Gobierno del Estado, Ra\u00fal Palomares, como nuevo magistrado.<br \/>\nPara ello, pidi\u00f3 a la LXIV Legislatura ratificar la designaci\u00f3n de Palomares Palomino con el voto de las dos terceras partes de los miembros presentes de la Legislatura.<br \/>\nEn la v\u00edspera, el magistrado Villegas Aquino en contubernio con el magistrado Quiroga Avenda\u00f1o, denunciaron que la LXIV Legislatura violar\u00eda la jurisprudencia de observancia obligatoria emitida por el Pleno de la Suprema Corte de Justicia de la Naci\u00f3n (SCJN), porque el Congreso no ha emitido el dictamen de evaluaci\u00f3n para la ratificaci\u00f3n de al menos cuatro magistrados, raz\u00f3n por la que procedi\u00f3 la reelecci\u00f3n o ratificaci\u00f3n t\u00e1cita y para ello, interpuso el amparo 576\/2019, del cual se desisti\u00f3 el pasado 12 de agosto.<br \/>\nAdem\u00e1s de Villegas Aquino, otros tres magistrados fenecieron sus cargos, s\u00f3lo que en el Tribunal Superior de Justicia, entre los que se encuentran Jorge Luis Reyes Hern\u00e1ndez, magistrado por 8 a\u00f1os y cuyo termino se le venci\u00f3 el pasado 7 de julio, Ricardo Porfirio Sibaja y Mar\u00eda Luna Ortiz Aguirre, que su periodo es de 15 a\u00f1os y venci\u00f3 el 12 de diciembre de 2018.<br \/>\nAs\u00ed mismo, la magistrada Mar\u00eda Eugenia Villanueva Abraj\u00e1n, presidenta del Tribunal Superior de Justicia del Estado de Oaxaca, inform\u00f3 mediante oficio de fecha 24 de junio de 2019, al Poder Ejecutivo del Estado de Oaxaca, que se encuentra una plaza para licenciadas o licenciados en derecho que aspiren a ocupar la vacante, debido al fallecimiento del magistrado del Tribunal Superior de Justicia, Sergio Sa\u00fal Estrada Romero.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-8024\" src=\"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2019\/08\/IMG-20190815-WA0096-217x300.jpg?resize=217%2C300\" alt=\"\" width=\"217\" height=\"300\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO Tras ventilarse la serie de ilegalidades del magistrado Presidente del Tribunal de Justicia Administrativa, Adri\u00e1n Quiroga Avenda\u00f1o, y por su franca confrontaci\u00f3n con el Gobernador, Alejandro Murat Hinojosa, siete magistrados de la Sala Superior de ese \u00f3rgano jurisdiccional, tomaron la decisi\u00f3n de destituirlo del cargo y designar a la magistrada Mar\u00eda [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":{"0":"post-8022","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-uncategorized"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9Ynjw-25o","jetpack-related-posts":[{"id":8027,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2019\/08\/15\/escala-disputa-por-el-tribunal-de-justicia-administrativa-magistrado-destituido-se-aferra-al-cargo-sigo-siendo-presidente-dice\/","url_meta":{"origin":8022,"position":0},"title":"Escala disputa por el Tribunal de Justicia Administrativa; Magistrado destituido se aferra al cargo, \u201csigo siendo Presidente\u201d, dice.","author":"ariadna","date":"agosto 15, 2019","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO Tras ser destituido como magistrado Presidente del Tribunal de Justicia Administrativa, Adri\u00e1n Quiroga Avenda\u00f1o -por su franca confrontaci\u00f3n con el Gobernador, Alejandro Murat Hinojosa e incurrir presuntos actos ilegales- el ahora ex titular de ese \u00f3rgano jurisdiccional, calific\u00f3 esa acci\u00f3n como un acto porril e ilegal\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8038,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2019\/08\/18\/aprueban-en-comision-magistrado-del-tribunal-de-justicia-administrativa-propuesto-por-murat-la-moneda-en-el-aire-por-amparo\/","url_meta":{"origin":8022,"position":1},"title":"Aprueban en Comisi\u00f3n, magistrado del Tribunal de Justicia  Administrativa propuesto por Murat; la moneda en el aire por amparo.","author":"ariadna","date":"agosto 18, 2019","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO En medio de la disputa de magistrados del Tribunal de Justicia Administrativa de Oaxaca (TJAO), la Comisi\u00f3n de Administraci\u00f3n y Procuraci\u00f3n de Justicia de la LXIV Legislatura, aprob\u00f3 la ratificaci\u00f3n de Ra\u00fal Palomares Palomino, como Magistrado de la Sala Superior de ese \u00f3rgano jurisdiccional, propuesto por\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2019\/08\/IMG-20190817-WA0002-233x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":8103,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2019\/08\/22\/piden-a-murat-investigacion-vs-consejero-juridico-y-titular-de-ssp-por-violentar-tja-advierten-nuevo-tribunal-y-magistrados-por-disputa\/","url_meta":{"origin":8022,"position":2},"title":"Piden a Murat investigaci\u00f3n vs Consejero Jur\u00eddico y titular de SSP por violentar TJA; advierten nuevo Tribunal y magistrados por disputa.","author":"ariadna","date":"agosto 22, 2019","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO La LXIV Legislatura, pidi\u00f3 al Gobernador del Estado, Alejandro Murat Hinojosa, iniciar una investigaci\u00f3n contra el Consejero Jur\u00eddico, Octavio Tinajero Zenil; el Secretario de Seguridad, Ernesto Salcedo Rosales; y del Comisionado de la Polic\u00eda, Ra\u00fal Antonio Castillejos Sol\u00eds, por organizar, planear y ejecutar un operativo que\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":11234,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2020\/03\/18\/de-la-fge-morena-presunta-combatiente-a-la-corrupcion-y-ex-funcionario-de-la-semovi-entre-los-designados-como-magistrados-del-tja\/","url_meta":{"origin":8022,"position":3},"title":"De la FGE, Morena, presunta combatiente a la corrupci\u00f3n, y ex funcionario de la Semovi, entre los designados como Magistrados del TJA.","author":"ariadna","date":"marzo 18, 2020","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO Entre militantes de Morena, presuntos hermanos de diputadas del PRI, ex funcionarias de la Fiscal\u00eda, acad\u00e9micas y la presidenta del Comit\u00e9 de Consulta y Participaci\u00f3n Ciudadana del Estado de Oaxaca, el Gobernador, Alejandro Murat Hinojosa, design\u00f3 a los nuevos magistrados y magistradas del Tribunal de Justicia\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":6844,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2019\/05\/17\/omision-del-congreso-por-falta-de-ley-organica-magistrada-del-tribunal-de-justicia-administrativa-sin-nombramiento-usurpa-funciones\/","url_meta":{"origin":8022,"position":4},"title":"Omisi\u00f3n del Congreso; por falta de ley org\u00e1nica, \u201cmagistrada\u201d del\u00a0Tribunal de Justicia Administrativa, sin nombramiento, usurpa funciones","author":"denise","date":"mayo 17, 2019","format":false,"excerpt":"#Redacci\u00f3nOaxaca #JaimeGuerrero Por omisi\u00f3n del Congreso del Estado y las disputas internas en el Tribunal de Justicia Administrativa del Estado (TJAE), no hay una ley org\u00e1nica de ese \u00f3rgano jurisdiccional, lo cual ha derivado en la ilegalidad y la falta de nombramiento de Ana Mar\u00eda Soledad Cruz Vasconcelos, como Magistrada\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":20848,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2021\/09\/13\/condena-congreso-de-oaxaca-asesinato-de-magistrado\/","url_meta":{"origin":8022,"position":5},"title":"Condena Congreso de Oaxaca asesinato de Magistrado.","author":"ariadna","date":"septiembre 13, 2021","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca San Raymundo Jalpan, 13 de septiembre de 2021.- La LXIV Legislatura del Congreso Local conden\u00f3 la inseguridad que se vive en la entidad oaxaque\u00f1a, misma que ha llegado a transgredir la estabilidad en las instituciones p\u00fablicas. Mediante un posicionamiento, Fredie Delf\u00edn Avenda\u00f1o, Presidente de la Junta de Coordinaci\u00f3n\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/8022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/comments?post=8022"}],"version-history":[{"count":1,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/8022\/revisions"}],"predecessor-version":[{"id":8026,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/8022\/revisions\/8026"}],"wp:attachment":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/media?parent=8022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/categories?post=8022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/tags?post=8022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}