{"id":8038,"date":"2019-08-18T10:11:41","date_gmt":"2019-08-18T15:11:41","guid":{"rendered":"http:\/\/redaccionoaxaca.com\/?p=8038"},"modified":"2019-08-18T10:11:41","modified_gmt":"2019-08-18T15:11:41","slug":"aprueban-en-comision-magistrado-del-tribunal-de-justicia-administrativa-propuesto-por-murat-la-moneda-en-el-aire-por-amparo","status":"publish","type":"post","link":"https:\/\/redaccionoaxaca.com\/index.php\/2019\/08\/18\/aprueban-en-comision-magistrado-del-tribunal-de-justicia-administrativa-propuesto-por-murat-la-moneda-en-el-aire-por-amparo\/","title":{"rendered":"Aprueban en Comisi\u00f3n, magistrado del Tribunal de Justicia  Administrativa propuesto por Murat; la moneda en el aire por amparo."},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>#Redacci\u00f3nOaxaca<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>#Oaxaca<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Jaime GUERRERO<\/strong><\/p>\n<p style=\"text-align: justify;\">En medio de la disputa de magistrados del Tribunal de Justicia Administrativa de Oaxaca (TJAO), la Comisi\u00f3n de Administraci\u00f3n y Procuraci\u00f3n de Justicia de la LXIV Legislatura, aprob\u00f3 la ratificaci\u00f3n de Ra\u00fal Palomares Palomino, como Magistrado de la Sala Superior de ese \u00f3rgano jurisdiccional, propuesto por el Gobernador del Estado, Alejandro Murat Hinojosa.<\/p>\n<p style=\"text-align: justify;\">Tras desahogar el proceso, la revisi\u00f3n de documentaci\u00f3n y requisitos establecidos en el art\u00edculo 114 Qu\u00e1rter de la Constituci\u00f3n, y desahogada la comparecencia del ex Tesorero de la Secretar\u00eda de Finanzas, la Comisi\u00f3n de Administraci\u00f3n consider\u00f3 que la designaci\u00f3n hecha por el mandatario estatal, cumple con los requisitos establecidos para ser electo para un periodo de 7 a\u00f1os.<\/p>\n<p style=\"text-align: justify;\">Sin embargo, la moneda est\u00e1 en el aire por un segundo amparo promovido por el magistrado, Hugo Villegas Aquino, quien se resiste a dejar el cargo.<\/p>\n<p style=\"text-align: justify;\">Fue el juez d\u00e9cimo primero de distrito -el cual ha protegido de actos desplegados por el Congreso del Estado y Murat Hinojosa contra magistrados sembrados por el ex gobernador, Gabino Cu\u00e9, del grupo del ex presidente del Tribunal Superior de Justicia, Alfredo Lagunas, entre ellos, Villegas Aquino y Enrique Pacheco Mart\u00ednez, Adri\u00e1n Quiriga, y la Sala Indigena- quien otorg\u00f3 la suspensi\u00f3n provisional mientras se resuelve el fondo del asunto.<\/p>\n<p style=\"text-align: justify;\">El dictamen en el que se aprueba la designaci\u00f3n de Palomares Palomino, est\u00e1 firmado por los diputados Eliza Zepeda Lagunas, Magaly L\u00f3pez Dom\u00ednguez, Karina Espino Camorna, de la bancada de Morena; y el diputado del PRI, Jorge Villaca\u00f1a Jim\u00e9nez. El diputado del PT, No\u00e9 Doroteo Castillejos, se abstuvo de firmar el documento, al no tener permiso de su jefe pol\u00edtico, el diputado federal, Benjam\u00edn Robles Montoya.<\/p>\n<p style=\"text-align: justify;\">No obstante, aun cuando el proceso de elecci\u00f3n del nuevo magistrado del TJA, contin\u00faa su curso en el Congreso del Estado y en la pr\u00f3xima sesi\u00f3n ordinaria de la LXIV Legislatura, ser\u00e1 presentado al pleno en primera lectura, se podr\u00eda entrampar porque el magistrado Villegas Aquino, se ampar\u00f3 el juez decimo primero de distrito le concedi\u00f3 la suspensi\u00f3n provisional a los actos que desplegado el Gobernador, Alejandro Murat Hinojosa; el Congreso del Estado y la Consejer\u00eda Jur\u00eddica.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s en una clara intromisi\u00f3n a los Poderes del Estado y por intereses econ\u00f3micos-personales, el presidente del TJA destituido por un grupo de 8 magistrados, Adri\u00e1n Quiroga Avenda\u00f1o, orden\u00f3 -sin fundamento constitucional- a la LXIV Legislatura, no aprobar o ratificar el nombramiento de Ra\u00fal Palomares Palomino, como Magistrado de ese \u00f3rgano jurisdiccional, propuesto por el Gobernador del Estado, Alejandro Murat Hinojosa, confront\u00e1ndose con el mandatario estatal.<br \/>\nEn un claro conflicto de inter\u00e9s personal a favor de Villegas Aquino, el titular del Tribunal de Justicia Administrativa, literalmente ordena al Poder Legislativo, no hacer caso a Murat Hinojosa.<\/p>\n<p style=\"text-align: justify;\">En el oficio TJAO\/P\/36\/2019, fechado al 11 de julio, Quiroga Avenda\u00f1o, notific\u00f3 al Congreso del Estado -en base a una interpretaci\u00f3n de una jurisprudencia de la Suprema Corte de Justicia de la Naci\u00f3n y basada en una legislaci\u00f3n secundaria anterior a la vigencia que rige el Poder Judicial- que operaba a favor de Villegas Aquino la reelecci\u00f3n t\u00e1cita.<\/p>\n<p style=\"text-align: justify;\">No obstante, el pasado jueves, Quiroga Avenda\u00f1o, fue destituido del cargo a 9 meses de fenecer su cargo, por incurrir en presuntas ilegalidades.<\/p>\n<p style=\"text-align: justify;\">De su lado, el gobernador del estado, Alejandro Murat Hinojosa, pidi\u00f3 a la LXIV Legislatura, aprobar la designaci\u00f3n de Ra\u00fal Palomares Palomino -actual Tesorero de la Secretar\u00eda de Finanzas-, como magistrado de la Sala Superior del Tribunal de Justicia Administrativa.<\/p>\n<p style=\"text-align: justify;\">En la v\u00edspera, Villegas Aquino en contubernio con el magistrado Quiroga Avenda\u00f1o, denunciaron que la LXIV Legislatura violar\u00eda la jurisprudencia de observancia obligatoria emitida por el Pleno de la Suprema Corte de Justicia de la Naci\u00f3n (SCJN), porque el Congreso no ha emitido el dictamen de evaluaci\u00f3n para la ratificaci\u00f3n de al menos cuatro magistrados, raz\u00f3n por la que proced\u00eda la reelecci\u00f3n o ratificaci\u00f3n t\u00e1cita y para ello, interpuso el amparo 576\/2019, el cual le fue negado, y tras desistirse del primero, posteriormente presenta un segundo en el expediente 705\/2019, en el cual el juez decimo primero de distrito le concede la suspensi\u00f3n provisional.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-8039\" src=\"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2019\/08\/IMG-20190817-WA0002-233x300.jpg?resize=233%2C300\" alt=\"\" width=\"233\" height=\"300\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO En medio de la disputa de magistrados del Tribunal de Justicia Administrativa de Oaxaca (TJAO), la Comisi\u00f3n de Administraci\u00f3n y Procuraci\u00f3n de Justicia de la LXIV Legislatura, aprob\u00f3 la ratificaci\u00f3n de Ra\u00fal Palomares Palomino, como Magistrado de la Sala Superior de ese \u00f3rgano jurisdiccional, propuesto por el Gobernador del Estado, Alejandro [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":{"0":"post-8038","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-uncategorized"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9Ynjw-25E","jetpack-related-posts":[{"id":21115,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2021\/09\/25\/avala-parlamento-oaxaqueno-rechazos-y-ratificacion-de-funcionarios-del-tribunal-de-justicia\/","url_meta":{"origin":8038,"position":0},"title":"Avala Parlamento oaxaque\u00f1o rechazos y ratificaci\u00f3n de funcionarios del Tribunal de Justicia.","author":"ariadna","date":"septiembre 25, 2021","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Comunicado San Raymundo Jalpan, Oax. 25 de septiembre de 2021.- La C\u00e1mara de Diputadas y Diputados de Oaxaca aprob\u00f3 el rechazo y la ratificaci\u00f3n de titulares de magistraturas del Tribunal Superior de Justicia del Poder Judicial del Estado. En un primer dictamen aprob\u00f3 ratificar al ciudadano Luis Enrique\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":17560,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2021\/03\/17\/congreso-aprueba-magistraturas-del-tsj-y-tja-propuestas-por-murat\/","url_meta":{"origin":8038,"position":1},"title":"Congreso, aprueba magistraturas  del TSJ y TJA, propuestas por Murat.","author":"ariadna","date":"marzo 17, 2021","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO Con 28 votos en favor, el pleno de la LXIV Legislatura, aprob\u00f3 la ratificaci\u00f3n de 6 magistrados y magistradas del Tribunal Superior de Justicia del Estado y del Tribunal de Justicia Administrativa, propuestos por el Gobernador del Estado, Alejandro Murat Hinojosa, entre los que destacan actuales\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":21590,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2021\/10\/13\/video-ex-tecnica-del-congreso-de-oaxaca-es-designada-magistrada-por-gobernador-pero-no-declina-en-ine-por-presidencia-del-ieepco\/","url_meta":{"origin":8038,"position":2},"title":"VIDEO: Ex t\u00e9cnica del Congreso de Oaxaca, es designada Magistrada por   Gobernador, pero NO declina en INE por Presidencia del IEEPCO.","author":"ariadna","date":"octubre 13, 2021","format":"video","excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO La ex secretaria t\u00e9cnica de la Comisi\u00f3n de Administraci\u00f3n de Justicia de la LXIV Legislatura, Camelia Gaspar Mart\u00ednez, quien fue designada por el Gobernador, Alejandro Murat Hinojosa, como magistrada del Tribunal de Justicia Administrativa de Oaxaca (#TJAO), no ha declinado su participaci\u00f3n ante el Instituto Nacional\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8216,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2019\/08\/29\/pri-y-aliados-se-imponen-para-ratificar-a-palomares-palomino-como-magistrado-del-tja-morena-dividido-no-pudo-con-votacion\/","url_meta":{"origin":8038,"position":3},"title":"PRI y aliados se imponen para ratificar a Palomares Palomino  como Magistrado del TJA; Morena dividido no pudo con votaci\u00f3n.","author":"ariadna","date":"agosto 29, 2019","format":"video","excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO Con 26 votos a favor y 10 en contra, la LXIV Legislatura, aprob\u00f3 la ratificaci\u00f3n de Ra\u00fal Palomares Palomino, como Magistrado de la Sala Superior del Tribunal de Justicia Administrativa, propuesto por el Gobernador, Alejandro Murat Hinojosa. El pasado 24 de junio, Murat Hinojosa, pidi\u00f3 a\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":10506,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2020\/02\/06\/murat-designara-a-su-ex-consejero-juridico-como-nuevo-magistrado-del-tsje-congreso-no-culmino-seleccion\/","url_meta":{"origin":8038,"position":4},"title":"Murat designar\u00e1 a su ex consejero Jur\u00eddico como nuevo  Magistrado del TSJE; Congreso no culmin\u00f3 selecci\u00f3n.","author":"ariadna","date":"febrero 6, 2020","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO \u00a0\u00c1ngel Alejo Torres, ex Consejero Jur\u00eddico del Gobernador, Alejandro Murat Hinojosa, ser\u00eda el virtual Magistrado del Tribunal Superior de Justicia del Estado, luego de que la LXIV Legislatura, no proces\u00f3 en tiempo y forma la designaci\u00f3n del nuevo integrante del Poder Judicial, y una vez vencido\u2026","rel":"","context":"Entrada similar ","block_context":{"text":"Entrada similar ","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/redaccionoaxaca.com\/wp-content\/uploads\/2020\/02\/zo-225x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12002,"url":"https:\/\/redaccionoaxaca.com\/index.php\/2020\/04\/27\/con-reforma-constitucional-buscan-quitarle-facultad-a-gobernador-de-oaxaca-en-designacion-de-magistrados-del-poder-judicial\/","url_meta":{"origin":8038,"position":5},"title":"Con reforma constitucional, buscan quitarle facultad a Gobernador de Oaxaca en designaci\u00f3n de magistrados del Poder Judicial.","author":"ariadna","date":"abril 27, 2020","format":false,"excerpt":"#Redacci\u00f3nOaxaca #Oaxaca Jaime GUERRERO La bancada del Partido Regeneraci\u00f3n Nacional (Morena), present\u00f3 una iniciativa de reforma a la Constituci\u00f3n local para quitarle la facultad al gobernador del estado, en turno, en la designaci\u00f3n de los las y los magistrados del Tribunal Superior de Justicia, del Tribunal de Justicia Administrativa y\u2026","rel":"","context":"En &quot;Agenda Pol\u00edtica&quot;","block_context":{"text":"Agenda Pol\u00edtica","link":"https:\/\/redaccionoaxaca.com\/index.php\/category\/agenda-politica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/8038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/comments?post=8038"}],"version-history":[{"count":1,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/8038\/revisions"}],"predecessor-version":[{"id":8040,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/posts\/8038\/revisions\/8040"}],"wp:attachment":[{"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/media?parent=8038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/categories?post=8038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redaccionoaxaca.com\/index.php\/wp-json\/wp\/v2\/tags?post=8038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}